{"id":737150,"date":"2023-07-27T14:00:11","date_gmt":"2023-07-27T12:00:11","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=737150"},"modified":"2023-07-27T14:00:12","modified_gmt":"2023-07-27T12:00:12","slug":"joe-burrow-pas-decourager-negociations-contractuelles","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/","title":{"rendered":"Joe Burrow ne se laisse pas d\u00e9courager par les n\u00e9gociations contractuelles"},"content":{"rendered":"<h2>Alors que le monde du football r&eacute;agit &agrave; une s&eacute;rie de contrats de quarterback de haut niveau et record, la star des Bengals de Cincinnati, Joe Burrow, reste imperturbable, gardant les yeux sur la saison &agrave; venir et la synergie de son &eacute;quipe.<\/h2><p>Alors que Justin Herbert des Chargers de Los Angeles a r&eacute;cemment accept&eacute; un <a href=\"https:\/\/theplayoffs.news\/fr\/nfl\/justin-herbert-chez-les-chargers-5-ans-plus\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>contrat stup&eacute;fiant de 262,5 millions de dollars sur cinq ans<\/a>, Burrow semble r&eacute;solu dans son processus de n&eacute;gociation avec les Bengals. <a href=\"https:\/\/www.youtube.com\/watch?v=SET3qnUn_70&amp;pp=ygUKam9lIGJ1cnJvdw%3D%3D\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Sa philosophie reste simple<\/a> :<\/p><blockquote><p>&laquo;&nbsp;&Ccedil;a se fera quand &ccedil;a se fera.&nbsp;&raquo;<\/p><\/blockquote><p>Ce comportement imperturbable refl&egrave;te la ferme conviction de Burrow de parvenir &agrave; un accord mutuellement b&eacute;n&eacute;fique pour lui et son &eacute;quipe.<\/p><p>Au milieu de ces n&eacute;gociations, la direction des Bengals et Joe Burrow ont convenu de garder le silence, marquant un contraste frappant avec les discussions contractuelles g&eacute;n&eacute;ralement publiques et scrut&eacute;es dans la NFL.<\/p><p>Le quarterback de quatri&egrave;me ann&eacute;e croit que c&rsquo;est la &laquo;&nbsp;meilleure fa&ccedil;on de faire des affaires&nbsp;&raquo;, soulignant qu&rsquo;il met l&rsquo;accent sur la performance plut&ocirc;t que sur les n&eacute;gociations.<\/p><h3>Donner la priorit&eacute; &agrave; l&rsquo;alchimie d&rsquo;&eacute;quipe<\/h3><p>L&rsquo;engagement ind&eacute;fectible de Joe Burrow envers son &eacute;quipe s&rsquo;&eacute;tend &agrave; son soutien aux receveurs <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/tee-higgins-nfl-8479986\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'><strong>Tee Higgins<\/strong><\/a> et <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/jamarr-chase-nfl-8725256\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'><strong>Ja&rsquo;Marr Chase<\/strong><\/a>, qui doivent &eacute;galement n&eacute;gocier un contrat. Burrow a soulign&eacute; l&rsquo;importance de garder l&rsquo;&eacute;quipe de base ensemble pendant longtemps, soulignant la valeur de la chimie sur le terrain.<\/p><p>Le premier jour de l&rsquo;ancien quarterback de LSU au camp d&rsquo;entra&icirc;nement l&rsquo;a vu en pleine forme. Avec un ajustement pr&eacute;-snap impressionnant sur la ligne de m&ecirc;l&eacute;e, de bonnes d&eacute;cisions et des lancers pr&eacute;cis, Burrow a prouv&eacute; que les pourparlers contractuels n&rsquo;affectaient pas ses performances.<\/p><h3>Inflexible face aux d&eacute;fis<\/h3><p>Alors que les Bengals luttent pour leur troisi&egrave;me titre cons&eacute;cutif de l&rsquo;AFC Nord et une autre course vers le Super Bowl, la d&eacute;termination de Joe Burrow reste in&eacute;branlable. Apr&egrave;s une s&eacute;rie de revers personnels au cours des deux derni&egrave;res ann&eacute;es &ndash; y compris des blessures et la pand&eacute;mie de COVID &ndash; Burrow est d&eacute;termin&eacute; &agrave; tirer le meilleur parti de chaque journ&eacute;e de pr&eacute;paration pour l&rsquo;ann&eacute;e &agrave; venir.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":737173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[118,40],"tags":[802,747],"sport":[],"saison":[],"class_list":["post-737150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nfl","category-nfl","tag-cincinnati-bengals","tag-joe-burrow"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Joe Burrow ne se laisse pas d&eacute;courager par les n&eacute;gociations contractuelles - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joe Burrow ne se laisse pas d&eacute;courager par les n&eacute;gociations contractuelles - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T14:00:12+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Taudin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Taudin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/\",\"name\":\"Joe Burrow ne se laisse pas d\u00e9courager par les n\u00e9gociations contractuelles - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg\",\"datePublished\":\"2023-07-27T12:00:11+00:00\",\"dateModified\":\"2023-07-27T12:00:12+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg\",\"width\":1920,\"height\":1068,\"caption\":\"Joe Burrow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joe Burrow ne se laisse pas d\u00e9courager par les n\u00e9gociations contractuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\",\"name\":\"Charles Taudin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"caption\":\"Charles Taudin\"},\"description\":\"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.\",\"sameAs\":[\"https:\/\/www.instagram.com\/ctaudin_\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joe Burrow ne se laisse pas d&eacute;courager par les n&eacute;gociations contractuelles - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Joe Burrow ne se laisse pas d&eacute;courager par les n&eacute;gociations contractuelles - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-07-27T12:00:12+00:00","og_image":[{"width":1920,"height":1068,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg","type":"image\/jpeg"}],"author":"Charles Taudin","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Charles Taudin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/","name":"Joe Burrow ne se laisse pas d\u00e9courager par les n\u00e9gociations contractuelles - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg","datePublished":"2023-07-27T12:00:11+00:00","dateModified":"2023-07-27T12:00:12+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/07\/Capture-decran-2023-07-27-a-13.50.18.jpg","width":1920,"height":1068,"caption":"Joe Burrow"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/joe-burrow-pas-decourager-negociations-contractuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Joe Burrow ne se laisse pas d\u00e9courager par les n\u00e9gociations contractuelles"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133","name":"Charles Taudin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","caption":"Charles Taudin"},"description":"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.","sameAs":["https:\/\/www.instagram.com\/ctaudin_\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/737150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=737150"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/737150\/revisions"}],"predecessor-version":[{"id":737182,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/737150\/revisions\/737182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/737173"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=737150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=737150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=737150"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=737150"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=737150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}