{"id":610759,"date":"2023-06-04T20:03:17","date_gmt":"2023-06-04T18:03:17","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=610759"},"modified":"2023-06-04T20:03:19","modified_gmt":"2023-06-04T18:03:19","slug":"elf-2023-week-1-le-barometre-mousquetaires","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/","title":{"rendered":"ELF 2023 &#8211; Week 1: Le barom\u00e8tre des Mousquetaires"},"content":{"rendered":"<h2>Apr&egrave;s chaque match des Mousquetaires de Paris en ELF, la r&eacute;daction de TFA vous proposera les points forts et les points faibles de la prestation parisienne.<\/h2><p>Une victoire pour les Mousquetaires lors de l&rsquo;ouverture de la saison d&rsquo;ELF, c&rsquo;&eacute;tait l&rsquo;objectif affich&eacute; par les dirigeants parisiens avant la rencontre inaugurale de la saison face aux Centurions de Cologne. Un objectif r&eacute;alis&eacute; gr&acirc;ce &agrave; un succ&egrave;s arrach&eacute; dans les toutes derni&egrave;res secondes de la rencontre (<a href=\"https:\/\/theplayoffs.news\/fr\/elf\/mousquetaires-de-paris-premier-succes\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>24-17<\/a>). Retour sur les r&eacute;ussites et les points d&rsquo;am&eacute;liorations pour les Mousquetaires de Paris au lendemain de cette premi&egrave;re rencontre europ&eacute;enne.<\/p><h3>Les tops de la prestation des Mousquetaires<\/h3><h4>Une d&eacute;fense souvent solide<\/h4><p>S&rsquo;il est un chiffre qui prouve la bonne performance d&eacute;fensive des parisiens sur cette premi&egrave;re rencontre d&rsquo;ELF, c&rsquo;est bien le 0 point&eacute; au tableau d&rsquo;affichage pour les Centurions au terme de la premi&egrave;re mi-temps. Dans ce premier acte les allemands ont compl&egrave;tement &eacute;t&eacute; &eacute;touff&eacute; par la pression mise par la ligne d&eacute;fensive des Mousquetaires. Une pression qui venait de tous les c&ocirc;t&eacute;s et que la ligne offensive de Cologne a eu toutes les peines du monde &agrave; contenir comme en atteste les sacks nombreux de Stanley Zeregbe ou encore de Digaan Gomis Katchanga.<\/p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"fr\" dir=\"ltr\">Encore un sack pour Stanley Zeregbe <a href=\"https:\/\/twitter.com\/hashtag\/PARatCCE?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#PARatCCE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ELF?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#ELF<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/footus?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#footus<\/a> <a href=\"https:\/\/t.co\/xdx9TjVeCi\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/xdx9TjVeCi<\/a><\/p>\n<p>&mdash; Spring Football News (@SpringFBnews) <a href=\"https:\/\/twitter.com\/SpringFBnews\/status\/1665049660073934849?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Une performance d&eacute;fensive qui a eu l&rsquo;avantage de permettre aux parisiens de ne pas conc&eacute;der trop de points lors de leurs temps faibles offensifs. Mais une performance qui a aussi et surtout permis aux Mousquetaires d&rsquo;inscrire des points. En effet, sur les 24 points inscrits par la franchise fran&ccedil;aise dans cette premi&egrave;re rencontre de la saison, un tiers sont venus directement de la d&eacute;fense. Tout d&rsquo;abord gr&acirc;ce &agrave; un safety qui a amen&eacute; les deux premiers points de l&rsquo;histoire de Paris en ELF puis gr&acirc;ce &agrave; un gros plaquage qui conduira &agrave; un fumble remont&eacute; jusqu&rsquo;&agrave; la end-zone allemande.<\/p><h4>Un Zach Edwards qui trouve rapidement ses marques<\/h4><p>Il n&rsquo;est jamais facile pour un joueur de changer d&rsquo;&eacute;quipe &agrave; l&rsquo;intersaison et de se confronter &agrave; l&rsquo;apprentissage de nouveaux syst&egrave;mes de jeu. Une difficult&eacute; peut &ecirc;tre encore plus criante lorsqu&rsquo;il s&rsquo;agit d&rsquo;un quarterback. Pourtant Zach Edwards a sembl&eacute; plut&ocirc;t &agrave; l&rsquo;aise dans cette nouvelle &eacute;quipe des Mousquetaires. M&ecirc;me s&rsquo;il fut parfois abandonn&eacute; par sa ligne offensive ce qui lui a permis de gouter plusieurs fois au gazon allemand, Edwards s&rsquo;est montr&eacute; plut&ocirc;t pr&eacute;cis dans ses passes comme sur le dernier drive d&eacute;cisif avec un touchdown qu&rsquo;il a lui m&ecirc;me converti &agrave; la course.<\/p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"fr\" dir=\"ltr\">&#128064; Zach Edwards r&eacute;ussie la conversion &agrave; 2-pt <a href=\"https:\/\/twitter.com\/hashtag\/PARatCCE?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#PARatCCE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ELF?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#ELF<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/footus?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#footus<\/a> <a href=\"https:\/\/t.co\/GnqZqzxSlR\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/GnqZqzxSlR<\/a><\/p>\n<p>&mdash; Spring Football News (@SpringFBnews) <a href=\"https:\/\/twitter.com\/SpringFBnews\/status\/1665058164117479429?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Bilan: 2 touchdowns lanc&eacute;s et aucune interception contre le quarterback des Mousquetaires. Une belle premi&egrave;re impression qui est encore major&eacute;e par les connexions nombreuses qu&rsquo;il a pu montrer avec ses diff&eacute;rentes cibles. Ainsi, Kyle Sweet, qu&rsquo;Edwards conna&icirc;t parfaitement, a re&ccedil;u la courte passe du touchdown d&eacute;cisif. Mais avant cela Adria Botella Moreno ou encore Florian Larose avait pu montrer que leur entente avec le quarterback &eacute;tait d&eacute;j&agrave; bien &eacute;tablie. De bonne augure pour la suite offensive de la saison.<\/p><h3>Les flops de la prestation des Mousquetaires<\/h3><h4>Mauvaise soir&eacute;e pour Benjamin Bono<\/h4><p>Le poste de kicker est sans aucun doute l&rsquo;une des positions les plus ingrates dans le football am&eacute;ricain. Lorsque les conversions de touchdowns ou les field goals s&rsquo;encha&icirc;nent avec succ&egrave;s, peu sont les m&eacute;dias et les observateurs qui viendront encenser votre performance. A l&rsquo;inverse, quand vous vivez une mauvaise soir&eacute;e et que votre pied flanche, tout le monde s&rsquo;en rend compte imm&eacute;diatement. C&rsquo;est ce qui est malheureusement arriver lors du premier match de la saison &agrave; <a href=\"https:\/\/europeanleague.football\/players\/benjamin-bono_da49f450-e544-11ed-8d49-2dfc39e128a1\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Benjamin Bono<\/a> qui a simplement manqu&eacute; tous ses coups de pied de la soir&eacute;e.<\/p><p>Loin de nous l&rsquo;id&eacute;e d&rsquo;accabler le kicker des Mousquetaires d&rsquo;autant que sa performance manqu&eacute;e ne pr&ecirc;te pas &agrave; cons&eacute;quence puisque les parisiens ont tout de m&ecirc;me r&eacute;ussi &agrave; s&rsquo;imposer. Mais il est certain que les parisiens ne pourront pas se permettre de laisser filer 7 points (2 field goals et un PAT) tous les week-end. Il est donc plus qu&rsquo;urgent pour Benjamin Bono de prouver qu&rsquo;il est capable de mieux et de faire taire les critiques en montrant que cette soir&eacute;e allemande n&rsquo;&eacute;tait qu&rsquo;une mauvaise journ&eacute;e qui ne se reproduira pas.<\/p><h4>Des p&eacute;nalit&eacute;s trop nombreuses<\/h4><p>Comme nous l&rsquo;expliquions dans la premi&egrave;re partie, la d&eacute;fense parisienne s&rsquo;est montr&eacute;e &agrave; la hauteur sur l&rsquo;ensemble de la rencontre. Mais s&rsquo;il fallait relever un point noir dans cette performance ce serait sans aucun doute les p&eacute;nalit&eacute;s trop nombreuses et souvent plut&ocirc;t grossi&egrave;res dont se sont rendus les Mousquetaires tout au long de la rencontre. Des p&eacute;nalit&eacute;s qui ont souvent eu le d&eacute;faut de laisser des drives des Centurions en vie en plus de leur offrir des dizaines de yards gratuits. La encore l&rsquo;indiscipline parisienne ne devra pas se reproduire sous peine de couter tr&egrave;s cher face &agrave; des franchises mieux arm&eacute;es que Cologne.<\/p><p>En r&eacute;sum&eacute;, la victoire sera &agrave; retenir pour les Parisiens et les quelques points d&rsquo;am&eacute;liorations, logiques au sortir d&rsquo;une premi&egrave;re rencontre historique, peuvent permettre aux Mousquetaires d&rsquo;entrevoir plut&ocirc;t sereinement l&rsquo;avenir dans cette saison 2023 d&rsquo;ELF.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180309964,"featured_media":610770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[5964],"tags":[5996,4833],"sport":[2785],"saison":[3453],"class_list":["post-610759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elf","tag-cologne-centurions","tag-mousquetaires-de-paris","sport-nfl","saison-3453"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ELF 2023 - Week 1: Le barom&egrave;tre des Mousquetaires - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELF 2023 - Week 1: Le barom&egrave;tre des Mousquetaires - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T20:03:19+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1681\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flavien Jumeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavien Jumeau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/\",\"name\":\"ELF 2023 - Week 1: Le barom\u00e8tre des Mousquetaires - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg\",\"datePublished\":\"2023-06-04T18:03:17+00:00\",\"dateModified\":\"2023-06-04T18:03:19+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg\",\"width\":1681,\"height\":638,\"caption\":\"Mousquetaires week 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELF 2023 &#8211; Week 1: Le barom\u00e8tre des Mousquetaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\",\"name\":\"Flavien Jumeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"caption\":\"Flavien Jumeau\"},\"description\":\"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELF 2023 - Week 1: Le barom&egrave;tre des Mousquetaires - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/","og_locale":"fr_FR","og_type":"article","og_title":"ELF 2023 - Week 1: Le barom&egrave;tre des Mousquetaires - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-06-04T18:03:19+00:00","og_image":[{"width":1681,"height":638,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg","type":"image\/jpeg"}],"author":"Flavien Jumeau","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Flavien Jumeau","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/","url":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/","name":"ELF 2023 - Week 1: Le barom\u00e8tre des Mousquetaires - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg","datePublished":"2023-06-04T18:03:17+00:00","dateModified":"2023-06-04T18:03:19+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/06\/Kyle-Sweet-week-1.jpg","width":1681,"height":638,"caption":"Mousquetaires week 1"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/elf\/elf-2023-week-1-le-barometre-mousquetaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"ELF 2023 &#8211; Week 1: Le barom\u00e8tre des Mousquetaires"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d","name":"Flavien Jumeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","caption":"Flavien Jumeau"},"description":"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!","url":"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/610759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180309964"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=610759"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/610759\/revisions"}],"predecessor-version":[{"id":610773,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/610759\/revisions\/610773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/610770"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=610759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=610759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=610759"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=610759"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=610759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}