{"id":589940,"date":"2023-05-15T11:35:04","date_gmt":"2023-05-15T09:35:04","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=589940"},"modified":"2023-05-15T12:30:20","modified_gmt":"2023-05-15T10:30:20","slug":"sixers-avenir-franchise-play-offs","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/","title":{"rendered":"Philadelphia Sixers\u00a0: Quel avenir pour la franchise apr\u00e8s une nouvelle d\u00e9sillusion en play-offs\u00a0?"},"content":{"rendered":"<h2>Encore une fois &eacute;limin&eacute;s en demi-finale par Boston cette nuit, de grands changements doivent op&eacute;rer chez les Sixers pour sortir de cet encha&icirc;nement d&rsquo;&eacute;checs.<\/h2><p>&nbsp;<\/p><p>Les ann&eacute;es passent et se ressemblent &agrave; Philadelphie. Les Sixers se sont lourdement inclin&eacute;s 88-112 face aux Celtics cette nuit, une victoire synonyme d&rsquo;&eacute;limination en demi-finale. Avec ce nouvel &eacute;chec, la franchise n&rsquo;a plus retrouv&eacute; les finales de conf&eacute;rence depuis 22 ans. Un r&eacute;el changement doit op&eacute;rer au sein des Sixers et de lourdes d&eacute;cisions doivent &ecirc;tre prise d&egrave;s cet &eacute;t&eacute;.<\/p><p>&nbsp;<\/p><h3>Doc Rivers&nbsp;: la d&eacute;faite de trop&nbsp;?<\/h3><p>&nbsp;<\/p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Doc Rivers plans to coach the Sixers next year  <a href=\"https:\/\/t.co\/x0VLtUy4mQ\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/x0VLtUy4mQ<\/a><\/p>\n<p>&mdash; NBACentral (@TheDunkCentral) <a href=\"https:\/\/twitter.com\/TheDunkCentral\/status\/1657875033090293762?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>May 14, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>&nbsp;<\/p><p>Le coach des Sixers viens de manquer sa 31<sup>&egrave;me<\/sup> opportunit&eacute; de terminer une s&eacute;rie de play-offs en carri&egrave;re, un record absolu. C&rsquo;est la septi&egrave;me fois qu&rsquo;il se fait revenir dans une s&eacute;rie men&eacute;e 3-1 ou 3-2 et il est sur quatre d&eacute;faites d&rsquo;affil&eacute; en match 7. Des statistiques peu glorieuses pour coach qui pourtant aimerait rester &agrave; Philadelphie la saison prochaine&nbsp;:<\/p><p>&nbsp;<\/p><blockquote><p>&laquo;&nbsp;Je ne compte pas quitter l&rsquo;&eacute;quipe, je crois qu&rsquo;il me reste deux ans de contrat&nbsp;&raquo;<\/p><\/blockquote><p>&nbsp;<\/p><p>Apr&egrave;s ce nouvel &eacute;chec peu de chances n&eacute;anmoins de voir rester le Doc du c&ocirc;t&eacute; de la Pennsylvanie, surtout vu le d&eacute;samour qu&rsquo;il suscite chez les fans.<\/p><p>&nbsp;<\/p><h3>Les leaders doivent prendre leurs responsabilit&eacute;s<\/h3><p>&nbsp;<\/p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">&ldquo;Me and James, we can't win alone. That's why basketball is played 5-on-5. We need everybody to find ways to be better.&rdquo;<\/p>\n<p>&ndash; Joel Embiid after being eliminated &#128556; <a href=\"https:\/\/t.co\/rxvWta1Eq1\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/rxvWta1Eq1<\/a><\/p>\n<p>&mdash; CBS Sports (@CBSSports) <a href=\"https:\/\/twitter.com\/CBSSports\/status\/1657898259195604996?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>May 14, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>&nbsp;<\/p><p>Une d&eacute;faite en match 7 dans une s&eacute;rie serr&eacute;e face &agrave; Boston n&rsquo;est sur le papier pas une d&eacute;sillusion. Ce qui rend cette d&eacute;faite frustrante c&rsquo;est le manque d&rsquo;envie et l&rsquo;indiff&eacute;rence de l&rsquo;&eacute;quipe dans un moment aussi crucial &agrave; commencer par <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/joel-embiid-philadelphia-76ers-nba\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Joel Embiid<\/a>. Le n&eacute;o-MVP a r&eacute;alis&eacute; une s&eacute;rie dans ses standards avant de s&rsquo;&eacute;crouler compl&egrave;tement au match 7&nbsp;: 15 points &agrave; 5\/18 au tir. Le camerounais a expliqu&eacute; qu&rsquo;il &laquo;&nbsp;aurait pu faire mieux&nbsp;&raquo; avant de bl&acirc;mer ses co&eacute;quipiers&nbsp;:<\/p><p>&nbsp;<\/p><blockquote><p>&laquo;&nbsp;James et moi ne pouvons pas gagner tout seuls&nbsp;&raquo; a d&eacute;clar&eacute; le pivot en interview<\/p><\/blockquote><p>&nbsp;<\/p><p>R&eacute;action &agrave; chaud ou message envers son front office en vue du march&eacute; de l&rsquo;&eacute;t&eacute;&nbsp;? En tout cas les fans des Sixers attendaient plus d&rsquo;excuses de la part de leur leader.<\/p><p>&nbsp;<\/p><p>Son co&eacute;quipier <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/james-harden-philadelphia-76ers-nba\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>James Harden<\/a> est aussi &agrave; bl&acirc;mer. Apr&egrave;s une saison r&eacute;guli&egrave;re satisfaisante le meneur a r&eacute;alis&eacute; une s&eacute;rie en dents de scie. The Beard a sorti deux matchs exceptionnels &agrave; 42 et 45 points avec deux game-winner. Mais il est &eacute;galement capables de proposer des performances m&eacute;diocres au tir comme hier soir&nbsp;: 9 points &agrave; 3\/11 au tir.<\/p><p>&nbsp;<\/p><h3>Tucker, Harris, Harden&nbsp;: que faire sur le march&eacute; des transferts&nbsp;?<\/h3><p>&nbsp;<\/p><p>Aux grands maux les grands rem&egrave;des et le g&eacute;n&eacute;ral manager Daryl Morey va devoir prendre des d&eacute;cisions capitales pour l&rsquo;avenir de la franchise. Tout d&rsquo;abord g&eacute;rer le cas James Harden. Le joueur a jusqu&rsquo;au 29 juin pour d&eacute;cider de prendre sa player option &agrave; <a href=\"https:\/\/www.spotrac.com\/nba\/philadelphia-76ers\/james-harden-6312\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>35 millions de dollars l&rsquo;ann&eacute;e<\/a>. Il avait d&eacute;j&agrave; accept&eacute; de faire des concessions l&rsquo;&eacute;t&eacute; dernier pour aider &agrave; cr&eacute;er une &eacute;quipe comp&eacute;titive.<\/p><p>&nbsp;<\/p><p>S&rsquo;il d&eacute;cide de resigner un contrat moins &eacute;lev&eacute; pour les saisons suivantes, son avenir pourrait &ecirc;tre assur&eacute; &agrave; Philadelphie. En cas de prise de sa player option sans discussion de prolongation, il devrait y avoir des discussions de trade pour &eacute;viter de le perdre en agent libre.<\/p><p>&nbsp;<\/p><p><a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/tobias-harris-philadelphia-76ers-nba\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Tobias Harris<\/a> a r&eacute;alis&eacute; des play-offs solides et est peut &ecirc;tre le joueur le plus r&eacute;gulier des Sixers&nbsp;: 15 points de moyenne a 50% au tir. Pourtant, l&rsquo;ailier dispose d&rsquo;un salaire a 40 millions de dollars la saison prochaine et sera ensuite agent libre. Un trade est donc envisageable pour amener un joueur de plus haut calibre mais des pi&egrave;ces devront absolument lui &ecirc;tre associ&eacute;.<\/p><p>&nbsp;<\/p><p>La derni&egrave;re interrogation est <a href=\"https:\/\/theplayoffs.news\/fr\/nba-basketball\/pj-tucker-bat-record-0-point-0-tir\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>PJ Tucker<\/a>. Le v&eacute;t&eacute;ran de 38 ans a sign&eacute; un contrat &agrave; 11 millions de dollars la saison l&rsquo;&eacute;t&eacute; dernier. Tucker rempli son r&ocirc;le de d&eacute;fenseur agressif et motivateur d&rsquo;&eacute;quipe. N&eacute;anmoins ses performances au tir ont &eacute;t&eacute; irr&eacute;guli&egrave;res et peut parfois &ecirc;tre un poids mort offensif. Il tournait &agrave; 20% de r&eacute;ussite &agrave; trois points contre les Nets puis 48% contre les Celtics. Tucker peut &ecirc;tre un excellent joueur de devoir pour les Sixers mais pourrait servir de pi&egrave;ce pour un potentiel transfert de Tobias Harris.<\/p><p>&nbsp;<\/p><p>L&rsquo;avenir des Sixers va donc se d&eacute;cider dans les prochaines semaines et le management va devoir prendre de grandes d&eacute;cisions.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310163,"featured_media":589951,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[5522,5859],"sport":[2783],"saison":[3453],"class_list":["post-589940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-philadelphia-sixers","tag-play-offs-2023","sport-nba","saison-3453"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Philadelphia Sixers&nbsp;: Quel avenir pour la franchise apr&egrave;s une nouvelle d&eacute;sillusion en play-offs&nbsp;? - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Philadelphia Sixers&nbsp;: Quel avenir pour la franchise apr&egrave;s une nouvelle d&eacute;sillusion en play-offs&nbsp;? - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-15T12:30:20+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vincent Roume\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vincent Roume\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/\",\"name\":\"Philadelphia Sixers\u00a0: Quel avenir pour la franchise apr\u00e8s une nouvelle d\u00e9sillusion en play-offs\u00a0? - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg\",\"datePublished\":\"2023-05-15T09:35:04+00:00\",\"dateModified\":\"2023-05-15T10:30:20+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e1eb37e783b47f37f6df5a709b09eae2\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg\",\"width\":680,\"height\":408,\"caption\":\"Doc Rivers, Philadelphia Sixers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Philadelphia Sixers\u00a0: Quel avenir pour la franchise apr\u00e8s une nouvelle d\u00e9sillusion en play-offs\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e1eb37e783b47f37f6df5a709b09eae2\",\"name\":\"Vincent Roume\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/369ea9e86b8e0b97c7028ca828abb59d958ea6f5a23ce2eb8c04af3eb2dbd218?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/369ea9e86b8e0b97c7028ca828abb59d958ea6f5a23ce2eb8c04af3eb2dbd218?s=96&d=mm&r=g\",\"caption\":\"Vincent Roume\"},\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/vincent-roumegmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Philadelphia Sixers&nbsp;: Quel avenir pour la franchise apr&egrave;s une nouvelle d&eacute;sillusion en play-offs&nbsp;? - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/","og_locale":"fr_FR","og_type":"article","og_title":"Philadelphia Sixers&nbsp;: Quel avenir pour la franchise apr&egrave;s une nouvelle d&eacute;sillusion en play-offs&nbsp;? - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-05-15T10:30:20+00:00","og_image":[{"width":680,"height":408,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg","type":"image\/jpeg"}],"author":"Vincent Roume","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Vincent Roume","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/","name":"Philadelphia Sixers\u00a0: Quel avenir pour la franchise apr\u00e8s une nouvelle d\u00e9sillusion en play-offs\u00a0? - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg","datePublished":"2023-05-15T09:35:04+00:00","dateModified":"2023-05-15T10:30:20+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e1eb37e783b47f37f6df5a709b09eae2"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/05\/FwHi914XwAAWeWc.jpg","width":680,"height":408,"caption":"Doc Rivers, Philadelphia Sixers"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/sixers-avenir-franchise-play-offs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Philadelphia Sixers\u00a0: Quel avenir pour la franchise apr\u00e8s une nouvelle d\u00e9sillusion en play-offs\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e1eb37e783b47f37f6df5a709b09eae2","name":"Vincent Roume","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/369ea9e86b8e0b97c7028ca828abb59d958ea6f5a23ce2eb8c04af3eb2dbd218?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/369ea9e86b8e0b97c7028ca828abb59d958ea6f5a23ce2eb8c04af3eb2dbd218?s=96&d=mm&r=g","caption":"Vincent Roume"},"url":"https:\/\/theplayoffs.news\/fr\/author\/vincent-roumegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/589940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310163"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=589940"}],"version-history":[{"count":3,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/589940\/revisions"}],"predecessor-version":[{"id":589953,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/589940\/revisions\/589953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/589951"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=589940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=589940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=589940"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=589940"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=589940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}