{"id":585541,"date":"2023-04-26T20:58:01","date_gmt":"2023-04-26T18:58:01","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=585541"},"modified":"2023-04-26T20:58:02","modified_gmt":"2023-04-26T18:58:02","slug":"playoffs-nhl-les-enjeux-des-matchs-5","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/","title":{"rendered":"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril"},"content":{"rendered":"<h2>Ce soir seulement deux matchs sont au programme en Playoffs NHL. Les cinqui&egrave;mes rencontres entre Boston et Florida et entre Colorado et Seattle.<\/h2><p>Alors que dans les trois premiers matchs 5 du premier tour de Playoffs aucune &eacute;quipe n&rsquo;est parvenue &agrave; valider son ticket pour la deuxi&egrave;me s&eacute;rie, ce soir une &eacute;quipe peut atteindre cet objectif. Dans l&rsquo;autre duel, le r&eacute;sultat est impr&eacute;visible mais permettrait &agrave; la franchise qui l&rsquo;emporte de quasiment s&eacute;curiser son accession au deuxi&egrave;me tour de phases finales.<\/p><h3>Boston Bruins vs Florida Panthers<\/h3><p>Bien que Carolina a dout&eacute; hier face au Islanders et a laiss&eacute; &eacute;chapper la qualification au prochain tour, les Bruins de Boston ont la possibilit&eacute; de passer ce premier tour des Playoffs de la Stanley Cup 2023 face aux Panthers. Les joueurs de Jim Montgomery ont remport&eacute; 3 des 4 matchs pr&eacute;c&eacute;dents face &agrave; une &eacute;quipe de Florida, assez en dessous mais pas d&eacute;m&eacute;ritante.<\/p><p>Ce soir, les Bruins reviennent au TD Garden, devant leur public et sont donc grands favoris de cette rencontre. A domicile cette ann&eacute;e Boston est quasiment imprenable, m&ecirc;me si les Panthers ont r&eacute;ussi &agrave; prendre le match 2 chez leurs adversaires. A voir si ils peuvent r&eacute;it&eacute;rer l&rsquo;exploit ce soir.<\/p><p>Du c&ocirc;t&eacute; des faits de jeu de ce soir, il faut noter le <a href=\"https:\/\/www.nhl.com\/news\/boston-bruins-florida-panthers-game-5-preview\/c-343919094?tid=343199104\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>potentiel retour du capitaine<\/a> <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/patrice-bergeron-nhl-4560\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Patrice Bergeron<\/a> dans la composition d&rsquo;&eacute;quipe des Bruins. Un retour au bon moment pour le num&eacute;ro 37, apr&egrave;s sa maladie plus persistante que pr&eacute;vue. Pour Florida, le retour d&rsquo;<a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/aaron-ekblad-florida-panthers-nhl\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Ekblad<\/a> devrait aussi faire du bien en d&eacute;fense. Au niveau des pronostics, les Bruins devraient se qualifier ce soir, devant leurs supporters.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-585542 size-medium\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/BERGERON-300x169.jpg\" alt=\"The Free Agent - Bergeron - Playoffs\" width=\"300\" height=\"169\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/BERGERON-300x169.jpg 300w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/BERGERON-768x432.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/BERGERON-705x397.jpg 705w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/BERGERON.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><h3>Colorado Avalanche vs Seattle Kraken<\/h3><p>Dans l&rsquo;autre affrontement de la soir&eacute;e, l&rsquo;Avalanche du Colorado re&ccedil;oit le Kraken de Seattle. Dans cette s&eacute;rie palpitante, le score est &agrave; deux partout entre ces deux franchises. Lors de la derni&egrave;re rencontre, c&rsquo;est <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/jordan-eberle-nhl-10064\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Eberle<\/a> qui avait donn&eacute; la victoire au sien &agrave; domicile en prolongations.<\/p><p>Pour ce nouveau duel de Playoffs, le Kraken se d&eacute;place plein de motivation. Pas forc&eacute;ment vu comme favoris de cette s&eacute;rie, les joueurs de Dave Hakstol surprennent par leur beau jeu collectif et leur capacit&eacute; &agrave; ne rien l&acirc;cher. De l&rsquo;autre c&ocirc;t&eacute;, Colorado va une nouvelle fois se reposer sur ses leaders <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/nathan-mackinnon-nhl-6083938\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>MacKinnon<\/a> et <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/mikko-rantanen-nhl-7799876\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Rantanen<\/a> pour faire le jeu &agrave; domicile.<\/p><p><a href=\"https:\/\/www.nhl.com\/news\/seattle-kraken-regroup-for-game-5-without-injured-jared-mccann\/c-343897870?tid=343453068\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Deux absents de marque seront &agrave; noter dans la rencontre de ce soir<\/a> entre les deux &eacute;quipes. Pour le Kraken du Seattle, il faudra composer sans l&rsquo;attaquant phare de cette saison, <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/jared-mccann-nhl-6229554\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Jared McCann<\/a>. Touch&eacute; au dernier match, il ne sera pas pr&eacute;sent cette nuit. Quant &agrave; Colorado, &ccedil;a sera justement l&rsquo;aggresseur de McCann qui passera sa soir&eacute;e au chaud pour cette nouvelle rencontre de Playoffs. <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/cale-makar-nhl-8467126\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Cale Makar<\/a> est suspendu pour le choc contre l&rsquo;attaquant du Kraken dans le match 4.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-585543 size-medium\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-300x200.jpg\" alt=\"The Free Agent - Makar - Playoffs\" width=\"300\" height=\"200\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-300x200.jpg 300w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-1030x687.jpg 1030w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-1536x1025.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-1500x1001.jpg 1500w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-705x470.jpg 705w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR-1320x881.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MAKAR.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310143,"featured_media":585544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[187,26],"tags":[253,91,368,24,96,720],"sport":[2784],"saison":[3453],"class_list":["post-585541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nhl","category-nhl","tag-boston-bruins","tag-colorado-avalanche","tag-florida-panthers","tag-nhl","tag-playoffs","tag-seattle-kraken","sport-nhl","saison-3453"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T20:58:02+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Th\u00e9o Ganiage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Th\u00e9o Ganiage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/\",\"name\":\"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg\",\"datePublished\":\"2023-04-26T18:58:01+00:00\",\"dateModified\":\"2023-04-26T18:58:02+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/898dffbe68cd03b32d24c64ce7fa4085\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg\",\"width\":628,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/898dffbe68cd03b32d24c64ce7fa4085\",\"name\":\"Th\u00e9o Ganiage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e2b9fd2c51fad124de94f1af5f8f024beb650dddbff16415baee387c2251a63e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e2b9fd2c51fad124de94f1af5f8f024beb650dddbff16415baee387c2251a63e?s=96&d=mm&r=g\",\"caption\":\"Th\u00e9o Ganiage\"},\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/theo-ganiagegmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/","og_locale":"fr_FR","og_type":"article","og_title":"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-04-26T18:58:02+00:00","og_image":[{"width":628,"height":480,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg","type":"image\/jpeg"}],"author":"Th\u00e9o Ganiage","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Th\u00e9o Ganiage","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/","name":"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg","datePublished":"2023-04-26T18:58:01+00:00","dateModified":"2023-04-26T18:58:02+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/898dffbe68cd03b32d24c64ce7fa4085"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/04\/MISE-EN-AVANT-1.jpg","width":628,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nhl\/playoffs-nhl-les-enjeux-des-matchs-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Playoffs NHL 2023 : Les enjeux des matchs du 27 avril"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/898dffbe68cd03b32d24c64ce7fa4085","name":"Th\u00e9o Ganiage","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e2b9fd2c51fad124de94f1af5f8f024beb650dddbff16415baee387c2251a63e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2b9fd2c51fad124de94f1af5f8f024beb650dddbff16415baee387c2251a63e?s=96&d=mm&r=g","caption":"Th\u00e9o Ganiage"},"url":"https:\/\/theplayoffs.news\/fr\/author\/theo-ganiagegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/585541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310143"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=585541"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/585541\/revisions"}],"predecessor-version":[{"id":585546,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/585541\/revisions\/585546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/585544"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=585541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=585541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=585541"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=585541"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=585541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}