{"id":568044,"date":"2023-02-21T09:14:17","date_gmt":"2023-02-21T08:14:17","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=568044"},"modified":"2023-02-21T09:16:05","modified_gmt":"2023-02-21T08:16:05","slug":"new-orleans-pelicans-attentes-fin-saison","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/","title":{"rendered":"New Orleans Pelicans : quelles attentes pour la fin de saison ?"},"content":{"rendered":"<h2>Alors que la NBA s&rsquo;accorde quelques jours de repos, les &eacute;quipes de TFA vous proposent un focus sur certaines des 30 franchises de la ligue, afin de faire le point sur ce qui s&rsquo;est d&eacute;j&agrave; d&eacute;roul&eacute; et envisager la suite, en se demandant quels sont les attentes et ambitions r&eacute;alisables pour cette derni&egrave;re ligne droite de la saison.<\/h2><p>&nbsp;<\/p><p style=\"text-align: center\"><strong>Aujourd&rsquo;hui, les New Orleans Pelicans<\/strong><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-568048 aligncenter\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/pels-1000x600.png\" alt=\"\" width=\"423\" height=\"254\"><\/p><h3>La premi&egrave;re partie de saison<\/h3><p>Le moins que l&rsquo;on puisse dire, c&rsquo;est qu&rsquo;il vaut mieux aimer les sensations fortes et les rebondissements pour suivre les Pelicans. Entre s&eacute;rie d&rsquo;impressionnantes victoires et blessures &agrave; r&eacute;p&eacute;titions, il n&rsquo;y a qu&rsquo;un pas en Louisiane.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-567971\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/Capture1.png\" alt=\"\" width=\"512\" height=\"487\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/Capture1.png 512w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/Capture1-300x285.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p><p>Apr&egrave;s un d&eacute;but de saison plut&ocirc;t tranquille, bien install&eacute; dans le large peloton de t&ecirc;te de la conf&eacute;rence Ouest, les vieux d&eacute;mons de l&rsquo;&eacute;quipe vont ressurgir. Avec en parfait exemple de ce ph&eacute;nom&egrave;ne : Zion.<\/p><p>Au jour d&rsquo;aujourd&rsquo;hui, <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/zion-williamson-nba-8791256\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Zion Williamson<\/a> a rat&eacute; pas moins de la moiti&eacute; de la saison. Et cela n&rsquo;est pas pr&ecirc;t de s&rsquo;arranger puisque la date de son retour reste encore floue.<\/p><p>Le constat est d&rsquo;ailleurs le m&ecirc;me pour <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/brandon-ingram-nba-7826352\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Brandon Ingram<\/a>. Bien qu&rsquo;il retrouve actuellement petit &agrave; petit les parquets, c&rsquo;est seulement 24 rencontres disput&eacute;es pour le joueur de 25 ans. Difficile d&rsquo;&ecirc;tre performant sur la dur&eacute;e dans ces conditions.<\/p><p><iframe loading=\"lazy\" title=\"Zion Williamson is BACK ! 2023 Season Highlights\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/0nEXtQ96dRs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p><h3>Retour sur la p&eacute;riode de trade et le nouvel effectif<\/h3><p>La p&eacute;riode de trade deadline a &eacute;t&eacute; assez calme du cot&eacute; de la Nouvelle Orl&eacute;ans. Le groupe semble &ecirc;tre bien form&eacute;, c&rsquo;&eacute;tait donc un jeu des petites retouches auquel s&rsquo;est adonn&eacute; Trajan Langdon, le GM des Pels.<\/p><p>C&rsquo;est donc <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/josh-richardson-nba-5162380\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Josh Richardson<\/a> qui a d&eacute;pos&eacute; ses valises en ville. Il sera &eacute;chang&eacute; contre <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/devonte-graham-nba-6267202\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Devonte Graham<\/a>. Cette transaction pourrait sembler anodine mais elle para&icirc;t sur le papier apporter plus de fiabilit&eacute; au niveau de la rotation. En effet, Graham semblait avoir un apport moindre compar&eacute; &agrave; la saison pass&eacute;, l&rsquo;&eacute;volution de l&rsquo;effectif ayant s&ucirc;rement &eacute;t&eacute; l&rsquo;une des causes de cela.<\/p><h3>Le calendrier de fin de saison<\/h3><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-featured_large_middle_high wp-image-568054\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/Capture-decran-7-1-e1676813768908-440x600.png\" alt=\"\" width=\"440\" height=\"600\"><\/p><p>Comme pas mal de leurs concurrents, la route pour acc&eacute;der &agrave; une bonne place au soleil de la postseason ne sera pas de tout repos.<\/p><p>Hormis une encha&icirc;nement plut&ocirc;t abordable au mois de Mars (Houston x2, San Antonio puis Charlotte) c&rsquo;est surtout du c&ocirc;t&eacute; du sprint final qu&rsquo;il va falloir s&rsquo;accrocher pour les hommes de Willie Green.<\/p><h3>Nos attentes pour les Pelicans<\/h3><p>Vont-ils concr&eacute;tiser toutes les bonnes choses que l&rsquo;on a d&eacute;j&agrave; vu en d&eacute;but de saison ? On l&rsquo;esp&egrave;re. Seront-ils au complet pour cette fin de saison ? Ca c&rsquo;est moins s&ucirc;r.<\/p><p>Bien que le facteur blessure soit inh&eacute;rent &agrave; tout les effectifs de NBA, ce dernier semble d&rsquo;autant plus important pour les Pelicans, tant ils ont pu souffrir de p&eacute;pins physiques sur ces derniers mois.<\/p><p>En tout cas la bataille sera rude et il faudra un groupe soud&eacute; pour esp&eacute;rer faire mieux que la saison derni&egrave;re.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310133,"featured_media":568057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[774,23,842,627],"sport":[2783],"saison":[2791,3453],"class_list":["post-568044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-brandon-ingram","tag-nba-tag","tag-new-orleans-pelicans","tag-zion-williamson","sport-nba","saison-2791","saison-3453"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T09:16:05+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axel Bey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axel Bey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/\",\"name\":\"New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg\",\"datePublished\":\"2023-02-21T08:14:17+00:00\",\"dateModified\":\"2023-02-21T08:16:05+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e817c5ceccd4a0abbf6dfee25b65cd91\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"New Orleans Pelicans vont-il y arriver ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Orleans Pelicans : quelles attentes pour la fin de saison ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e817c5ceccd4a0abbf6dfee25b65cd91\",\"name\":\"Axel Bey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/85c288096bec239377295bd49ba28c8b1c716367626a996507fabceb042d846a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/85c288096bec239377295bd49ba28c8b1c716367626a996507fabceb042d846a?s=96&d=mm&r=g\",\"caption\":\"Axel Bey\"},\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/axelbeyicloud-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/","og_locale":"fr_FR","og_type":"article","og_title":"New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-02-21T08:16:05+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg","type":"image\/jpeg"}],"author":"Axel Bey","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Axel Bey","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/","name":"New Orleans Pelicans : quelles attentes pour la fin de saison ? - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg","datePublished":"2023-02-21T08:14:17+00:00","dateModified":"2023-02-21T08:16:05+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e817c5ceccd4a0abbf6dfee25b65cd91"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/02\/peels.jpg","width":1920,"height":1080,"caption":"New Orleans Pelicans vont-il y arriver ?"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/new-orleans-pelicans-attentes-fin-saison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"New Orleans Pelicans : quelles attentes pour la fin de saison ?"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/e817c5ceccd4a0abbf6dfee25b65cd91","name":"Axel Bey","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/85c288096bec239377295bd49ba28c8b1c716367626a996507fabceb042d846a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85c288096bec239377295bd49ba28c8b1c716367626a996507fabceb042d846a?s=96&d=mm&r=g","caption":"Axel Bey"},"url":"https:\/\/theplayoffs.news\/fr\/author\/axelbeyicloud-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/568044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310133"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=568044"}],"version-history":[{"count":5,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/568044\/revisions"}],"predecessor-version":[{"id":568509,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/568044\/revisions\/568509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/568057"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=568044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=568044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=568044"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=568044"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=568044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}