{"id":538086,"date":"2023-01-21T10:42:29","date_gmt":"2023-01-21T09:42:29","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=538086"},"modified":"2023-01-21T10:42:30","modified_gmt":"2023-01-21T09:42:30","slug":"jeunes-warriors-se-paient-cavaliers","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/","title":{"rendered":"Les jeunes Warriors se paient les Cavaliers !"},"content":{"rendered":"<h2><strong>Priv&eacute;s de leur &laquo;&nbsp;Big Three&nbsp;&raquo;, les Warriors ont laiss&eacute; les jeunes prendre la mesure des Cavaliers pour boucler leur road trip.<\/strong><\/h2><p>Il n&rsquo;&eacute;tait pas vraiment pr&eacute;vu que les Cavaliers, priv&eacute;s de <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/donovan-mitchell-nba-7817618\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'><strong>Donovan Mitchell<\/strong><\/a>, soient largement domin&eacute;s par les Warriors lors de la rencontre de vendredi soir. Pourtant, les Warriors ont r&eacute;ussi &agrave; cr&eacute;er la surprise en s&rsquo;imposant avec la mani&egrave;re en Ohio, gr&acirc;ce notamment &agrave; la performance de <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/jordan-poole-golden-state-warriors-nba\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'><strong>Jordan Poole<\/strong><\/a> au centre de l&rsquo;attaque (32 points, 3 rebonds et 2 passes). Les Warriors ont globalement domin&eacute; le match, ne laissant les Cavaliers mener au score qu&rsquo;&agrave; deux reprises.<\/p><p>La cl&eacute; de la victoire des Warriors a &eacute;t&eacute; leur performance offensive. Les jeunes joueurs de Steve Kerr ont opt&eacute; pour une strat&eacute;gie de tir facile et cela a pay&eacute; : 23 sur 43 derri&egrave;re l&rsquo;arc (54% de r&eacute;ussite) et 50% aux tirs en g&eacute;n&eacute;ral. Les Cavaliers, bien qu&rsquo;ils aient eux-m&ecirc;mes r&eacute;ussi un bon pourcentage aux tirs (50%), ont &eacute;t&eacute; d&eacute;pass&eacute;s par l&rsquo;adresse ext&eacute;rieure de leurs adversaires.<\/p><p>Ce match a &eacute;t&eacute; un v&eacute;ritable &laquo;&nbsp;upset&nbsp;&raquo; pour les Cavaliers, mais c&rsquo;est une tr&egrave;s bonne op&eacute;ration pour les Warriors qui &eacute;quilibrent &agrave; nouveau leur bilan &agrave; 23 victoires pour autant de d&eacute;faites. Les Warriors ont r&eacute;ussi &agrave; cr&eacute;er l&rsquo;exploit malgr&eacute; l&rsquo;absence de certains de leurs cadres, montrant leur profondeur de banc. M&ecirc;me si les Cavaliers ont essay&eacute; de revenir dans le money-time, ils n&rsquo;ont pas r&eacute;ussi &agrave; contenir les Warriors qui ont su maintenir leur avance jusqu&rsquo;&agrave; la fin.<\/p><h3><strong>Back to the future<\/strong><\/h3><p>Le questionnement autour de l&rsquo;avenir des Warriors est assez r&eacute;current.<\/p><p>Sans Stephen Curry, Klay Thompson ni Draymond Green, ce match a donn&eacute; un aper&ccedil;u de ce que pourrait &ecirc;tre le futur de Golden State, quand ces joueurs auront pris leur retraite ou seront potentiellement partis ailleurs. Ce futur sera probablement centr&eacute; autour de Jordan Poole, qui a &eacute;t&eacute; l&rsquo;option principale en attaque sans les v&eacute;t&eacute;rans, mais aussi de Jonathan Kuminga qui a &eacute;t&eacute; pr&eacute;cieux avec 10 points, 3 rebonds et 5 passes, et d&rsquo;autres joueurs utiles qui pourraient s&rsquo;installer chez les Warriors &agrave; long terme, tels que Donte DiVincenzo (17 points, 6 rebonds, 4 passes et 4 interceptions), Ty Jerome (22 points et 8 passes) et Anthony Lamb (12 points et 2 passes).<\/p><p>Plus largement, le futur de la franchise est li&eacute; &agrave; Steve Kerr et &agrave; son syst&egrave;me offensif performant, capable de briser la d&eacute;fense adverse, quel que soit le personnel sur le terrain. Leur performance lors de ce match montre qu&rsquo;ils peuvent avoir un avenir prometteur, m&ecirc;me sans leur &laquo;&nbsp;Big Three&nbsp;&raquo; habituel.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":538087,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[1097],"sport":[],"saison":[],"class_list":["post-538086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-golden-state-warriors"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-21T10:42:30+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Taudin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Taudin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/\",\"name\":\"Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg\",\"datePublished\":\"2023-01-21T09:42:29+00:00\",\"dateModified\":\"2023-01-21T09:42:30+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg\",\"width\":1200,\"height\":783,\"caption\":\"Jan 20, 2023; Cleveland, Ohio, USA; Golden State Warriors guard Jordan Poole (3) drives to the basket against Cleveland Cavaliers center Jarrett Allen (31) during the first half at Rocket Mortgage FieldHouse. Mandatory Credit: Ken Blaze-USA TODAY Sports\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les jeunes Warriors se paient les Cavaliers !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\",\"name\":\"Charles Taudin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"caption\":\"Charles Taudin\"},\"description\":\"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.\",\"sameAs\":[\"https:\/\/www.instagram.com\/ctaudin_\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/","og_locale":"fr_FR","og_type":"article","og_title":"Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-01-21T09:42:30+00:00","og_image":[{"width":1200,"height":783,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg","type":"image\/jpeg"}],"author":"Charles Taudin","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Charles Taudin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/","name":"Les jeunes Warriors se paient les Cavaliers ! - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg","datePublished":"2023-01-21T09:42:29+00:00","dateModified":"2023-01-21T09:42:30+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/tinywow_jordan-poole-january-21-2023_12059733.jpg","width":1200,"height":783,"caption":"Jan 20, 2023; Cleveland, Ohio, USA; Golden State Warriors guard Jordan Poole (3) drives to the basket against Cleveland Cavaliers center Jarrett Allen (31) during the first half at Rocket Mortgage FieldHouse. Mandatory Credit: Ken Blaze-USA TODAY Sports"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jeunes-warriors-se-paient-cavaliers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Les jeunes Warriors se paient les Cavaliers !"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133","name":"Charles Taudin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","caption":"Charles Taudin"},"description":"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.","sameAs":["https:\/\/www.instagram.com\/ctaudin_\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/538086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=538086"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/538086\/revisions"}],"predecessor-version":[{"id":538089,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/538086\/revisions\/538089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/538087"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=538086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=538086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=538086"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=538086"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=538086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}