{"id":526763,"date":"2023-01-13T15:27:31","date_gmt":"2023-01-13T14:27:31","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=526763"},"modified":"2023-01-13T15:27:32","modified_gmt":"2023-01-13T14:27:32","slug":"tous-les-terrains-triple-a-arbitre-robot","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/","title":{"rendered":"Tous les terrains de Triple-A auront un arbitre robot"},"content":{"rendered":"<h2><strong>Le jugement de la zone de frappe sera robotis&eacute; sur les 30 terrains de Triple-A la saison prochaine.<\/strong><\/h2><p>Dans la moiti&eacute; des terrains de Triple-A les d&eacute;cisions concernant la zone de frappe seront enti&egrave;rement prise par le robot tandis que dans l&rsquo;autre moiti&eacute; les entra&icirc;neurs auront la possibilit&eacute; de demander une r&eacute;vision du jugement au syst&egrave;me &eacute;lectronique de jugement. Chaque &eacute;quipe se verra accord&eacute; 3 challenges et les conservera s&rsquo;ils sont corrects durant la rencontre.<\/p><p>Apr&egrave;s les premiers tests r&eacute;alis&eacute; en 2019 puis en 2021, cette impl&eacute;mentation en triple-A rapproche un peu plus son utilisation en MLB.<\/p><p>Les premiers retours ont &eacute;t&eacute; plus que positifs concernant l&rsquo;utilisation de ce syst&egrave;me &eacute;lectronique et si cela continue ainsi, rien ne pourra plus emp&ecirc;cher la MLB de l&rsquo;impl&eacute;menter dans ses stades.<\/p><p>Cette saison, la MLB proc&egrave;de d&eacute;j&agrave; &agrave; quelques changements comme l&rsquo;utilisation d&rsquo;une horloge pour les lanceurs, la limitation des tentatives de pickoff mais aussi des shifts d&eacute;fensifs et l&rsquo;augmentation de la taille des bases. Cette saison, une emphase sera aussi faite sur l&rsquo;abaissement du haut de la zone de frappe pour tenter de limiter le nombre de retraits au b&acirc;ton.<\/p><p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":526808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[188,9],"tags":[5276,2588],"sport":[],"saison":[],"class_list":["post-526763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-mlb","category-mlb","tag-abritre-robot","tag-triple-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T15:27:32+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Taudin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Taudin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/\",\"name\":\"Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg\",\"datePublished\":\"2023-01-13T14:27:31+00:00\",\"dateModified\":\"2023-01-13T14:27:32+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg\",\"width\":700,\"height\":475,\"caption\":\"triple A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tous les terrains de Triple-A auront un arbitre robot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\",\"name\":\"Charles Taudin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"caption\":\"Charles Taudin\"},\"description\":\"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.\",\"sameAs\":[\"https:\/\/www.instagram.com\/ctaudin_\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/","og_locale":"fr_FR","og_type":"article","og_title":"Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-01-13T14:27:32+00:00","og_image":[{"width":700,"height":475,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg","type":"image\/jpeg"}],"author":"Charles Taudin","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Charles Taudin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/","name":"Tous les terrains de Triple-A auront un arbitre robot - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg","datePublished":"2023-01-13T14:27:31+00:00","dateModified":"2023-01-13T14:27:32+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/01\/Trackman-1-1.jpg","width":700,"height":475,"caption":"triple A"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-mlb\/tous-les-terrains-triple-a-arbitre-robot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Tous les terrains de Triple-A auront un arbitre robot"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133","name":"Charles Taudin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","caption":"Charles Taudin"},"description":"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.","sameAs":["https:\/\/www.instagram.com\/ctaudin_\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/526763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=526763"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/526763\/revisions"}],"predecessor-version":[{"id":526822,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/526763\/revisions\/526822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/526808"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=526763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=526763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=526763"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=526763"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=526763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}