{"id":1504462,"date":"2025-10-13T19:37:56","date_gmt":"2025-10-13T17:37:56","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-10-28T19:09:15","modified_gmt":"2025-10-28T18:09:15","slug":"oklahoma-city-thunder","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/","title":{"rendered":"Guide NBA 2025-2026 : Oklahoma City Thunder"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Une domination historique <\/h3><p>Champion NBA 2024-25, le <strong>Thunder <\/strong>a r&eacute;alis&eacute; l&rsquo;une des saisons les plus dominantes de l&rsquo;histoire de la ligue l&rsquo;an dernier. L&rsquo;&eacute;quipe a conclu la saison r&eacute;guli&egrave;re avec 68 victoires et 14 d&eacute;faites, soit le meilleur bilan de toute la <a href=\"https:\/\/theplayoffs.news\/fr\/category\/sports\/basketball-sports\/nba\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA <\/a>et une 1&#691;&#7497; place incontest&eacute;e &agrave; l&rsquo;Ouest.<\/p><p>Preuve de la domination sans partage des prot&eacute;g&eacute;s de <strong>Mark Daigneault<\/strong>, l&rsquo;&eacute;cart de 16 victoires avec son dauphin, les <strong>Houston Rockets<\/strong>, repr&eacute;sente la plus grande diff&eacute;rence entre le 1er et le 2e de la conf&eacute;rence Ouest depuis la fusion NBA-ABA en 1977.<\/p><p>Mieux, le Thunder a termin&eacute; la saison r&eacute;guli&egrave;re avec un Net Rating de +12,9 points, effa&ccedil;ant des tablettes le pr&eacute;c&eacute;dent record d&eacute;tenu par les <strong>Los Angeles Lakers <\/strong>1971-72 (+12,3), vieux de plus d&rsquo;un demi-si&egrave;cle.<\/p><p>V&eacute;ritable rouleau compresseur tout au  long de la saison, <strong>OKC <\/strong>s&rsquo;est appuy&eacute; sur une d&eacute;fense de fer (1er au Defensive Rating) et une agressivit&eacute; sans pareil (1er aux interception, 2&egrave;me aux contres!) pour alimenter une attaque &eacute;lite (3&egrave;me &agrave; l&rsquo;Offensive Rating). Le tout sous l&rsquo;impulsion d&rsquo;un homme : Shai Gilgeous-Alexander.<\/p><p>Auteur d&rsquo;un exercice de toute beaut&eacute;, marqu&eacute; par une premi&egrave;re place au classement des meilleurs marqueurs de la ligue et une premi&egrave;re couronne de MVP de la saison r&eacute;guli&egrave;re, le Canadien a sign&eacute; <strong>32,7 points<\/strong> &agrave; 51,9% au tir, <strong>6,4 passes<\/strong>, et <strong>5,0 rebonds<\/strong> de moyenne. Au-del&agrave; des chiffres, exceptionnels, SGA a fait preuve d&rsquo;une domination et d&rsquo;une efficacit&eacute; rarement vues pour un arri&egrave;re.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">&#127464;&#127462; Shai Gilgeous-Alexander en 2024\/25 : <br><br>&#128313; 72 matchs de suite &agrave; 20 points ou +<br>&#128313; 49 matchs &agrave; 30 points ou +<br>&#128313; 68 victoires, record de franchise<br>&#128313; 5&egrave;me plus grande SR All-Time<br>&#128313; 4 matchs &agrave; 50 points ou +<br>&#128313; 32.7 points &agrave; 64% TS<br><br>Most Valuable Player 2025. <a href=\"https:\/\/t.co\/GihQj49jfA\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/GihQj49jfA<\/a><\/p>&mdash; Oklahoma City Thunder France (@OKCThunderFR) <a href=\"https:\/\/twitter.com\/OKCThunderFR\/status\/1925280437418827918?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>May 21, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>Dans la roue de son leader, le Thunder a remport&eacute; le deuxi&egrave;me titre de son histoire apr&egrave;s le sacre de 1979 (&eacute;poque Seattle Supersonics) au terme d&rsquo;une campagne de Playoffs haletante. Vainqueur des Nuggets en 7 manches en demi-finale de conf&rsquo;, OKC a connu le m&ecirc;me sc&eacute;nario lors des Finals pour rafler la mise (4-3 face aux Pacers). La conclusion d&rsquo;une saison extraordinaire pour les co&eacute;quipiers d&rsquo;Ousmane Dieng. <\/p><h3 class=\"wp-block-heading\">S&eacute;curiser l&rsquo;avenir et gagner maintenant<\/h3><p>Avec ce triomphe, le <strong>Thunder 2024-25<\/strong> est devenu le deuxi&egrave;me effectif le plus jeune de l&rsquo;histoire &agrave; remporter le troph&eacute;e <strong>Larry O&rsquo;Brien<\/strong>. Une caract&eacute;ristique qui a convaincu le front office de ne p&acirc;s trop remodeler son roster. Ainsi le GM <strong>Sam Presti<\/strong>, consid&eacute;r&eacute; comme l&rsquo;un des meilleurs dirigeants de la NBA, s&rsquo;est content&eacute; de resigner ses cadres pour s&rsquo;assurer de leur pr&eacute;sence au sein de l&rsquo;&eacute;quipe sur le long terme.<\/p><p><strong>Shai Gilgeous-Alexander<\/strong>, Jalen Williams et Chet Holmgren, les 3 stars d&rsquo;OKC ont donc tous sign&eacute; une extension de contrat cet &eacute;t&eacute;, les liant au Thunder pour au moins cinq ans. <strong>Shai <\/strong>a logiquement paraph&eacute; la prolongation la plus prestigieuse avec pas moins de 285 millions de dollars sur 4 saisons, pour h&eacute;riter du plus gros salaire annuel de l&rsquo;histoire de la NBA (71,3 millions par an).<\/p><p>Holmgren et Williams ont &eacute;galement rempil&eacute; pour <strong>5 ans<\/strong>, avec &agrave; la cl&eacute; des montants respectifs pouvant atteindre <strong>239M$<\/strong> et <strong>287M$ en fonction des diff&eacute;rentes primes existantes au contrat<\/strong>.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Shai Gilgeous-Alexander and the Oklahoma City Thunder have agreed to a 4-year, $285 million super max contract extension, per <a href=\"https:\/\/twitter.com\/ShamsCharania?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@ShamsCharania<\/a> <br><br>SGA will now have the largest annual salary in league history &#9889;&#65039;&#128293; <a href=\"https:\/\/t.co\/eYvl2Z9v0G\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/eYvl2Z9v0G<\/a><\/p>&mdash; NBA TV (@NBATV) <a href=\"https:\/\/twitter.com\/NBATV\/status\/1940049807785025569?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>Retenu en 15&egrave;me position de la derni&egrave;re Draft, <strong>Thomas Sorber<\/strong>, victime d&rsquo;une rupture des ligaments crois&eacute;s durant l&rsquo;intersaison, n&rsquo;aura pas la chance de faire ses premiers pas en NBA cette saison. A l&rsquo;instar de <strong>Chet Holmgren<\/strong> en 2022 et de Nikola Topic en 2024, l&rsquo;ancien de Georgetown suivra l&rsquo;exercice d&rsquo;OKC depuis les gradins. D&eacute;sormais r&eacute;tabli, Topic fera lui ses grands d&eacute;buts en <a href=\"https:\/\/theplayoffs.news\/fr\/category\/sports\/basketball-sports\/nba\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA <\/a>cette ann&eacute;e et pourrait &eacute;voluer &agrave; la m&egrave;ne en relais de SGA<\/p><h3 class=\"wp-block-heading\">Le Thunder vers le back to back ?<\/h3><p>Malgr&eacute; ses statistiques historiques, le Thunder n&rsquo;a pas remport&eacute; le titre sans difficult&eacute;s. Les s&eacute;ries face aux <strong>Indiana Pacers<\/strong> et aux <strong>Denver Nuggets<\/strong> ont &eacute;t&eacute; de vrais tests, et rappel&eacute; que la postseason &eacute;tait un autre monde.<\/p><p>La saison 2025-26 s&rsquo;annonce ainsi plus exigeante encore, avec le retour en force des Nuggets et la mont&eacute;e en puissance des Houston Rockets, d&eacute;sormais men&eacute;s par <strong>Kevin Durant<\/strong>.<\/p><p>Favori annonc&eacute; de l&rsquo;exercice 2025-2026, <strong>OKC <\/strong>aborde la saison avec un nouveau statut. Et la pression qui va avec. La bande &agrave; Jalen Williams sera donc attendue de pied ferme chaque soir, et devra confirmer son superbe parcours de l&rsquo;an dernier. Un challenge de taille qui n&rsquo;autorisera aucune d&eacute;convenue.<\/p><p>Pour autant les prot&eacute;g&eacute;s de <strong>Mark Daigneault<\/strong> auront une fois de plus les cartes en main pour rafler un second titre de rang. Sur les ailes d&rsquo;un big 3 aguerri par l&rsquo;adversit&eacute; de la derni&egrave;re campagne de <strong>Playoffs<\/strong>, dans le sillage de son MVP en titre et gr&acirc;ce &agrave; sa grande exp&eacute;rience collective, OKC pourrait bien devenir la premi&egrave;re &eacute;quipe &agrave; encha&icirc;ner deux titres successifs depuis les Warriors en 2017 et 2018. <\/p><h3 class=\"wp-block-heading\">L&rsquo;av&egrave;nement attendu de Jalen Williams<\/h3><p>Deuxi&egrave;me option de l&rsquo;&eacute;quipe derri&egrave;re Shai Gilgeous-Alexander, <a href=\"https:\/\/www.basketball-reference.com\/players\/w\/willija06\/gamelog-playoffs\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Jalen Williams<\/a> a sign&eacute; des moyennes de <strong>21,6 points, 5,3 rebonds et 5,1 passes<\/strong> la saison derni&egrave;re, raflant au passage une premi&egrave;re s&eacute;lection au All-Star Game et une place dans une <strong>All-NBA Team<\/strong>.<\/p><p>Essentiel dans les performances collectives du <strong>Thunder<\/strong>, J-Dub a profit&eacute; de la postseason pour montrer qu&rsquo;il avait l&rsquo;&eacute;toffe d&rsquo;un grand. Auteur de 7 match &agrave; 26 points ou plus dont une perf monstrueuse &agrave; 40 unit&eacute;s lors du Game 5 des NBA Finals, l&rsquo;ancien de Santa Clara a laiss&eacute; entrevoir le potentiel d&rsquo;une superstar. <\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Jalen Williams' 40-point night helps OKC take Game 5, and puts them one win away from the Championship!<a href=\"https:\/\/twitter.com\/hashtag\/NBAFinals?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#NBAFinals<\/a> <a href=\"https:\/\/t.co\/qZJdR26Hqi\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/qZJdR26Hqi<\/a><\/p>&mdash; NBA UK (@NBAUK) <a href=\"https:\/\/twitter.com\/NBAUK\/status\/1934861931732717902?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 17, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>A l&rsquo;image de <strong>Chet Holmgren<\/strong>, attendu &agrave; un autre niveau cette ann&eacute;e pour sa 3&egrave;me saison dans la ligue, <strong>Jalen Williams<\/strong> pourrait lui aussi prendre une nouvelle dimension en 2025-2026. Une progression qui pourrait faire du Thunder un v&eacute;ritable serpent &agrave; deux t&ecirc;tes, et du duo Gilgeous-Alexander &ndash; Williams l&rsquo;un des plus redoutables de la ligue. Une perspective effrayante pour l&rsquo;ensemble de la ligue !<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310263,"featured_media":1504469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"custom-templates\/guide-child.php","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[10],"tags":[4276,9194,5768,23,52,4335,648,8037,395],"sport":[],"saison":[],"class_list":["post-1504462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-chet-holmgren","tag-guide-nba","tag-jalen-williams","tag-nba-tag","tag-okc","tag-oklahoma-city","tag-oklahoma-city-thunder","tag-shai-gilgeous-alexander-2","tag-thunder"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guide NBA 2025-2026 : Oklahoma City Thunder<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide NBA 2025-2026 : Oklahoma City Thunder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T19:09:15+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"1595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maxime Bodilis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Bodilis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/\",\"name\":\"Guide NBA 2025-2026 : Oklahoma City Thunder\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg\",\"datePublished\":\"2025-10-13T17:37:56+00:00\",\"dateModified\":\"2025-10-28T18:09:15+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/d871768c70a3f830131ee72b74bbd11d\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg\",\"width\":980,\"height\":1595,\"caption\":\"Shai Gilgeous-Alexander during the Thunder Media Day for the 25-26 NBA season at the Paycom Center Monday, Sept. 29, 2025.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide NBA 2025-2026 : Oklahoma City Thunder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/d871768c70a3f830131ee72b74bbd11d\",\"name\":\"Maxime Bodilis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e151acde6515a05571e0035bf803336362ba4f5e565dba89323f14d014ea180?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e151acde6515a05571e0035bf803336362ba4f5e565dba89323f14d014ea180?s=96&d=mm&r=g\",\"caption\":\"Maxime Bodilis\"},\"description\":\"R\u00e9dac\\\\' Chef \u00ab Basket \u00bb charg\u00e9 de la qualit\u00e9 des contenus et du respect de notre ligne \u00e9ditoriale. Ancien joueur de la SIG Strasbourg reconverti dans le journalisme. Pass\u00e9 par les centres de formation BeBasket, Reverse et Skweek avant de rejoindre The Playoffs. Biberonn\u00e9 aux dunks de Shawn Kemp et aux duels Pau-Limoges. Fan inconditionnel de Damian Lillard et Laurent Sciarra. Les highlights de Wemby illuminent mes journ\u00e9es. Et le shoot de Diamantidis continue de hanter mes nuits.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/maxime-bodilis-766a04153\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/maximebodilis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide NBA 2025-2026 : Oklahoma City Thunder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide NBA 2025-2026 : Oklahoma City Thunder","og_url":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-10-28T18:09:15+00:00","og_image":[{"width":980,"height":1595,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg","type":"image\/jpeg"}],"author":"Maxime Bodilis","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Maxime Bodilis","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/","url":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/","name":"Guide NBA 2025-2026 : Oklahoma City Thunder","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg","datePublished":"2025-10-13T17:37:56+00:00","dateModified":"2025-10-28T18:09:15+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/d871768c70a3f830131ee72b74bbd11d"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/10\/USATSI_27210206_168402440_lowres.jpg","width":980,"height":1595,"caption":"Shai Gilgeous-Alexander during the Thunder Media Day for the 25-26 NBA season at the Paycom Center Monday, Sept. 29, 2025."},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/sports\/oklahoma-city-thunder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Guide NBA 2025-2026 : Oklahoma City Thunder"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/d871768c70a3f830131ee72b74bbd11d","name":"Maxime Bodilis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5e151acde6515a05571e0035bf803336362ba4f5e565dba89323f14d014ea180?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e151acde6515a05571e0035bf803336362ba4f5e565dba89323f14d014ea180?s=96&d=mm&r=g","caption":"Maxime Bodilis"},"description":"R\u00e9dac\\' Chef \u00ab Basket \u00bb charg\u00e9 de la qualit\u00e9 des contenus et du respect de notre ligne \u00e9ditoriale. Ancien joueur de la SIG Strasbourg reconverti dans le journalisme. Pass\u00e9 par les centres de formation BeBasket, Reverse et Skweek avant de rejoindre The Playoffs. Biberonn\u00e9 aux dunks de Shawn Kemp et aux duels Pau-Limoges. Fan inconditionnel de Damian Lillard et Laurent Sciarra. Les highlights de Wemby illuminent mes journ\u00e9es. Et le shoot de Diamantidis continue de hanter mes nuits.","sameAs":["https:\/\/www.linkedin.com\/in\/maxime-bodilis-766a04153\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/maximebodilis\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1504462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310263"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1504462"}],"version-history":[{"count":8,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1504462\/revisions"}],"predecessor-version":[{"id":1505290,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1504462\/revisions\/1505290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1504469"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1504462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1504462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1504462"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1504462"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1504462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}