{"id":1499685,"date":"2025-08-23T19:19:55","date_gmt":"2025-08-23T17:19:55","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-08-23T19:20:02","modified_gmt":"2025-08-23T17:20:02","slug":"bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/","title":{"rendered":"Bears: Ben Johnson pas satisfait du rendement de son attaque"},"content":{"rendered":"<p>La victoire arrach&eacute;e par les Chicago Bears en <a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/presaison-nfl-2025-week-3-resultats-complets-et-faits-marquants\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pr&eacute;saison face aux Kansas City Chiefs (29-27)<\/a> n&rsquo;a pas suffi &agrave; rassurer leur entra&icirc;neur principal. Ben Johnson s&rsquo;est montr&eacute; particuli&egrave;rement critique envers son attaque, pointant un d&eacute;but de match &laquo; brouillon &raquo; qui, selon lui, refl&egrave;te des probl&egrave;mes persistants depuis le camp d&rsquo;entra&icirc;nement.<\/p><h2 class=\"wp-block-heading\">Deux premi&egrave;res possession infructueuses<\/h2><p>Les deux premi&egrave;res possessions de Chicago ont illustr&eacute; ces difficult&eacute;s: seulement 22 yards gagn&eacute;s et deux punts &agrave; la cl&eacute;. Sur la premi&egrave;re s&eacute;rie, Caleb Williams a mal g&eacute;r&eacute; une transmission avec Olamide Zaccheaus, tandis que le tight end Colston Loveland a &eacute;t&eacute; sanctionn&eacute; pour un faux d&eacute;part. Sur la suivante, le quarterback rookie a conserv&eacute; le ballon trop longtemps et s&rsquo;est fait sacker par Chris Jones apr&egrave;s pr&egrave;s de six secondes dans la poche. <\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&laquo; Offensivement, c&rsquo;&eacute;tait loin du niveau attendu. J&rsquo;avais l&rsquo;impression que nous avions corrig&eacute; &ccedil;a, mais visiblement ce n&rsquo;est pas le cas &raquo;, <a href=\"https:\/\/www.thescore.com\/nfl\/news\/3329757\/bears-johnson-rips-sloppy-offense-not-good-enough\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>a regrett&eacute; Johnson apr&egrave;s la rencontre.<\/a><\/p>\n<\/blockquote><h2 class=\"wp-block-heading\">Du mieux apr&egrave;s la pause<\/h2><p>Si la premi&egrave;re mi-temps a &eacute;t&eacute; d&eacute;cevante, les rempla&ccedil;ants ont su redresser la barre. Men&eacute;s de 17 points apr&egrave;s la pause, les Bears ont trouv&eacute; leur salut gr&acirc;ce &agrave; <a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-la-folle-semaine-de-tyson-bagent\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Tyson Bagent<\/a>. Entr&eacute; en seconde p&eacute;riode, le quarterback a affich&eacute; un bilan de 20 passes r&eacute;ussies sur 28 pour 212 yards et trois touchdowns. Il a notamment scell&eacute; la victoire sur une passe d&eacute;cisive pour le rookie Jahdae Walker dans les derni&egrave;res secondes. Un sc&eacute;nario parfait pour Bagent, fra&icirc;chement prolong&eacute; avec un contrat de deux ans pouvant atteindre 16 millions de dollars avec bonus.<\/p><p>Malgr&eacute; cette remont&eacute;e spectaculaire, Ben Johnson insiste: le probl&egrave;me r&eacute;side dans la capacit&eacute; de son &eacute;quipe &agrave; bien d&eacute;marrer. <\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&laquo; Si le premier quart-temps refl&egrave;te ce que nous sommes, ce n&rsquo;est pas suffisant. Nous devons progresser vite &raquo;, a-t-il martel&eacute;, tout en se montrant confiant quant au travail d&rsquo;analyse vid&eacute;o &agrave; venir pour corriger le tir.<\/p>\n<\/blockquote><p>Les Bears ont d&eacute;sormais deux semaines pour se pr&eacute;parer &agrave; recevoir les Minnesota Vikings le 8 septembre, avant d&rsquo;affronter les Lions, puis deux nouveaux adversaires: les Cowboys et les Raiders. Avec une bye week pr&eacute;vue d&egrave;s la cinqui&egrave;me journ&eacute;e, Johnson esp&egrave;re que son &eacute;quipe aura trouv&eacute; son identit&eacute; d&rsquo;ici l&agrave;.<\/p><p>Cr&eacute;dit photo: &copy; Denny Medley-Imagn Images<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NFL &#8211; Le nouvel entra\u00eeneur des Bears attend plus de son attaque pour le d\u00e9but de saison<\/p>\n","protected":false},"author":180309964,"featured_media":1499686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"NFL - Le nouvel entra\u00eeneur des Bears attend plus de son attaque pour le d\u00e9but de saison","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[118,8410,40,8408],"tags":[6897,887],"sport":[2785],"saison":[7475],"class_list":["post-1499685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nfl","category-football-americain","category-nfl","category-sports","tag-ben-johnson","tag-chicago-bears","sport-nfl","saison-7475"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR\" \/>\n<meta property=\"og:description\" content=\"NFL - Le nouvel entra&icirc;neur des Bears attend plus de son attaque pour le d&eacute;but de saison\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-23T19:20:02+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flavien Jumeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavien Jumeau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/\",\"name\":\"Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg\",\"datePublished\":\"2025-08-23T17:19:55+00:00\",\"dateModified\":\"2025-08-23T17:20:02+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Aug 22, 2025; Kansas City, Missouri, USA; Chicago Bears head coach Ben Johnson on field against the Kansas City Chiefs during the second half of the game at GEHA Field at Arrowhead Stadium. Mandatory Credit: Denny Medley-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bears: Ben Johnson pas satisfait du rendement de son attaque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\",\"name\":\"Flavien Jumeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"caption\":\"Flavien Jumeau\"},\"description\":\"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/","og_locale":"fr_FR","og_type":"article","og_title":"Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR","og_description":"NFL - Le nouvel entra&icirc;neur des Bears attend plus de son attaque pour le d&eacute;but de saison","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-08-23T17:20:02+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg","type":"image\/jpeg"}],"author":"Flavien Jumeau","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Flavien Jumeau","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/","name":"Bears: Ben Johnson pas satisfait du rendement de son attaque - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg","datePublished":"2025-08-23T17:19:55+00:00","dateModified":"2025-08-23T17:20:02+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/08\/USATSI_26908884.jpg","width":1920,"height":1280,"caption":"Aug 22, 2025; Kansas City, Missouri, USA; Chicago Bears head coach Ben Johnson on field against the Kansas City Chiefs during the second half of the game at GEHA Field at Arrowhead Stadium. Mandatory Credit: Denny Medley-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/bears-ben-johnson-pas-satisfait-du-rendement-de-son-attaque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Bears: Ben Johnson pas satisfait du rendement de son attaque"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d","name":"Flavien Jumeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","caption":"Flavien Jumeau"},"description":"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!","url":"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1499685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180309964"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1499685"}],"version-history":[{"count":1,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1499685\/revisions"}],"predecessor-version":[{"id":1499687,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1499685\/revisions\/1499687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1499686"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1499685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1499685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1499685"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1499685"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1499685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}