{"id":1497810,"date":"2025-07-24T08:58:58","date_gmt":"2025-07-24T06:58:58","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-07-24T08:59:10","modified_gmt":"2025-07-24T06:59:10","slug":"lebron-steroides-jeff-teague-podcast","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/","title":{"rendered":"\u00ab LeBron a utilis\u00e9 des st\u00e9ro\u00efdes \u00e0 l\u2019\u00e9poque du Heat \u00bb, affirme un ancien All-Star"},"content":{"rendered":"<p>Ancien titulaire reconnu en NBA durant sa carri&egrave;re, Jeff Teague a affront&eacute; LeBron James &agrave; 26 reprises, ne l&rsquo;emportant que cinq fois. Dans un nouvel &eacute;pisode de son podcast, l&rsquo;ancien joueur est revenu sur la p&eacute;riode o&ugrave; LeBron &eacute;voluait au Miami Heat. Il a alors affirm&eacute; que la star aurait eu recours &agrave; des st&eacute;ro&iuml;des pour am&eacute;liorer ses performances.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&laquo; Il &eacute;tait sous st&eacute;ro&iuml;des, mec. Il a d&ucirc; arr&ecirc;ter de jouer un moment parce qu&rsquo;il &eacute;tait sous st&eacute;ro&iuml;des, vraiment. Enfin, soi-disant &raquo;, <a href=\"https:\/\/x.com\/Fullcourtpass\/status\/1948104837217882320?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1948104837217882320%7Ctwgr%5E5dc5eb74f5afb4dbfc4e22cd42533de6db83deb0%7Ctwcon%5Es1_c10&amp;ref_url=https%3A%2F%2Ftheplayoffs.news%2Ffr%2Fwp-admin%2Fpost-new.php%3Fpost_type%3Dpost\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>a-t-il rectifi&eacute;.<\/a> &laquo; Ils ont commenc&eacute; &agrave; faire des tests pour d&eacute;tecter l&rsquo;hormone hGH, et il a d&ucirc; s&rsquo;arr&ecirc;ter. Il a dit qu&rsquo;il avait mal au dos, est rest&eacute; absent trois semaines, puis est revenu plus mince. &raquo;<\/p>\n<\/blockquote><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Jeff Teague says LeBron James used steroids while being on the Heat<br><br>&ldquo;They started testing for HGH and he had to sit out. He said his back was hurting and he sat out for 3 weeks then came back skinny.&rdquo;<br><br>(Via <a href=\"https:\/\/twitter.com\/club520podcast?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@club520podcast<\/a>, h\/t <a href=\"https:\/\/twitter.com\/JesseGladsaget?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@JesseGladsaget<\/a>)<br> <a href=\"https:\/\/t.co\/8Sd5bgwaXr\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/8Sd5bgwaXr<\/a><\/p>&mdash; Fullcourtpass (@Fullcourtpass) <a href=\"https:\/\/twitter.com\/Fullcourtpass\/status\/1948104837217882320?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 23, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>La &laquo; hGH &raquo; &eacute;voqu&eacute;e par Teague d&eacute;signe l&rsquo;hormone de croissance humaine. Bien qu&rsquo;elle ne soit pas un st&eacute;ro&iuml;de &agrave; proprement parler, elle est parfois utilis&eacute;e pour acc&eacute;l&eacute;rer la r&eacute;cup&eacute;ration, r&eacute;duire la masse grasse et am&eacute;liorer les performances physiques.<\/p><p>Cette d&eacute;claration a imm&eacute;diatement fait le tour des r&eacute;seaux. Quelques heures plus tard, Teague a tenu &agrave; clarifier ses propos via Instagram, expliquant qu&rsquo;il &laquo; plaisantait simplement &agrave; propos de LeBron &raquo;, et qu&rsquo;il &eacute;tait simplement &laquo; tr&egrave;s dominant &raquo;.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Jeff Teague says he was joking about LeBron being on steroids. <a href=\"https:\/\/t.co\/4dqfnIDv8I\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/4dqfnIDv8I<\/a><\/p>&mdash; NBA Retweet (@RTNBA) <a href=\"https:\/\/twitter.com\/RTNBA\/status\/1948134174230995013?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 23, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>Teague est connu pour le ton humoristique de son podcast, o&ugrave; il m&ecirc;le anecdotes de sa carri&egrave;re &agrave; des discussions sur l&rsquo;actualit&eacute; de la NBA. En 12 saisons dans la ligue, il a port&eacute; les couleurs des Atlanta Hawks, Indiana Pacers, Minnesota Timberwolves, Boston Celtics et Milwaukee Bucks. Il a &eacute;t&eacute; s&eacute;lectionn&eacute; une fois au All-Star Game, en 2015, et faisait partie de l&rsquo;&eacute;quipe des Bucks championne NBA en 2021.<\/p><h2 class=\"wp-block-heading\">LeBron James, toujours au sommet et pr&ecirc;t pour un nouveau record<\/h2><p>De son c&ocirc;t&eacute;, LeBron James se pr&eacute;pare pour sa 23e saison <a href=\"https:\/\/theplayoffs.news\/fr\/category\/sports\/basketball-sports\/nba\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA<\/a>, toujours sous les couleurs des Los Angeles Lakers. Lorsqu&rsquo;il foulera les parquets en octobre prochain, il deviendra, seul, le joueur ayant disput&eacute; le plus de saisons en NBA, d&eacute;passant Vince Carter avec qui il partage actuellement le record.<\/p><p>LeBron avait d&eacute;j&agrave; quatre ans d&rsquo;exp&eacute;rience professionnelle lorsque Teague est arriv&eacute; &agrave; l&rsquo;universit&eacute;. Il joue encore aujourd&rsquo;hui, quatre ans apr&egrave;s la retraite du meneur.<\/p><p>Cette long&eacute;vit&eacute; est d&rsquo;autant plus impressionnante que LeBron continue d&rsquo;exceller sur le terrain. Lors de la derni&egrave;re saison, il a tourn&eacute; &agrave; 24,4 points, 7,8 rebonds et 8,2 passes d&eacute;cisives de moyenne en 34,9 minutes par match.<\/p><p>Il est ainsi devenu le troisi&egrave;me joueur de 40 ans ou plus s&eacute;lectionn&eacute; pour un All-Star Game, aux c&ocirc;t&eacute;s de Dirk Nowitzki et Kareem Abdul-Jabbar. Il est &eacute;galement le premier joueur quadrag&eacute;naire &agrave; avoir &eacute;t&eacute; s&eacute;lectionn&eacute; dans une All-NBA Team.<\/p><p><\/p><p><em>Credit Photo: Gary A. Vasquez-Imagn Images<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180309799,"featured_media":1497811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,8414,10],"tags":[6281,116,8797],"sport":[],"saison":[],"class_list":["post-1497810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-basketball-sports","category-nba","tag-jeff-teague","tag-lebron-james","tag-steroides"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LeBron James accus&eacute; d&rsquo;avoir utilis&eacute; des st&eacute;ro&iuml;des au Heat : Jeff Teague s&#039;explique - The Playoffs FR<\/title>\n<meta name=\"description\" content=\"Jeff Teague a accus&eacute; LeBron James d&rsquo;avoir pris des st&eacute;ro&iuml;des durant son passage au Heat avant d&rsquo;affirmer qu&rsquo;il plaisantait.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LeBron James accus&eacute; d&rsquo;avoir utilis&eacute; des st&eacute;ro&iuml;des au Heat : Jeff Teague s&#039;explique - The Playoffs FR\" \/>\n<meta property=\"og:description\" content=\"Jeff Teague a accus&eacute; LeBron James d&rsquo;avoir pris des st&eacute;ro&iuml;des durant son passage au Heat avant d&rsquo;affirmer qu&rsquo;il plaisantait.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T08:59:10+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/\",\"name\":\"LeBron James accus\u00e9 d\u2019avoir utilis\u00e9 des st\u00e9ro\u00efdes au Heat : Jeff Teague s\\\\'explique - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg\",\"datePublished\":\"2025-07-24T06:58:58+00:00\",\"dateModified\":\"2025-07-24T06:59:10+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/bb40426f4e478f9bd8cdbfeb4f2f9784\"},\"description\":\"Jeff Teague a accus\u00e9 LeBron James d\u2019avoir pris des st\u00e9ro\u00efdes durant son passage au Heat avant d\u2019affirmer qu\u2019il plaisantait.\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Jan 3, 2025; Los Angeles, California, USA; Los Angeles Lakers forward LeBron James (23) reacts after scoring three point basket against the Atlanta Hawks during the second half at Crypto.com Arena. Mandatory Credit: Gary A. Vasquez-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab LeBron a utilis\u00e9 des st\u00e9ro\u00efdes \u00e0 l\u2019\u00e9poque du Heat \u00bb, affirme un ancien All-Star\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/bb40426f4e478f9bd8cdbfeb4f2f9784\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7e69b41460ab2c17d61c8c364b6a0ee006f957a70191383ef42be1f4733d6515?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7e69b41460ab2c17d61c8c364b6a0ee006f957a70191383ef42be1f4733d6515?s=96&d=mm&r=g\",\"caption\":\"La r\u00e9daction\"},\"description\":\"On dit qu\\\\'il faut un village pour s\\\\'occuper d\\\\'un enfant. Et bien c\\\\'est exactement ce dont il s\\\\'agit ici pour The Playoffs. La r\u00e9daction, ce sont vos r\u00e9dacteurs pr\u00e9f\u00e9r\u00e9s qui collaborent sur ces articles que vous lisez au quotidien.\u00a0\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/freeagentfr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LeBron James accus&eacute; d&rsquo;avoir utilis&eacute; des st&eacute;ro&iuml;des au Heat : Jeff Teague s&#039;explique - The Playoffs FR","description":"Jeff Teague a accus&eacute; LeBron James d&rsquo;avoir pris des st&eacute;ro&iuml;des durant son passage au Heat avant d&rsquo;affirmer qu&rsquo;il plaisantait.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/","og_locale":"fr_FR","og_type":"article","og_title":"LeBron James accus&eacute; d&rsquo;avoir utilis&eacute; des st&eacute;ro&iuml;des au Heat : Jeff Teague s&#039;explique - The Playoffs FR","og_description":"Jeff Teague a accus&eacute; LeBron James d&rsquo;avoir pris des st&eacute;ro&iuml;des durant son passage au Heat avant d&rsquo;affirmer qu&rsquo;il plaisantait.","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-07-24T06:59:10+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg","type":"image\/jpeg"}],"author":"La r\u00e9daction","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"La r\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/","name":"LeBron James accus\u00e9 d\u2019avoir utilis\u00e9 des st\u00e9ro\u00efdes au Heat : Jeff Teague s\\'explique - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg","datePublished":"2025-07-24T06:58:58+00:00","dateModified":"2025-07-24T06:59:10+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/bb40426f4e478f9bd8cdbfeb4f2f9784"},"description":"Jeff Teague a accus\u00e9 LeBron James d\u2019avoir pris des st\u00e9ro\u00efdes durant son passage au Heat avant d\u2019affirmer qu\u2019il plaisantait.","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Imagn-USATSI-25111198.jpg","width":1920,"height":1280,"caption":"Jan 3, 2025; Los Angeles, California, USA; Los Angeles Lakers forward LeBron James (23) reacts after scoring three point basket against the Atlanta Hawks during the second half at Crypto.com Arena. Mandatory Credit: Gary A. Vasquez-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lebron-steroides-jeff-teague-podcast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab LeBron a utilis\u00e9 des st\u00e9ro\u00efdes \u00e0 l\u2019\u00e9poque du Heat \u00bb, affirme un ancien All-Star"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/bb40426f4e478f9bd8cdbfeb4f2f9784","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7e69b41460ab2c17d61c8c364b6a0ee006f957a70191383ef42be1f4733d6515?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e69b41460ab2c17d61c8c364b6a0ee006f957a70191383ef42be1f4733d6515?s=96&d=mm&r=g","caption":"La r\u00e9daction"},"description":"On dit qu\\'il faut un village pour s\\'occuper d\\'un enfant. Et bien c\\'est exactement ce dont il s\\'agit ici pour The Playoffs. La r\u00e9daction, ce sont vos r\u00e9dacteurs pr\u00e9f\u00e9r\u00e9s qui collaborent sur ces articles que vous lisez au quotidien.\u00a0","url":"https:\/\/theplayoffs.news\/fr\/author\/freeagentfr\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180309799"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1497810"}],"version-history":[{"count":1,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497810\/revisions"}],"predecessor-version":[{"id":1497812,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497810\/revisions\/1497812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1497811"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1497810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1497810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1497810"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1497810"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1497810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}