{"id":1497379,"date":"2025-07-17T07:00:00","date_gmt":"2025-07-17T05:00:00","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-07-17T07:00:43","modified_gmt":"2025-07-17T05:00:43","slug":"wnba-all-star-game-des-regles-speciales-instaurees","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/","title":{"rendered":"WNBA All-Star Game : Des r\u00e8gles sp\u00e9ciales instaur\u00e9es"},"content":{"rendered":"<p><strong>Au WNBA All-Star Game 2025, quatre r&egrave;gles sp&eacute;ciales seront appliqu&eacute;es pendant le match.<\/strong><\/p><p>Les r&egrave;gles sp&eacute;ciales sont mises en place dans le but d&rsquo;accro&icirc;tre le suspense et le rythme de jeu pour le format du <a href=\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-les-titulaires-revelees\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>WNBA All-Star Game de 2025<\/a>.<\/p><h2 class=\"wp-block-heading\">Le tir &agrave; 4 points<\/h2><p>Quatre cercles (deux par moiti&eacute; de terrain) seront ajout&eacute;s &agrave; 28 pieds (&asymp; 8,5 m) du panier, soit environ 1,80 m au-del&agrave; de la ligne &agrave; 3 points. Tout tir tent&eacute; avec un pied dans ce cercle et r&eacute;ussi comptera 4 points. Chaque tir r&eacute;ussi entra&icirc;nera une donation &agrave; des associations soutenues par les joueuses et la WNBA.<\/p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-1200x675.avif\" alt=\"\" class=\"wp-image-1497382\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-1200x675.avif 1200w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-600x338.avif 600w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-768x432.avif 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-1536x864.avif 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-2048x1152.avif 2048w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/Thumbnail-24-1320x743.avif 1320w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Les 4 ronds AT&amp;T vaudront 4 points.<br>Cr&eacute;dit Photo : WNBA <\/figcaption><\/figure><h2 class=\"wp-block-heading\">Horloge des tirs r&eacute;duite &agrave; 20 secondes<\/h2><p>Le temps de possession passe de 24 &agrave; 20 secondes. En cas de rebond offensif, la possession sera r&eacute;initialis&eacute;e &agrave; 14 secondes (comme d&rsquo;habitude).<\/p><h2 class=\"wp-block-heading\">Remplacements en jeu (type hockey)<\/h2><p>Seule l&rsquo;&eacute;quipe en attaque peut faire des remplacements pendant le jeu en direct. Un seul changement est autoris&eacute; par possession. Les joueuses doivent entrer\/sortir dans le backcourt, entre la ligne m&eacute;diane et la marque des 28 pieds. La joueuse qui entre ne peut pas toucher le ballon dans le backcourt. Toute infraction &agrave; ces r&egrave;gles est &eacute;gale &agrave; une perte de balle.<\/p><h2 class=\"wp-block-heading\">Lancers francs automatiques<\/h2><p>Les lancers francs ne seront pas physiquement tir&eacute;s (sauf dans les deux derni&egrave;res minutes du 4e quart-temps ou en prolongation). La joueuse b&eacute;n&eacute;ficiera automatiquement du nombre maximal de points correspondant &agrave; la faute subie. Le score refl&eacute;tera le nombre de lancers &laquo; tent&eacute;s &raquo; et &laquo; r&eacute;ussis &raquo;. <\/p><p>Source texte : <a href=\"https:\/\/www.wnba.com\/news\/special-rules-for-2025-att-wnba-all-star-game\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Communiqu&eacute; de presse de la WNBA<\/a><br>Cr&eacute;dit Photo : HG Biggs\/IndyStar \/ USA TODAY NETWORK via Imagn Images<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310247,"featured_media":1497384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[8414,8408,143],"tags":[8770,8154,7558,8723],"sport":[2902],"saison":[7475],"class_list":["post-1497379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basketball-sports","category-sports","category-wnba","tag-4-points","tag-wnba-2025","tag-wnba-all-star","tag-wnba-all-star-game-2025-2","sport-wnba","saison-7475"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WNBA All-Star Game : Des r&egrave;gles sp&eacute;ciales instaur&eacute;es - The Playoffs FR<\/title>\n<meta name=\"description\" content=\"Au WNBA All-Star Game 2025, quatre r&egrave;gles sp&eacute;ciales seront appliqu&eacute;es pendant le match dont un tir &agrave; 4 points.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WNBA All-Star Game : Des r&egrave;gles sp&eacute;ciales instaur&eacute;es - The Playoffs FR\" \/>\n<meta property=\"og:description\" content=\"Au WNBA All-Star Game 2025, quatre r&egrave;gles sp&eacute;ciales seront appliqu&eacute;es pendant le match dont un tir &agrave; 4 points.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T07:00:43+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eliott Caillot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliott Caillot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/\",\"name\":\"WNBA All-Star Game : Des r\u00e8gles sp\u00e9ciales instaur\u00e9es - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg\",\"datePublished\":\"2025-07-17T05:00:00+00:00\",\"dateModified\":\"2025-07-17T05:00:43+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b3263eb0855dc52bd89a891bffd4ac2d\"},\"description\":\"Au WNBA All-Star Game 2025, quatre r\u00e8gles sp\u00e9ciales seront appliqu\u00e9es pendant le match dont un tir \u00e0 4 points.\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg\",\"width\":1920,\"height\":1520,\"caption\":\"Signs advertising the WNBA All-Star games go up around Gainbridge Fieldhouse, Tuesday, July 8, 2025, in Indianapolis.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WNBA All-Star Game : Des r\u00e8gles sp\u00e9ciales instaur\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b3263eb0855dc52bd89a891bffd4ac2d\",\"name\":\"Eliott Caillot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f0e6c30d165f1a46b16f05bf08040e1dfc41812cc7ff16ed9b1cde5726a8c951?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f0e6c30d165f1a46b16f05bf08040e1dfc41812cc7ff16ed9b1cde5726a8c951?s=96&d=mm&r=g\",\"caption\":\"Eliott Caillot\"},\"description\":\"\u00c9tudiant en journalisme, r\u00e9dacteur sp\u00e9cialis\u00e9 dans le basket f\u00e9minin avec la WNBA et Unrivaled Women\u2019s Basketball. Passionn\u00e9 de basket depuis que j\u2019ai assist\u00e9 \u00e0 un derby new-yorkais au Barclays Center en 2016, j\u2019aime autant \u00eatre sur le parquet qu\u2019en tribune de presse pour faire vibrer les lecteurs. Les salles de conf\u00e9rences de presse sont ma deuxi\u00e8me maison. Si votre num\u00e9ro favori est le 22, et que vous avez d\u00e9j\u00e0 entendu parler d\u2019une jeune Clark, vous serez au bon endroit sur TPO.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/eliott-caillot-etudiant\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/eliott-caillotgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WNBA All-Star Game : Des r&egrave;gles sp&eacute;ciales instaur&eacute;es - The Playoffs FR","description":"Au WNBA All-Star Game 2025, quatre r&egrave;gles sp&eacute;ciales seront appliqu&eacute;es pendant le match dont un tir &agrave; 4 points.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/","og_locale":"fr_FR","og_type":"article","og_title":"WNBA All-Star Game : Des r&egrave;gles sp&eacute;ciales instaur&eacute;es - The Playoffs FR","og_description":"Au WNBA All-Star Game 2025, quatre r&egrave;gles sp&eacute;ciales seront appliqu&eacute;es pendant le match dont un tir &agrave; 4 points.","og_url":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-07-17T05:00:43+00:00","og_image":[{"width":1920,"height":1520,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg","type":"image\/jpeg"}],"author":"Eliott Caillot","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Eliott Caillot","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/","url":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/","name":"WNBA All-Star Game : Des r\u00e8gles sp\u00e9ciales instaur\u00e9es - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg","datePublished":"2025-07-17T05:00:00+00:00","dateModified":"2025-07-17T05:00:43+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b3263eb0855dc52bd89a891bffd4ac2d"},"description":"Au WNBA All-Star Game 2025, quatre r\u00e8gles sp\u00e9ciales seront appliqu\u00e9es pendant le match dont un tir \u00e0 4 points.","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26604687.jpg","width":1920,"height":1520,"caption":"Signs advertising the WNBA All-Star games go up around Gainbridge Fieldhouse, Tuesday, July 8, 2025, in Indianapolis."},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/wnba\/wnba-all-star-game-des-regles-speciales-instaurees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"WNBA All-Star Game : Des r\u00e8gles sp\u00e9ciales instaur\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b3263eb0855dc52bd89a891bffd4ac2d","name":"Eliott Caillot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f0e6c30d165f1a46b16f05bf08040e1dfc41812cc7ff16ed9b1cde5726a8c951?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0e6c30d165f1a46b16f05bf08040e1dfc41812cc7ff16ed9b1cde5726a8c951?s=96&d=mm&r=g","caption":"Eliott Caillot"},"description":"\u00c9tudiant en journalisme, r\u00e9dacteur sp\u00e9cialis\u00e9 dans le basket f\u00e9minin avec la WNBA et Unrivaled Women\u2019s Basketball. Passionn\u00e9 de basket depuis que j\u2019ai assist\u00e9 \u00e0 un derby new-yorkais au Barclays Center en 2016, j\u2019aime autant \u00eatre sur le parquet qu\u2019en tribune de presse pour faire vibrer les lecteurs. Les salles de conf\u00e9rences de presse sont ma deuxi\u00e8me maison. Si votre num\u00e9ro favori est le 22, et que vous avez d\u00e9j\u00e0 entendu parler d\u2019une jeune Clark, vous serez au bon endroit sur TPO.","sameAs":["https:\/\/www.linkedin.com\/in\/eliott-caillot-etudiant"],"url":"https:\/\/theplayoffs.news\/fr\/author\/eliott-caillotgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310247"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1497379"}],"version-history":[{"count":6,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497379\/revisions"}],"predecessor-version":[{"id":1497387,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1497379\/revisions\/1497387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1497384"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1497379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1497379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1497379"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1497379"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1497379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}