{"id":1496405,"date":"2025-07-02T14:06:32","date_gmt":"2025-07-02T12:06:32","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-07-02T16:19:45","modified_gmt":"2025-07-02T14:19:45","slug":"nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/","title":{"rendered":"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles"},"content":{"rendered":"<p>Apr&egrave;s deux nuits de NBA Free Agency, quelques gros noms ont trouv&eacute; leur nouvelle franchise. Myles Turner a rejoint les Bucks, que Brook Lopez a quitt&eacute;s pour les Clippers. Jaren Jackson Jr. a, lui, re-sign&eacute; &agrave; Memphis et a vu Ty Jerome l&rsquo;a suivi. D&rsquo;Angelo Russell est devenu un joueur des Mavs, Nickeil Alexander-Walker et Caris LeVert sont partis chez les Hawks, tandis que Clint Capela s&rsquo;en est all&eacute; pour retourner &agrave; Houston.<\/p><p>Cependant, il reste encore quelques superbes recrues disponibles, qui repr&eacute;sentent de vraies opportunit&eacute;s pour les franchises NBA.<\/p><p>L&rsquo;occasion pour The Playoffs de vous pr&eacute;senter le Top 10 des free agents encore disponibles cet &eacute;t&eacute; !<\/p><h2 class=\"wp-block-heading\">Le Top 10 des agents libres encore disponible pour le jour 3 de la free agency NBA<\/h2><figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Joueur<\/th><th>Poste<\/th><\/tr><\/thead><tbody><tr><td><strong>Quentin Grimes<\/strong><\/td><td>Arri&egrave;re<\/td><\/tr><tr><td><strong>Moritz Wagner<\/strong><\/td><td>Ailier Fort<\/td><\/tr><tr><td><strong>Chris Paul<\/strong><\/td><td>Meneur<\/td><\/tr><tr><td><strong>Spencer Dinwiddie<\/strong><\/td><td>Arri&egrave;re<\/td><\/tr><tr><td><strong>Al Horford<\/strong><\/td><td>Ailier Fort<\/td><\/tr><tr><td><strong>Malik Beasley<\/strong><\/td><td>Arri&egrave;re<\/td><\/tr><tr><td><strong>Russell Westbrook<\/strong><\/td><td>Meneur<\/td><\/tr><tr><td><strong>Jonathan Kuminga<\/strong><\/td><td>Ailier<\/td><\/tr><tr><td><strong>Josh Giddey<\/strong><\/td><td>Meneur<\/td><\/tr><tr><td><strong>Damian Lillard<\/strong><\/td><td>Meneur<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\">10. Quentin Grimes, Sixers, Arri&egrave;re<\/h3><p>Co&eacute;quipier de Guerschon Yabusele &agrave; Philly, Quentin Grimes a fait parler la poudre sur la seconde moiti&eacute; de saison. Transf&eacute;r&eacute; aux Sixers par Dallas dans le trade pour Luka, l&rsquo;ex-Knick a fait des &eacute;tincelles dans la cit&eacute; de l&rsquo;amour fraternel. Au point de tourner &agrave; 21,9 points de moyenne sur 28 matchs et de signer plusieurs coups d&rsquo;&eacute;clat retentissants, &agrave; l&rsquo;image de ses deux sorties &agrave; plus de 40 points d&eacute;but mars (44 et 46).<\/p><p>Capable de scorer des quatre coins du parquet, Grimes devrait signer un gros ch&egrave;que cet &eacute;t&eacute;. &Agrave; seulement 24 ans et apr&egrave;s quatre premi&egrave;res ann&eacute;es compliqu&eacute;es en NBA (quatre &eacute;quipes diff&eacute;rentes), le Texan d&rsquo;origine a tout du late bloomer pr&ecirc;t &agrave; passer un cap dans cette Free Agency.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 14,6 points, 4,3 rebonds et 3,0 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Quentin Grimes &lsquo;24-25 scoring OTD <a href=\"https:\/\/t.co\/kyShYIOJp5\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/kyShYIOJp5<\/a><\/p>&mdash; Brett Usher (@UsherNBA) <a href=\"https:\/\/twitter.com\/UsherNBA\/status\/1935490469120675915?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 19, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">9. Moritz Wagner, Magic, Ailier fort<\/h3><p>Laiss&eacute; libre par le Magic (Team Option d&eacute;clin&eacute;e), Mo Wagner ne devrait pas rester sur le carreau bien longtemps. Malgr&eacute; la rupture des ligaments crois&eacute;s subie en d&eacute;cembre, le fr&egrave;re de Franz Wagner ne devrait pas avoir de mal &agrave; trouver un nouveau point de chute. V&eacute;ritable pile &eacute;lectrique, capable de frustrer l&rsquo;adversaire par sa seule d&eacute;bauche d&rsquo;&eacute;nergie et son agressivit&eacute; des deux c&ocirc;t&eacute;s du terrain, l&rsquo;Allemand constitue un renfort de poids pour toute second unit ambitieuse. Son abn&eacute;gation et son flair font de lui un joueur au profil rare en NBA, capable de pilonner pr&egrave;s du cercle comme de tirer &agrave; 3 points (36,0 %).<\/p><p><strong>Statistiques 2024-2025 : <\/strong>12,9 points, 4,9 rebonds et 1,4 passe d&eacute;cisive.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Join us in wishing Moritz Wagner of the <a href=\"https:\/\/twitter.com\/OrlandoMagic?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@OrlandoMagic<\/a> a HAPPY 28th BIRTHDAY! <a href=\"https:\/\/twitter.com\/hashtag\/NBABDAY?src=hash&amp;ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>#NBABDAY<\/a> <a href=\"https:\/\/t.co\/pakCdIm2pQ\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/pakCdIm2pQ<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1916099948296409411?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>April 26, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">8. Chris Paul, Spurs, Meneur<\/h3><p>&Agrave; 40 ans, le meneur qui a pass&eacute; la saison 2024-2025 aux Spurs a su prouver son importance malgr&eacute; son &acirc;ge avanc&eacute;. L&rsquo;ancien des Clippers a disput&eacute; et d&eacute;but&eacute; chacun des 82 matchs de la saison r&eacute;guli&egrave;re, jouant &agrave; merveille son r&ocirc;le de mentor dans un effectif jeune, talentueux et s&eacute;duisant. Pour sa 21e saison en NBA, Paul devrait sans doute jouer un r&ocirc;le similaire dans sa nouvelle franchise, qui devrait &ecirc;tre en Californie apr&egrave;s que CP3 a &eacute;voqu&eacute; sa volont&eacute; de se rapprocher de sa maison &agrave; Los Angeles.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 8,8 points, 3,6 rebonds, 7,4 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Haynes: Bucks have shown interest in Chris Paul.<br><br>Paul wants to stay closer to home; Clippers, Suns still in play.<\/p>&mdash; Underdog NBA (@UnderdogNBA) <a href=\"https:\/\/twitter.com\/UnderdogNBA\/status\/1940268237092266150?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 2, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">7. Spencer Dinwiddie, Mavericks, Arri&egrave;re<\/h3><p>Tr&egrave;s pr&eacute;cieux dans une &eacute;quipe des Mavs qui a connu une h&eacute;catombe de blessures, Spencer Dinwiddie a affich&eacute; une forme impressionnante, lui permettant de disputer 79 matchs. Tr&egrave;s bon en sortie de banc, le natif de Californie a encore quelques belles ann&eacute;es devant lui et pourrait renforcer une &eacute;quipe en manque de talent sur le banc.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 11 points, 2,6 rebonds, 4,4 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">There is some speculation that the Timberwolves may be looking to add Spencer Dinwiddie here in free agency &#128064;<br><br>Dinwiddie is 6&rsquo;5, so bigger than Conley and Rob and can also facilitate and be a  play maker. Averaged 11PPG to go along with 4AST last season. <a href=\"https:\/\/t.co\/tffvCqgrsX\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/tffvCqgrsX<\/a><\/p>&mdash; SleeperTimberwolves (@SleeperTWolves) <a href=\"https:\/\/twitter.com\/SleeperTWolves\/status\/1940030251976872228?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">6. Al Horford, Celtics, Ailier fort<\/h3><p>Pas le plus flashy, mais certainement le plus exp&eacute;riment&eacute; de cette cuv&eacute;e d&rsquo;agents libres. Et l&rsquo;un des plus impactants. Arriv&eacute; dans la ligue en 2007 au sortir d&rsquo;une superbe carri&egrave;re universitaire &agrave; Florida, aur&eacute;ol&eacute;e de deux titres de champion aux c&ocirc;t&eacute;s de Joakim Noah, Al Horford en a encore sous la semelle. Toujours capable de d&eacute;fendre le plomb et de d&eacute;gainer derri&egrave;re l&rsquo;arc (36,3 %), l&rsquo;ex-Hawk a le profil parfait pour renforcer un contender au titre supr&ecirc;me. Reconnu pour son &eacute;tat d&rsquo;esprit irr&eacute;prochable, le champion NBA 2024 avec les Celtics n&rsquo;aura aucun mal &agrave; s&rsquo;adapter &agrave; n&rsquo;importe quelle &eacute;quipe ambitieuse.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 9,0 points, 6,2 rebonds et 0,9 contre.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">If Al Horford truly is gone&hellip; NEVER FORGETl Al Horford nodding and saying &ldquo;okay&rdquo; to Giannis then dropping 30 on 11\/14 shooting<br><br>Cold man <a href=\"https:\/\/t.co\/9bQa6WYDhS\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/9bQa6WYDhS<\/a><\/p>&mdash; &#120385;&#120423;&#120410;&#120409; &#9752;&#65039; (@BOSFred7) <a href=\"https:\/\/twitter.com\/BOSFred7\/status\/1939901309798228216?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">5. Malik Beasley, Pistons, Arri&egrave;re<\/h3><p>En perte de vitesse apr&egrave;s ses passages au Jazz et aux Lakers, Malik Beasley a repris des couleurs &agrave; Detroit la saison pass&eacute;e. Dans un r&ocirc;le d&rsquo;artificier en chef, l&rsquo;ancien Nugget s&rsquo;est &eacute;clat&eacute; aux c&ocirc;t&eacute;s de Cade Cunningham. En tant que spot-up shooter, Beasley a montr&eacute; une adresse insolente. L&rsquo;arri&egrave;re a ainsi tourn&eacute; &agrave; 43,0 % tout en prenant pr&egrave;s de 10 tirs derri&egrave;re l&rsquo;arc par rencontre !<\/p><p>Une capacit&eacute; unique (ou presque) &agrave; &eacute;tirer les d&eacute;fenses qui devrait attirer quelques convoitises durant l&rsquo;intersaison. Et permettre &agrave; Malik Beasley de d&eacute;crocher LE gros contrat de sa carri&egrave;re &agrave; bient&ocirc;t 29 ans. &Agrave; moins que ses d&eacute;boires extra-sportifs ne viennent dissuader les plus offrants ?<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 16,3 points, 2,6 rebonds et 1,7 passe d&eacute;cisive.<\/p><h3 class=\"wp-block-heading\">4. Russell Westbrook, Nuggets, Meneur<\/h3><p>Russell Westbrook aurait pu figurer plus haut, mais &agrave; 36 ans, l&rsquo;ancien du Thunder semble plus enclin &agrave; int&eacute;grer une rotation d&rsquo;une &eacute;quipe contender ou &agrave; figurer dans le cinq majeur d&rsquo;une &eacute;quipe aux ambitions moindres. Le meneur slasher reste tout de m&ecirc;me une superbe recrue pour l&rsquo;&eacute;quipe qui jettera son d&eacute;volu sur lui. Selon le journaliste <a href=\"https:\/\/marcstein.substack.com\/p\/the-absolute-latest-nba-free-agency\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Marc Stein<\/a>, Westbrook suscite l&rsquo;int&eacute;r&ecirc;t de plusieurs franchises <a href=\"https:\/\/theplayoffs.news\/fr\/category\/sports\/basketball-sports\/nba\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA <\/a>: New York Knicks, Minnesota Timberwolves, New Orleans Pelicans, Sacramento Kings et Denver Nuggets. &Agrave; voir si la situation &eacute;voluera dans les prochains jours.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 13,3 points, 4,9 rebonds et 6,1 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Russell Westbrook is 505 Points away from becoming the highest scoring Point Guard in NBA history &#128016;<br><br>Do you believe Russ will get it done in Year 18? &#128064; <a href=\"https:\/\/t.co\/sBXWRg7YCg\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/sBXWRg7YCg<\/a><\/p>&mdash; Beastbrook (@Beastbr00k0) <a href=\"https:\/\/twitter.com\/Beastbr00k0\/status\/1939869922617598065?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><div class=\"related-slider related-slider--loading\">\n    <div class=\"related-slider__header\">\n        <div class=\"related-slider__header__title\">Vous aimeriez aussi :<\/div>\n        <div class=\"related-slider__header__buttons\">\n            <div class=\"swiper-button-prev\"><\/div>\n            <div class=\"swiper-button-next\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"swiper-container\">\n        <div class=\"swiper-wrapper\">\n                            <div class=\"swiper-slide\">\n                    <a class=\"related-slider-card  trk-cta-img\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-18-12-les-mavs-douchent-les-pistons-maxime-raynaud-superstar\/\" title=\"R&eacute;sultats NBA (18\/12): les Mavs douchent les Pistons, Maxime Raynaud superstar !\" data-cta-trk='{\"ctaType\":\"Image\",\"ctaSubType\":\"main\"}'>\n    <div class=\"related-slider-card__image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-600x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"NBA Cooper Flagg Nikola Jokic Maxime Raynaud Cade Cunningham\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-600x400.jpg 600w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-1200x800.jpg 1200w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-1536x1024.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres-1320x880.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27848729_168402440_lowres.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\">\n                            <\/div>\n    <div class=\"related-slider-card__content\">\n        <div class=\"related-slider-card__content__tags\">\n                            <div class=\"related-slider-card__content__tags__category\">\n                    Actualit&eacute; NBA\n                <\/div>\n                        <div class=\"related-slider-card__content__tags__date\" data-dynamic-date=\"2025-12-19T09:45:57+01:00\">\n                19 d&eacute;cembre 2025\n            <\/div>\n        <\/div>\n        <div class=\"related-slider-card__content__title\">\n            R&eacute;sultats NBA (18\/12): les Mavs douchent les Pistons, Maxime Raynaud superstar !\n        <\/div>\n                    <div class=\"related-slider-card__content__read-more\">\n                Voir plus\n                <i>\n                    <svg width=\"17\" height=\"15\" viewbox=\"0 0 17 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M1 6.5C0.447715 6.5 0 6.94772 0 7.5C0 8.05228 0.447715 8.5 1 8.5V6.5ZM16.7071 8.20711C17.0976 7.81658 17.0976 7.18342 16.7071 6.79289L10.3431 0.428932C9.95262 0.0384078 9.31946 0.0384078 8.92893 0.428932C8.53841 0.819457 8.53841 1.45262 8.92893 1.84315L14.5858 7.5L8.92893 13.1569C8.53841 13.5474 8.53841 14.1805 8.92893 14.5711C9.31946 14.9616 9.95262 14.9616 10.3431 14.5711L16.7071 8.20711ZM1 7.5V8.5H8.5V7.5V6.5H1V7.5ZM8.5 7.5V8.5H16V7.5V6.5H8.5V7.5Z\" fill=\"white\"><\/path>\n<\/svg>\n\n                <\/i>\n            <\/div>\n            <\/div>\n<\/a>\n\n                <\/div>\n                            <div class=\"swiper-slide\">\n                    <a class=\"related-slider-card  trk-cta-img\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-17-12-chicago-enfonce-les-cavs-memphis-en-patron-dans-le-minnesota\/\" title=\"R&eacute;sultats NBA (17\/12): Chicago enfonce les Cavs, Memphis en patron dans le Minnesota !\" data-cta-trk='{\"ctaType\":\"Image\",\"ctaSubType\":\"main\"}'>\n    <div class=\"related-slider-card__image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-600x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"NBA Minnesota Timberwolves Ja Morant Anthony Edwards Rudy Gobert Julius Randle Josh Giddey\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-600x400.jpg 600w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-1200x799.jpg 1200w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-1536x1023.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres-1320x879.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27840419_168402440_lowres.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\">\n                            <\/div>\n    <div class=\"related-slider-card__content\">\n        <div class=\"related-slider-card__content__tags\">\n                            <div class=\"related-slider-card__content__tags__category\">\n                    Actualit&eacute; NBA\n                <\/div>\n                        <div class=\"related-slider-card__content__tags__date\" data-dynamic-date=\"2025-12-18T14:27:38+01:00\">\n                18 d&eacute;cembre 2025\n            <\/div>\n        <\/div>\n        <div class=\"related-slider-card__content__title\">\n            R&eacute;sultats NBA (17\/12): Chicago enfonce les Cavs, Memphis en patron dans le Minnesota !\n        <\/div>\n                    <div class=\"related-slider-card__content__read-more\">\n                Voir plus\n                <i>\n                    <svg width=\"17\" height=\"15\" viewbox=\"0 0 17 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M1 6.5C0.447715 6.5 0 6.94772 0 7.5C0 8.05228 0.447715 8.5 1 8.5V6.5ZM16.7071 8.20711C17.0976 7.81658 17.0976 7.18342 16.7071 6.79289L10.3431 0.428932C9.95262 0.0384078 9.31946 0.0384078 8.92893 0.428932C8.53841 0.819457 8.53841 1.45262 8.92893 1.84315L14.5858 7.5L8.92893 13.1569C8.53841 13.5474 8.53841 14.1805 8.92893 14.5711C9.31946 14.9616 9.95262 14.9616 10.3431 14.5711L16.7071 8.20711ZM1 7.5V8.5H8.5V7.5V6.5H1V7.5ZM8.5 7.5V8.5H16V7.5V6.5H8.5V7.5Z\" fill=\"white\"><\/path>\n<\/svg>\n\n                <\/i>\n            <\/div>\n            <\/div>\n<\/a>\n\n                <\/div>\n                            <div class=\"swiper-slide\">\n                    <a class=\"related-slider-card  trk-cta-img\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-cup-16-12-jalen-brunson-mvp-les-knicks-soffrent-un-premier-trophee-depuis-1973\/\" title=\"R&eacute;sultats NBA Cup (16\/12): Jalen Brunson MVP, les Knicks s&rsquo;offrent un premier troph&eacute;e depuis 1973 !\" data-cta-trk='{\"ctaType\":\"Image\",\"ctaSubType\":\"main\"}'>\n    <div class=\"related-slider-card__image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-600x450.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Jalen Brunson Victor Wembanyama Knicks Spurs NBA Cup\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-600x450.jpg 600w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-1200x900.jpg 1200w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-768x576.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-1536x1152.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres-1320x990.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27835319_168402440_lowres.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\">\n                            <\/div>\n    <div class=\"related-slider-card__content\">\n        <div class=\"related-slider-card__content__tags\">\n                            <div class=\"related-slider-card__content__tags__category\">\n                    Actualit&eacute; NBA\n                <\/div>\n                        <div class=\"related-slider-card__content__tags__date\" data-dynamic-date=\"2025-12-17T09:44:05+01:00\">\n                17 d&eacute;cembre 2025\n            <\/div>\n        <\/div>\n        <div class=\"related-slider-card__content__title\">\n            R&eacute;sultats NBA Cup (16\/12): Jalen Brunson MVP, les Knicks s&rsquo;offrent un premier troph&eacute;e depuis 1973 !\n        <\/div>\n                    <div class=\"related-slider-card__content__read-more\">\n                Voir plus\n                <i>\n                    <svg width=\"17\" height=\"15\" viewbox=\"0 0 17 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M1 6.5C0.447715 6.5 0 6.94772 0 7.5C0 8.05228 0.447715 8.5 1 8.5V6.5ZM16.7071 8.20711C17.0976 7.81658 17.0976 7.18342 16.7071 6.79289L10.3431 0.428932C9.95262 0.0384078 9.31946 0.0384078 8.92893 0.428932C8.53841 0.819457 8.53841 1.45262 8.92893 1.84315L14.5858 7.5L8.92893 13.1569C8.53841 13.5474 8.53841 14.1805 8.92893 14.5711C9.31946 14.9616 9.95262 14.9616 10.3431 14.5711L16.7071 8.20711ZM1 7.5V8.5H8.5V7.5V6.5H1V7.5ZM8.5 7.5V8.5H16V7.5V6.5H8.5V7.5Z\" fill=\"white\"><\/path>\n<\/svg>\n\n                <\/i>\n            <\/div>\n            <\/div>\n<\/a>\n\n                <\/div>\n                            <div class=\"swiper-slide\">\n                    <a class=\"related-slider-card  trk-cta-img\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/pour-deaaron-fox-lherbe-est-plus-verte-a-san-antonio\/\" title=\"Pour De&rsquo;Aaron Fox, &laquo;&nbsp;l&rsquo;herbe est plus verte&nbsp;&raquo; &agrave; San Antonio\" data-cta-trk='{\"ctaType\":\"Image\",\"ctaSubType\":\"main\"}'>\n    <div class=\"related-slider-card__image\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-600x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"NBA De'Aaron Fox Victor Wembanyama Spurs Knicks\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-600x400.jpg 600w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-1200x800.jpg 1200w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-1536x1024.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres-1320x880.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/12\/USATSI_27813133_168402440_lowres.jpg 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\">\n                            <\/div>\n    <div class=\"related-slider-card__content\">\n        <div class=\"related-slider-card__content__tags\">\n                            <div class=\"related-slider-card__content__tags__category\">\n                    Actualit&eacute; NBA\n                <\/div>\n                        <div class=\"related-slider-card__content__tags__date\" data-dynamic-date=\"2025-12-16T12:47:20+01:00\">\n                16 d&eacute;cembre 2025\n            <\/div>\n        <\/div>\n        <div class=\"related-slider-card__content__title\">\n            Pour De&rsquo;Aaron Fox, &laquo;&nbsp;l&rsquo;herbe est plus verte&nbsp;&raquo; &agrave; San Antonio\n        <\/div>\n                    <div class=\"related-slider-card__content__read-more\">\n                Voir plus\n                <i>\n                    <svg width=\"17\" height=\"15\" viewbox=\"0 0 17 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M1 6.5C0.447715 6.5 0 6.94772 0 7.5C0 8.05228 0.447715 8.5 1 8.5V6.5ZM16.7071 8.20711C17.0976 7.81658 17.0976 7.18342 16.7071 6.79289L10.3431 0.428932C9.95262 0.0384078 9.31946 0.0384078 8.92893 0.428932C8.53841 0.819457 8.53841 1.45262 8.92893 1.84315L14.5858 7.5L8.92893 13.1569C8.53841 13.5474 8.53841 14.1805 8.92893 14.5711C9.31946 14.9616 9.95262 14.9616 10.3431 14.5711L16.7071 8.20711ZM1 7.5V8.5H8.5V7.5V6.5H1V7.5ZM8.5 7.5V8.5H16V7.5V6.5H8.5V7.5Z\" fill=\"white\"><\/path>\n<\/svg>\n\n                <\/i>\n            <\/div>\n            <\/div>\n<\/a>\n\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div><h3 class=\"wp-block-heading\">3. Jonathan Kuminga, Warriors, Ailier<\/h3><p>L&rsquo;heure du d&eacute;part a-t-elle enfin sonn&eacute; pour Jonathan Kuminga ? Continuellement au c&oelig;ur des rumeurs de transfert, sans r&ocirc;le d&eacute;fini depuis l&rsquo;arriv&eacute;e de Jimmy Butler chez les Warriors, l&rsquo;ailier congolais devrait quitter le navire &agrave; l&rsquo;intersaison. Athl&eacute;tique au possible, attaquant instinctif et dou&eacute;, le natif de Goma a tout en rayon pour faire le bonheur d&rsquo;une franchise en reconstruction ou &agrave; la recherche d&rsquo;une star en devenir.<\/p><p>Car en d&eacute;pit de lacunes &eacute;videntes, &agrave; commencer par le tir &agrave; 3 points (30 % l&rsquo;an dernier) et la cr&eacute;ation, JK poss&egrave;de un m&eacute;lange de qualit&eacute;s qui pourrait lui ouvrir les portes du All-Star Game sous peu. &Agrave; condition de se voir responsabilis&eacute; en tant que tel.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 15,3 points, 4,6 rebonds et 2,2 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Jonathan Kuminga's stats as a starter last season:<br><br>&mdash; 16.8 PPG<br>&mdash; 4.5 RPG<br>&mdash; 45\/32\/51%<br><br>Went 4-6 in the starting five. <a href=\"https:\/\/t.co\/8iLbiWN7d9\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/8iLbiWN7d9<\/a><\/p>&mdash; StatMuse (@statmuse) <a href=\"https:\/\/twitter.com\/statmuse\/status\/1939741472493900059?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 30, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">2. Josh Giddey, Bulls, Meneur<\/h3><p>Si Alex Caruso a beaucoup fait parler de lui lors des Finals gr&acirc;ce &agrave; son impact en sortie de banc, que dire de la contrepartie de l&rsquo;&eacute;change qui a envoy&eacute; le divin chauve au Thunder, Josh Giddey ? Coinc&eacute; derri&egrave;re Shai Gilgeous-Alexander &agrave; OKC, l&rsquo;Australien a litt&eacute;ralement explos&eacute; aux Bulls cette saison. D&eacute;positaire du jeu de Chicago, charg&eacute; de la cr&eacute;ation offensive, Giddey a &eacute;clabouss&eacute; la saison de son talent et de sa polyvalence, sans oublier d&rsquo;ajouter une arme &agrave; son arsenal : le tir longue distance. Peu r&eacute;put&eacute; dans l&rsquo;exercice jusqu&rsquo;ici, le 6e choix de la Draft 2021 a termin&eacute; l&rsquo;exercice &agrave; 37,8 % de r&eacute;ussite derri&egrave;re l&rsquo;arc. De quoi se pr&eacute;senter comme le second plus gros poisson de cette cuv&eacute;e de free agents.<\/p><p><strong>Statistiques 2024-2025 : <\/strong>14,6 points, 8,1 rebonds et 7,2 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Josh Giddey&rsquo;s Instagram story <a href=\"https:\/\/t.co\/Jqv2YnaRVy\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/Jqv2YnaRVy<\/a><\/p>&mdash; Ross Pins (@chisportsross) <a href=\"https:\/\/twitter.com\/chisportsross\/status\/1940327093369545185?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 2, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h3 class=\"wp-block-heading\">1. Damian Lillard, Bucks, Meneur<\/h3><p>Petit nouveau de la bande des agents libres apr&egrave;s avoir &eacute;t&eacute; coup&eacute; la nuit derni&egrave;re par les Bucks, Damian Lillard devient le plus gros poisson de cette NBA Free Agency 2025. Le meneur devrait &ecirc;tre r&eacute;cup&eacute;r&eacute; par une grosse &eacute;curie et pourrait enfin esp&eacute;rer aller loin en playoffs. Apr&egrave;s deux saisons d&eacute;cevantes aux c&ocirc;t&eacute;s de Giannis Antetokounmpo, l&rsquo;ancien de Portland, d&eacute;sormais &acirc;g&eacute; de 34 ans, entre dans une p&eacute;riode critique de sa carri&egrave;re. S&rsquo;il veut esp&eacute;rer d&eacute;crocher un titre de conf&eacute;rence voire une bague de champion, il devra rejoindre un projet &laquo; win now &raquo;.<\/p><p><strong>Statistiques 2024-2025 :<\/strong> 24,9 points, 4,7 rebonds et 7,1 passes d&eacute;cisives.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Damian Lillard is reportedly preparing to drop a diss track targeting the Bucks &#128563;<br><br>(Via <a href=\"https:\/\/twitter.com\/ChrisBHayne?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@ChrisBHayne<\/a>) <a href=\"https:\/\/t.co\/hK00nnbrSF\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/hK00nnbrSF<\/a><\/p>&mdash; NBACentel (@TheNBACentel) <a href=\"https:\/\/twitter.com\/TheNBACentel\/status\/1940123553539793262?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>Cr&eacute;dit photo : Michael McLoone-Imagn Images<\/p><p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310250,"featured_media":1496422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,8414,10,8408],"tags":[1883,237,508,2492,2510,1288,8449,23,8707,5036,605],"sport":[2783],"saison":[7475],"class_list":["post-1496405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-basketball-sports","category-nba","category-sports","tag-al-horford","tag-chris-paul","tag-damian-lillard","tag-jonathan-kuminga","tag-josh-giddey","tag-malik-beasley","tag-moritz-wagner","tag-nba-tag","tag-nba-free-agency","tag-quentin-grimes","tag-russell-westbrook","sport-nba","saison-7475"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR<\/title>\n<meta name=\"description\" content=\"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr&eacute;sentent de vraies opportunit&eacute;s : Damian Lillard, Josh Giddey...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR\" \/>\n<meta property=\"og:description\" content=\"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr&eacute;sentent de vraies opportunit&eacute;s : Damian Lillard, Josh Giddey...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T16:19:45+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Fabre-Jevanoff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@the_jfj_42\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Fabre-Jevanoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/\",\"name\":\"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg\",\"datePublished\":\"2025-07-02T12:06:32+00:00\",\"dateModified\":\"2025-07-02T14:19:45+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d\"},\"description\":\"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr\u00e9sentent de vraies opportunit\u00e9s : Damian Lillard, Josh Giddey...\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg\",\"width\":1920,\"height\":1271,\"caption\":\"Apr 25, 2025; Milwaukee, Wisconsin, USA; Milwaukee Bucks guard Damian Lillard (0) reacts after making a basket against the Indiana Pacers in the second half during game three of first round for the 2024 NBA Playoffs at Fiserv Forum. Mandatory Credit: Michael McLoone-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d\",\"name\":\"Jean Fabre-Jevanoff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g\",\"caption\":\"Jean Fabre-Jevanoff\"},\"description\":\"Journaliste polyvalent sur le football am\u00e9ricain, j\u2019\u00e9cris aussi des articles sur le basket. Commentateur sur Twitch et sur YouTube. Pass\u00e9 par Eurosport notamment. Un mix d\u2019Eminem et de OBJ, fan inconditionnel de Patrick Mahomes et Lebron James\",\"sameAs\":[\"https:\/\/www.instagram.com\/_juaniitooo_\",\"https:\/\/www.linkedin.com\/in\/jean-fabre-jevanoff-84bb9b1a9\/\",\"https:\/\/x.com\/the_jfj_42\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/jeanfj42gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR","description":"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr&eacute;sentent de vraies opportunit&eacute;s : Damian Lillard, Josh Giddey...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR","og_description":"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr&eacute;sentent de vraies opportunit&eacute;s : Damian Lillard, Josh Giddey...","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-07-02T14:19:45+00:00","og_image":[{"width":1920,"height":1271,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg","type":"image\/jpeg"}],"author":"Jean Fabre-Jevanoff","twitter_card":"summary_large_image","twitter_creator":"@the_jfj_42","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Jean Fabre-Jevanoff","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/","name":"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg","datePublished":"2025-07-02T12:06:32+00:00","dateModified":"2025-07-02T14:19:45+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d"},"description":"NBA Free Agency regorge encore de quelques gros noms disponibles et qui repr\u00e9sentent de vraies opportunit\u00e9s : Damian Lillard, Josh Giddey...","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/07\/USATSI_26017260.jpg","width":1920,"height":1271,"caption":"Apr 25, 2025; Milwaukee, Wisconsin, USA; Milwaukee Bucks guard Damian Lillard (0) reacts after making a basket against the Indiana Pacers in the second half during game three of first round for the 2024 NBA Playoffs at Fiserv Forum. Mandatory Credit: Michael McLoone-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-free-agency-2025-le-top-10-des-joueurs-encore-disponibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"NBA Free Agency 2025 : le Top 10 des joueurs encore disponibles"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d","name":"Jean Fabre-Jevanoff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g","caption":"Jean Fabre-Jevanoff"},"description":"Journaliste polyvalent sur le football am\u00e9ricain, j\u2019\u00e9cris aussi des articles sur le basket. Commentateur sur Twitch et sur YouTube. Pass\u00e9 par Eurosport notamment. Un mix d\u2019Eminem et de OBJ, fan inconditionnel de Patrick Mahomes et Lebron James","sameAs":["https:\/\/www.instagram.com\/_juaniitooo_","https:\/\/www.linkedin.com\/in\/jean-fabre-jevanoff-84bb9b1a9\/","https:\/\/x.com\/the_jfj_42"],"url":"https:\/\/theplayoffs.news\/fr\/author\/jeanfj42gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1496405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310250"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1496405"}],"version-history":[{"count":6,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1496405\/revisions"}],"predecessor-version":[{"id":1496466,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1496405\/revisions\/1496466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1496422"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1496405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1496405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1496405"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1496405"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1496405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}