{"id":1487746,"date":"2025-04-08T11:03:25","date_gmt":"2025-04-08T09:03:25","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-04-08T12:12:17","modified_gmt":"2025-04-08T10:12:17","slug":"stephen-curry-manque-de-vice-selon-draymond-green","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/","title":{"rendered":"Stephen Curry manque de vice selon Draymond Green"},"content":{"rendered":"<p>Stephen Curry est l&rsquo;un des meilleurs joueurs de NBA, notamment en ce qui concerne le scoring, et il est respect&eacute; par beaucoup de ses pairs. Il est difficile d&rsquo;arr&ecirc;ter le meneur des Warriors de mani&egrave;re licite, ce qui pousse de nombreux d&eacute;fenseurs &agrave; commettre des fautes sur lui. <\/p><p>Cependant, selon son co&eacute;quipier Draymond Green, Curry ne tire pas suffisamment parti des fautes dont il est victime.&nbsp;<\/p><h2 class=\"wp-block-heading\">Stephen Curry est-il trop respectueux ?&nbsp;<\/h2><p>Dans le sport de haut niveau, il est courant de chercher &agrave; provoquer des fautes pour obtenir des situations avantageuses. Certains joueurs vont m&ecirc;me jusqu&rsquo;&agrave; en abuser, en simulant des contacts (ce qu&rsquo;on appelle le flopping en NBA),&nbsp;une preuve de vice. <\/p><p>Ce type de comportement ne fait pas partie du jeu de Stephen Curry, et Draymond Green trouve cela regrettable, compte tenu du traitement que lui r&eacute;servent les d&eacute;fenses adverses.&nbsp;<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&ldquo;Il est en permanence agripp&eacute; et retenu off ball, parce que personne ne veut avoir ne serait-ce qu&rsquo;un pas de retard sur lui&hellip; Du coup, tout le monde l&rsquo;attrape et l&rsquo;accroche&rdquo;, <a href=\"https:\/\/x.com\/DraymondShow\/status\/1909395914856321294\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>d&eacute;voile Green<\/a>.&nbsp;<\/p>\n<\/blockquote><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">not a single call in any of these, btw. <a href=\"https:\/\/t.co\/rRjUgisZmw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/rRjUgisZmw<\/a><\/p>&mdash; nana (@namxsj) <a href=\"https:\/\/twitter.com\/namxsj\/status\/1908901607326044424?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>April 6, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>Pour Green, aucun doute : ce sont les tricheurs adeptes du flopping qui sont r&eacute;compens&eacute;s, plut&ocirc;t que les joueurs honn&ecirc;tes comme le meneur des Warriors.&nbsp;<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&ldquo;Il devrait avoir au moins 10 lancers francs par match, il les m&eacute;rite. Mais il ne parle pas assez aux arbitres&hellip; Il est d&rsquo;ailleurs p&eacute;nalis&eacute; &agrave; cause de &ccedil;a. Et il est aussi d&eacute;savantag&eacute; par le fait qu&rsquo;il ne floppe pas ; les arbitres se disent qu&rsquo;il n&rsquo;a pas &eacute;t&eacute; r&eacute;ellement faut&eacute;, ou que ce n&rsquo;est pas si grave puisqu&rsquo;il n&rsquo;exag&egrave;re pas le contact. Dans cette ligue, on r&eacute;compense le flopping. Il existe pourtant une r&egrave;gle contre &ccedil;a, mais elle n&rsquo;est jamais appliqu&eacute;e&hellip; On valorise l&rsquo;acting et les exag&eacute;rations, et Steph ne fait ni l&rsquo;un ni l&rsquo;autre. Ce qui est emb&ecirc;tant, ce n&rsquo;est pas qu&rsquo;il n&rsquo;obtienne pas les coups de sifflet, car il continue de performer malgr&eacute; tout. Ce qui est emb&ecirc;tant, c&rsquo;est qu&rsquo;il ne les obtient pas justement parce qu&rsquo;il respecte l&rsquo;esprit du jeu.&rdquo;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lire aussi :<\/li>\n<\/ul>\n\n\n\n<p><a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephon-castle-pret-a-marcher-dans-les-pas-de-victor-wembanyama\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Stephon Castle pr&ecirc;t &agrave; marcher dans les pas de Victor Wembanyama !<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-players-of-the-week-giannis-antetokounmpo-et-kawhi-leonard-sacres\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA Players of the Week : Giannis Antetokounmpo et Kawhi Leonard sacr&eacute;s !<\/a><\/p>\n<\/blockquote><p>Selon <a href=\"https:\/\/www.espn.com\/nba\/player\/stats\/_\/id\/3975\/stephen-curry\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>ESPN<\/a>, les adversaires du shooteur d&rsquo;&eacute;lite commettent en moyenne&nbsp;quatre&nbsp;fautes par match sur lui. La <a href=\"https:\/\/theplayoffs.news\/fr\/category\/nba\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA <\/a>a &eacute;t&eacute; critiqu&eacute;e ces derni&egrave;res ann&eacute;es pour le nombre trop &eacute;lev&eacute; de fautes siffl&eacute;es. <\/p><p>Mais visiblement, Stephen Curry fait figure d&rsquo;exception, peut- &ecirc;tre&nbsp;parce qu&rsquo;il ne r&eacute;clame pas les fautes qu&rsquo;il subit, contrairement &agrave; certains de ses co&eacute;quipiers.&nbsp;<\/p><p>Il est clair qu&rsquo;avec un plus grand nombre de fautes siffl&eacute;es en sa faveur, le num&eacute;ro 30 serait encore un meilleur scoreur.&nbsp;<\/p><p>Pour rappel, il est actuellement le <a href=\"https:\/\/www.basketball-reference.com\/leaders\/pts_career.html\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>24e meilleur scoreur<\/a> de l&rsquo;histoire de la NBA, avec 25 281 points en carri&egrave;re.&nbsp;<\/p><p>Cr&eacute;dit photo : David Gonzales-Imagn Images<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310250,"featured_media":1487748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[311,1097,23,68],"sport":[2783],"saison":[7475],"class_list":["post-1487746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-draymond-green","tag-golden-state-warriors","tag-nba-tag","tag-stephen-curry","sport-nba","saison-7475"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stephen Curry manque de vice selon Draymond Green<\/title>\n<meta name=\"description\" content=\"Stephen Curry refuse de faire du flopping malgr&eacute; les fautes des d&eacute;fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stephen Curry manque de vice selon Draymond Green\" \/>\n<meta property=\"og:description\" content=\"Stephen Curry refuse de faire du flopping malgr&eacute; les fautes des d&eacute;fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T12:12:17+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Fabre-Jevanoff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@the_jfj_42\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Fabre-Jevanoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/\",\"name\":\"Stephen Curry manque de vice selon Draymond Green\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg\",\"datePublished\":\"2025-04-08T09:03:25+00:00\",\"dateModified\":\"2025-04-08T10:12:17+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d\"},\"description\":\"Stephen Curry refuse de faire du flopping malgr\u00e9 les fautes des d\u00e9fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Mar 8, 2025; San Francisco, California, USA; Golden State Warriors forward Draymond Green (23) and guard Stephen Curry (30) high-five during the first quarter against the Detroit Pistons at Chase Center. Mandatory Credit: David Gonzales-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stephen Curry manque de vice selon Draymond Green\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d\",\"name\":\"Jean Fabre-Jevanoff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g\",\"caption\":\"Jean Fabre-Jevanoff\"},\"description\":\"Journaliste polyvalent sur le football am\u00e9ricain, j\u2019\u00e9cris aussi des articles sur le basket. Commentateur sur Twitch et sur YouTube. Pass\u00e9 par Eurosport notamment. Un mix d\u2019Eminem et de OBJ, fan inconditionnel de Patrick Mahomes et Lebron James\",\"sameAs\":[\"https:\/\/www.instagram.com\/_juaniitooo_\",\"https:\/\/www.linkedin.com\/in\/jean-fabre-jevanoff-84bb9b1a9\/\",\"https:\/\/x.com\/the_jfj_42\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/jeanfj42gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stephen Curry manque de vice selon Draymond Green","description":"Stephen Curry refuse de faire du flopping malgr&eacute; les fautes des d&eacute;fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/","og_locale":"fr_FR","og_type":"article","og_title":"Stephen Curry manque de vice selon Draymond Green","og_description":"Stephen Curry refuse de faire du flopping malgr&eacute; les fautes des d&eacute;fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-04-08T10:12:17+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg","type":"image\/jpeg"}],"author":"Jean Fabre-Jevanoff","twitter_card":"summary_large_image","twitter_creator":"@the_jfj_42","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Jean Fabre-Jevanoff","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/","name":"Stephen Curry manque de vice selon Draymond Green","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg","datePublished":"2025-04-08T09:03:25+00:00","dateModified":"2025-04-08T10:12:17+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d"},"description":"Stephen Curry refuse de faire du flopping malgr\u00e9 les fautes des d\u00e9fenses adverses. Il devrait avoir 10 lancers par match selon Draymond Green.","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/04\/USATSI_25621750.jpg","width":1920,"height":1280,"caption":"Mar 8, 2025; San Francisco, California, USA; Golden State Warriors forward Draymond Green (23) and guard Stephen Curry (30) high-five during the first quarter against the Detroit Pistons at Chase Center. Mandatory Credit: David Gonzales-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/stephen-curry-manque-de-vice-selon-draymond-green\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Stephen Curry manque de vice selon Draymond Green"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/1ea25b88e79fe4fabd657430b0013d3d","name":"Jean Fabre-Jevanoff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18b28dab1159eebc6a17b9787eb8cbbe3242c3d0e8b53b89332f6dc1133aa361?s=96&d=mm&r=g","caption":"Jean Fabre-Jevanoff"},"description":"Journaliste polyvalent sur le football am\u00e9ricain, j\u2019\u00e9cris aussi des articles sur le basket. Commentateur sur Twitch et sur YouTube. Pass\u00e9 par Eurosport notamment. Un mix d\u2019Eminem et de OBJ, fan inconditionnel de Patrick Mahomes et Lebron James","sameAs":["https:\/\/www.instagram.com\/_juaniitooo_","https:\/\/www.linkedin.com\/in\/jean-fabre-jevanoff-84bb9b1a9\/","https:\/\/x.com\/the_jfj_42"],"url":"https:\/\/theplayoffs.news\/fr\/author\/jeanfj42gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1487746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310250"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1487746"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1487746\/revisions"}],"predecessor-version":[{"id":1487764,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1487746\/revisions\/1487764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1487748"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1487746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1487746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1487746"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1487746"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1487746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}