{"id":1482353,"date":"2025-02-25T09:11:55","date_gmt":"2025-02-25T08:11:55","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/uncategorized\/\/"},"modified":"2025-02-25T09:12:02","modified_gmt":"2025-02-25T08:12:02","slug":"resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/","title":{"rendered":"R\u00e9sultats NBA (24\/02) : Nikola Jokic en maestro, les Wolves font tomber le Thunder !\u00a0"},"content":{"rendered":"<p><strong>Huit matchs &eacute;taient au programme en NBA ce lundi, avec en t&ecirc;te d&rsquo;affiche un duel entre les Wolves et le Thunder.<\/strong><\/p><p><strong>De la performance exceptionnelle de Zach Lavine, &agrave; la nouvelle victoire de Detroit en passant par la d&eacute;monstration de Nikola Jokic, <em>The Playoffs<\/em> revient sur une nuit de folie en <a href=\"https:\/\/theplayoffs.news\/fr\/category\/nba\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NBA<\/a> !<\/strong><\/p><h2 class=\"wp-block-heading\"><strong>Minnesota Timberwolves 131 &ndash; 128 Oklahoma City Thunder<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Timberwolves 131, Thunder 128\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/jg66fH-PHwU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Men&eacute; de 25 points en seconde mi-temps, <strong>Minnesota<\/strong> (7e &agrave; l&rsquo;Ouest) a renvers&eacute; le<strong> Thunder<\/strong> (1e) en prolongation pour prendre sa revanche sur le match de la veille. <strong>Jaden McDaniels<\/strong> a brill&eacute; avec 27 points, 10 rebonds, 4 passes d&eacute;cisives et deux lancers francs cruciaux pour &eacute;galiser en fin de rencontre. <strong>Naaz Reid<\/strong> (22 points, 11 rebonds) et <strong>Nickeil Alexander-Walker<\/strong> (21 points, 5 rebonds, 3 passes) ont largement contribu&eacute; au succ&egrave;s des Wolves. <strong>Anthony Edwards <\/strong>(17 points, 13 rebonds, 8 passes) s&rsquo;est distingu&eacute; avec un contre d&eacute;cisif &agrave; 13,2 secondes du terme de la prolongation sur une tentative de <strong>Shai Gilgeous-Alexander.<\/strong> En sortie de banc,<strong> Terrence Shannon Jr.<\/strong> a jou&eacute; un r&ocirc;le cl&eacute; avec 17 points, dont 11 lors de la remont&eacute;e spectaculaire en fin de troisi&egrave;me quart-temps. <strong>Minnesota<\/strong> a &eacute;cras&eacute; <strong>Oklahoma City <\/strong>41-19 sur la derni&egrave;re s&eacute;quence du match.<\/p><p>Face &agrave; cette incroyable remont&eacute;e, <strong>Shai Gilgeous-Alexander<\/strong> a tout tent&eacute; avec 39 points, 10 rebonds et 8 passes d&eacute;cisives, mais son tir &agrave; trois points pour arracher une deuxi&egrave;me prolongation a &eacute;chou&eacute; &agrave; 2,9 secondes du buzzer. <strong>Jalen Williams<\/strong> (27 points, 6 rebonds, 6 passes) a multipli&eacute; les efforts, sans pouvoir &eacute;viter la d&eacute;faite.<\/p><p>Ce succ&egrave;s historique en NBA fait des <strong>Wolves<\/strong> la premi&egrave;re &eacute;quipe &agrave; s&rsquo;imposer &agrave; l&rsquo;ext&eacute;rieur apr&egrave;s avoir accus&eacute; au moins<strong> 20 points <\/strong>de retard dans le quatri&egrave;me quart-temps face &agrave; un adversaire affichant plus de 80 % de victoires.<\/p><p><strong>Rudy Gobert<\/strong> &eacute;tait absent pour blessure.&nbsp;<\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">ANTMAN GAME-WINNING BLOCK &#128680;<br><br>MINNESOTA COMES BACK FROM DOWN 25 TO WIN IT IN OT &#129327; <a href=\"https:\/\/t.co\/BDWjbV6yPl\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/BDWjbV6yPl<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1894232576643985424?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>February 25, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><h2 class=\"wp-block-heading\"><strong>Los Angeles Clippers 97 &ndash; 106 Detroit Pistons&nbsp;<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Pistons 106, Clippers 97\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/G4QPsTwV-d8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Les<strong> Pistons <\/strong>(6e de l&rsquo;Est) ont domin&eacute; les <strong>Clippers <\/strong>(6e de l&rsquo;Ouest) et encha&icirc;nent une septi&egrave;me victoire cons&eacute;cutive, une s&eacute;rie in&eacute;dite depuis d&eacute;cembre 2014. <strong>Cade Cunningham <\/strong>a confirm&eacute; sa grande forme avec 32 points, 9 rebonds et 7 passes d&eacute;cisives, bien &eacute;paul&eacute; par <strong>Jalen Duren<\/strong> (12 points, 19 rebonds) et <strong>Tobias Harris<\/strong> (20 unit&eacute;s).<\/p><p>C&ocirc;t&eacute; Clippers, <strong>James Harden<\/strong> s&rsquo;est illustr&eacute; avec 18 points, 12 rebonds et 5 passes d&eacute;cisives, tandis qu<strong>&rsquo;Ivica Zubac<\/strong> a sign&eacute; un double-double solide avec 13 points, 15 rebonds, 5 passes et 3 contres sans pour autant emp&ecirc;cher la 3e d&eacute;faite de suite de son &eacute;quipe.&nbsp;<\/p><p>Absent de la rencontre, <strong>Ben Simmons<\/strong> n&rsquo;a pas &eacute;t&eacute; align&eacute; en raison du back-to-back disput&eacute; par <strong>Los Angeles.<\/strong><\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Cade Cunningham drops 30+ PTS for the second night in a row to lead the <a href=\"https:\/\/twitter.com\/DetroitPistons?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@DetroitPistons<\/a> to their 7th straight win!<br><br>&#128293; 32 PTS<br>&#128293; 9 REB<br>&#128293; 7 AST<br>&#128293; 3 STL<br><br>This ties Detroit's longest winning streak since the 2014-15 season. <a href=\"https:\/\/t.co\/vfSUHdWA09\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/vfSUHdWA09<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1894221875149984036?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>February 25, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><h2 class=\"wp-block-heading\"><strong>Denver Nuggets 125 &ndash; 116 Indiana Pacers<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Nuggets 125, Pacers 116\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YWP8N1NZq04?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Les <strong>Nuggets <\/strong>(2e de l&rsquo;Ouest) ont pris le dessus sur les <strong>Pacers <\/strong>(5e de l&rsquo;Est) gr&acirc;ce &agrave; un <strong>Nikola Jokic<\/strong> en ma&icirc;tre du jeu (18 points, 9 rebonds, 19 passes d&eacute;cisives). Avec ce total, le <strong>pivot serbe<\/strong> &eacute;tablit un nouveau record personnel de passes en carri&egrave;re. <strong>Aaron Gordon<\/strong> s&rsquo;est illustr&eacute; avec 25 points et 5 rebonds, tandis que <strong>Michael Porter Jr.<\/strong> a ajout&eacute; 19 points et 11 rebonds. Adroits &agrave; 56 %, les <strong>champions NBA 2023<\/strong> ont domin&eacute; dans la raquette avec<strong> 46 <\/strong>rebonds contre<strong> 32<\/strong> pour <strong>Indiana<\/strong> et une &eacute;crasante sup&eacute;riorit&eacute; int&eacute;rieure, marquant<strong> 74 <\/strong>points dans la peinture contre <strong>46<\/strong>.<\/p><p>De l&rsquo;autre c&ocirc;t&eacute; du parquet, la s&eacute;rie de trois victoires cons&eacute;cutives d&rsquo;<strong>Indiana<\/strong> a pris fin, plomb&eacute;e par un manque d&rsquo;adresse &agrave; trois points (14 sur 43). <strong>Tyrese Haliburton<\/strong> a compil&eacute; 19 points et 15 passes d&eacute;cisives, tandis que <strong>Myles Turner<\/strong> a termin&eacute; avec 23 unit&eacute;s.<\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">NIKOLA JOKI&#262; A CAREER-HIGH 19 ASSISTS &#128680;<br><br>Watch every one from the <a href=\"https:\/\/twitter.com\/nuggets?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@nuggets<\/a> win! <a href=\"https:\/\/t.co\/X6CTVY0QT5\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/X6CTVY0QT5<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1894217405645144337?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>February 25, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><h2 class=\"wp-block-heading\"><strong>Miami Heat 86 &ndash; 98 Atlanta Hawks&nbsp;<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Hawks 98, Heat 86\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/CEWC8UdNhDI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Gr&acirc;ce &agrave; cette victoire, <strong>Atlanta<\/strong> grimpe &agrave; la huiti&egrave;me place de la conf&eacute;rence Est, d&eacute;passant <strong>Miami <\/strong>au classement.<strong> Les Hawks<\/strong> ont serr&eacute; le jeu en d&eacute;fense pour s&rsquo;imposer avec autorit&eacute;.<strong> Trae Young<\/strong> s&rsquo;est montr&eacute; discret au scoring avec 11 points &agrave; 4\/14 au tir, mais a compens&eacute; en distribuant 14 passes d&eacute;cisives. <strong>Onyeka Okongwu<\/strong> a sign&eacute; une solide prestation avec 17 points et 8 rebonds. En sortie de banc, <strong>Caris LeVert et Terance Mann <\/strong>ont apport&eacute; 15 points chacun. Plus en difficult&eacute;, le Fran&ccedil;ais <strong>Zaccharie Risacher<\/strong> s&rsquo;est content&eacute; de 2 points et 3 rebonds.<\/p><p><strong>Atlanta<\/strong> a livr&eacute; une prestation d&eacute;fensive de haut niveau, encaissant son plus faible total de points depuis le 14 mars 2021 (82 contre Cleveland).<strong> Dyson Daniels<\/strong> (10 points, 11 rebonds) a &eacute;t&eacute; l&rsquo;un des artisans de cette d&eacute;fense herm&eacute;tique avec 7 interceptions, &eacute;chouant &agrave; une unit&eacute; de son record en NBA.<\/p><p>De l&rsquo;autre c&ocirc;t&eacute;, <strong>Miami<\/strong> a conc&eacute;d&eacute; une sixi&egrave;me d&eacute;faite en sept matchs, malgr&eacute; une belle performance d&rsquo;<strong>Andrew Wiggins<\/strong>, auteur de 23 points.<\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">DYSON DANIELS' DEFENSIVE DOMINANCE CONTINUES &#128563;<br><br>After 7 steals in tonight's win, it's now his 11th game this season with 5+ steals!<br><br>The next closest player has 4 such games. <a href=\"https:\/\/t.co\/q0WCjv4nwU\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/q0WCjv4nwU<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1894223291528970404?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>February 25, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p><strong>Lire aussi :&nbsp;<\/strong><\/p><p><a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/jimmy-butler-la-piece-manquante-des-warriors\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Jimmy Butler, la pi&egrave;ce manquante des Warriors<\/a><\/p><p><a href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/tu-ne-sais-jamais-ce-quil-va-faire-bronny-james-parle-de-ce-quil-a-appris-de-luka-doncic\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>&ldquo;Tu ne sais jamais ce qu&rsquo;il va faire&rdquo; &ndash; Bronny James parle de ce qu&rsquo;il a appris de Luka Doncic &ndash; The Playoffs<\/a><\/p><h2 class=\"wp-block-heading\"><strong>Portland Trail Blazers 114 &ndash; 112 Utah Jazz<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Trail Blazers 114, Jazz 112\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/y7D6Rcx_Z9Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p><strong>Portland <\/strong>s&rsquo;est impos&eacute; sur le fil face au <strong>Jazz<\/strong> au terme d&rsquo;une fin de match haletante. <strong>Keyonte George<\/strong> a inscrit deux tirs prim&eacute;s pour ramener <strong>Utah<\/strong> &agrave; un point &agrave; 3,6 secondes du buzzer, avant que <strong>Jerami Grant <\/strong>ne convertisse un lancer franc sur deux. Derni&egrave;re opportunit&eacute; pour le <strong>Jazz<\/strong>, mais <strong>George<\/strong> a manqu&eacute; le tir &agrave; trois points au buzzer, scellant la victoire des<strong> Blazers<\/strong>.<\/p><p><strong>Anfernee Simons <\/strong>a brill&eacute; avec 28 points et 6 passes d&eacute;cisives, bien &eacute;paul&eacute; par <strong>Jerami Grant<\/strong> (20 unit&eacute;s) et <strong>Deni Avdija<\/strong> (18 points, 14 rebonds, 5 passes). Ce succ&egrave;s met fin &agrave; une s&eacute;rie de trois d&eacute;faites cons&eacute;cutives pour<strong> Portland<\/strong>.<\/p><p>C&ocirc;t&eacute; <strong>Jazz<\/strong>, trois joueurs se sont illustr&eacute;s :<strong> Kyle Filipowski<\/strong> (20 points, 11 rebonds, 5 passes),<strong> Brice Sensabaugh<\/strong> (21 points, 4 rebonds) et <strong>Keyonte George<\/strong> (21 points, 5 rebonds, 5 passes) en sortie de banc.<\/p><h2 class=\"wp-block-heading\"><strong>Brooklyn Nets 99 &ndash; 107 Washington Wizards&nbsp;<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Wizards 107, Nets 99\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/7cnv_qO9lb0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Apr&egrave;s six d&eacute;faites cons&eacute;cutives, les <strong>Wizards <\/strong>(15e de l&rsquo;Est) retrouvent enfin le go&ucirc;t de la victoire en s&rsquo;imposant face aux <strong>Nets<\/strong> (12e). Pour la premi&egrave;re fois de la saison, <strong>Washington <\/strong>est parvenu &agrave; maintenir un adversaire sous la barre des 100 points. Le Fran&ccedil;ais <strong>Bilal Coulibaly<\/strong> s&rsquo;est illustr&eacute; avec 20 points, 5 rebonds et 2 passes d&eacute;cisives, tandis que<strong> Jordan Poole<\/strong> a ajout&eacute; 26 points et 4 rebonds.<\/p><p><strong>Brooklyn<\/strong> conc&egrave;de une deuxi&egrave;me d&eacute;faite en deux matchs face &agrave; Washington cette saison (0-2), un revers surprenant au vu de la dynamique r&eacute;cente avec sept victoires sur les neuf derni&egrave;res rencontres. Malgr&eacute; leurs efforts, <strong>Ziaire Williams <\/strong>(19 points et 5 rebonds) et <strong>Cam Johnson <\/strong>(17 unit&eacute;s) n&rsquo;ont pas r&eacute;ussi &agrave; &eacute;viter la d&eacute;faite.<\/p><p><strong>Killian Hayes<\/strong> a conclu la rencontre avec 7 points, 3 rebonds et 8 passes d&eacute;cisives.<\/p><h2 class=\"wp-block-heading\"><strong>Charlotte Hornets 88 &ndash; 130 Sacramento Kings<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Kings 130, Hornets 88\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/pwnUmi216Gc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Les <strong>Kings<\/strong> (10e de l&rsquo;Ouest) ont surclass&eacute; les <strong>Hornets<\/strong> (14e de l&rsquo;Est), port&eacute;s par un <strong>Zach LaVine<\/strong> en feu. L&rsquo;arri&egrave;re a livr&eacute; une performance exceptionnelle avec 42 points &agrave; 16\/19 au tir. <strong>DeMar DeRozan<\/strong> a apport&eacute; sa contribution avec 18 points, 7 rebonds et 3 passes d&eacute;cisives. Un succ&egrave;s pr&eacute;cieux pour<strong> Sacramento<\/strong> dans la course au play-in en NBA.<\/p><p>En face, <strong>Charlotte<\/strong> s&rsquo;est appuy&eacute; sur <strong>Miles Bridges<\/strong>, auteur de 23 points et 6 rebonds. <strong>Moussa Diabat&eacute;<\/strong> a montr&eacute; de belles choses avec 12 points et 7 rebonds, tandis que <strong>Tidjane Salaun<\/strong> s&rsquo;est montr&eacute; plus discret avec 4 points et 3 rebonds.<\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Zach LaVine goes OFF for 42 PTS (most as a King) on 84.2 FG% in the <a href=\"https:\/\/twitter.com\/SacramentoKings?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>@SacramentoKings<\/a> win! &#128548; <a href=\"https:\/\/t.co\/k4jvIUcluS\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/k4jvIUcluS<\/a><\/p>&mdash; NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1894260929979724247?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>February 25, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><h2 class=\"wp-block-heading\"><strong>Chicago Bulls 142 &ndash; 110 Philadelphia Sixers<\/strong><\/h2><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Game Recap: Bulls 142, 76ers 110\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/F0Mr1CGqK-U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>Les <strong>Bulls<\/strong> (10e &agrave; l&rsquo;Est) ont surclass&eacute; les<strong> Sixers <\/strong>(12e) en &eacute;tablissant leur record de points de la saison NBA sur une mi-temps avec 75 unit&eacute;s. <strong>Josh Giddey<\/strong> a brill&eacute; avec 25 points, 16 rebonds et 6 passes, bien &eacute;paul&eacute; par <strong>Kevin Huerter<\/strong> (23 points) et <strong>Zach Collins<\/strong> (19 unit&eacute;s).<\/p><p>En face, <strong>Kelly Oubre Jr.<\/strong> (19 points, 8 rebonds) et <strong>Paul George<\/strong> (19 points) ont tent&eacute; de r&eacute;sister, sans succ&egrave;s face &agrave; la d&eacute;monstration de <strong>Chicago<\/strong>. <strong>Philadelphie<\/strong> encha&icirc;ne une huiti&egrave;me d&eacute;faite cons&eacute;cutive et continue de s&rsquo;enfoncer &agrave; l&rsquo;Est.<\/p><p><strong>Cr&eacute;dit photo :&nbsp;<\/strong>Trevor Ruszkowski-Imagn Images<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d\u00e9monstration de Nikola Jokic !<\/p>\n","protected":false},"author":180310268,"featured_media":1482355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d\u00e9monstration de Nikola Jokic !","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[1411,856,23,561,1809],"sport":[2783],"saison":[],"class_list":["post-1482353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-cade-cunningham","tag-minnesota-timberwolves","tag-nba-tag","tag-nikola-jokic","tag-zach-lavine","sport-nba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R&eacute;sultats NBA (24\/02) : les Wolves font tomber le Thunder !&nbsp;<\/title>\n<meta name=\"description\" content=\"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d&eacute;monstration de Nikola Jokic !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R&eacute;sultats NBA (24\/02) : les Wolves font tomber le Thunder !&nbsp;\" \/>\n<meta property=\"og:description\" content=\"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d&eacute;monstration de Nikola Jokic !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:12:02+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elian Goethals\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/elidwight\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elian Goethals\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/\",\"name\":\"R\u00e9sultats NBA (24\/02) : les Wolves font tomber le Thunder !\u00a0\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg\",\"datePublished\":\"2025-02-25T08:11:55+00:00\",\"dateModified\":\"2025-02-25T08:12:02+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/2bc470c6a49f4f6229a67af19c87a732\"},\"description\":\"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d\u00e9monstration de Nikola Jokic !\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg\",\"width\":1920,\"height\":1278,\"caption\":\"Feb 24, 2025; Indianapolis, Indiana, USA; Denver Nuggets center Nikola Jokic (15) holds the ball while Indiana Pacers center Myles Turner (33) defends in the first half at Gainbridge Fieldhouse. Mandatory Credit: Trevor Ruszkowski-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sultats NBA (24\/02) : Nikola Jokic en maestro, les Wolves font tomber le Thunder !\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/2bc470c6a49f4f6229a67af19c87a732\",\"name\":\"Elian Goethals\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/293e2e649a094756005b611f6122ac1a95e95d453dbfe74b9d434b39855927f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/293e2e649a094756005b611f6122ac1a95e95d453dbfe74b9d434b39855927f6?s=96&d=mm&r=g\",\"caption\":\"Elian Goethals\"},\"description\":\"Je suis sp\u00e9cialis\u00e9 dans la r\u00e9daction d\\\\'articles NBA et je suis un grand fan de basket am\u00e9ricain depuis toujours. Cela fait 20 ans que je joue au basket, et mon exp\u00e9rience sur les terrains me permet d\\\\'avoir une analyse approfondie des matchs. J\u2019ai d\u2019abord fait partie d\u2019autres m\u00e9dias sportifs en tant que b\u00e9n\u00e9vole avant de rejoindre ThePlayoffs en janvier. Je termine \u00e9galement un master en \u00e9tudes internationales. Ce que je pr\u00e9f\u00e8re dans mon travail, c\u2019est de transformer ma passion en m\u00e9tier et de partager avec vous l\u2019information NBA. J\u2019essaie de produire un contenu de qualit\u00e9 en esp\u00e9rant qu\u2019il vous plaise !\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/elian-goethals-729b71200\/\",\"https:\/\/x.com\/x.com\/elidwight\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/elian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R&eacute;sultats NBA (24\/02) : les Wolves font tomber le Thunder !&nbsp;","description":"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d&eacute;monstration de Nikola Jokic !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/","og_locale":"fr_FR","og_type":"article","og_title":"R&eacute;sultats NBA (24\/02) : les Wolves font tomber le Thunder !&nbsp;","og_description":"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d&eacute;monstration de Nikola Jokic !","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2025-02-25T08:12:02+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg","type":"image\/jpeg"}],"author":"Elian Goethals","twitter_card":"summary_large_image","twitter_creator":"@x.com\/elidwight","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Elian Goethals","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/","name":"R\u00e9sultats NBA (24\/02) : les Wolves font tomber le Thunder !\u00a0","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg","datePublished":"2025-02-25T08:11:55+00:00","dateModified":"2025-02-25T08:12:02+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/2bc470c6a49f4f6229a67af19c87a732"},"description":"NBA : performance exceptionnelle de Zach Lavine, nouvelle victoire de Detroit et d\u00e9monstration de Nikola Jokic !","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2025\/02\/USATSI_25502665.jpg","width":1920,"height":1278,"caption":"Feb 24, 2025; Indianapolis, Indiana, USA; Denver Nuggets center Nikola Jokic (15) holds the ball while Indiana Pacers center Myles Turner (33) defends in the first half at Gainbridge Fieldhouse. Mandatory Credit: Trevor Ruszkowski-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/resultats-nba-24-02-nikola-jokic-en-maestro-les-wolves-font-tomber-le-thunder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sultats NBA (24\/02) : Nikola Jokic en maestro, les Wolves font tomber le Thunder !\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/2bc470c6a49f4f6229a67af19c87a732","name":"Elian Goethals","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/293e2e649a094756005b611f6122ac1a95e95d453dbfe74b9d434b39855927f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/293e2e649a094756005b611f6122ac1a95e95d453dbfe74b9d434b39855927f6?s=96&d=mm&r=g","caption":"Elian Goethals"},"description":"Je suis sp\u00e9cialis\u00e9 dans la r\u00e9daction d\\'articles NBA et je suis un grand fan de basket am\u00e9ricain depuis toujours. Cela fait 20 ans que je joue au basket, et mon exp\u00e9rience sur les terrains me permet d\\'avoir une analyse approfondie des matchs. J\u2019ai d\u2019abord fait partie d\u2019autres m\u00e9dias sportifs en tant que b\u00e9n\u00e9vole avant de rejoindre ThePlayoffs en janvier. Je termine \u00e9galement un master en \u00e9tudes internationales. Ce que je pr\u00e9f\u00e8re dans mon travail, c\u2019est de transformer ma passion en m\u00e9tier et de partager avec vous l\u2019information NBA. J\u2019essaie de produire un contenu de qualit\u00e9 en esp\u00e9rant qu\u2019il vous plaise !","sameAs":["https:\/\/www.linkedin.com\/in\/elian-goethals-729b71200\/","https:\/\/x.com\/x.com\/elidwight"],"url":"https:\/\/theplayoffs.news\/fr\/author\/elian\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1482353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310268"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1482353"}],"version-history":[{"count":1,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1482353\/revisions"}],"predecessor-version":[{"id":1482356,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1482353\/revisions\/1482356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1482355"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1482353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1482353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1482353"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1482353"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1482353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}