{"id":1469400,"date":"2024-12-03T07:08:50","date_gmt":"2024-12-03T06:08:50","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1469400"},"modified":"2024-12-03T07:08:50","modified_gmt":"2024-12-03T06:08:50","slug":"podcast-nba-le-conseil-de-classe-episode-2","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/","title":{"rendered":"Podcast NBA &#8211; Le conseil de classe &#8211; \u00e9pisode 2"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">Dans cet &eacute;pisode de 1h15, on passe au tableau pour &eacute;valuer les performances des &eacute;quipes et joueurs NBA en ce d&eacute;but de saison. Qui sont les bons et les mauvais &eacute;l&egrave;ves ? Voici le programme :<\/p><p>&nbsp;<\/p><p>&#128204; <strong>Boston<\/strong> : le surdou&eacute; de la classe<\/p><p>&#128204; <strong>Cleveland<\/strong> : le bon &eacute;l&egrave;ve qui fait tout juste ce qu&rsquo;il faut<\/p><p>&#128204; <strong>Minnesota<\/strong> : en mode &ldquo;peut mieux faire&rdquo;<\/p><p>&#128204; <strong>New Orleans<\/strong> : le cancre &agrave; redresser d&rsquo;urgence<\/p><p>&nbsp;<\/p><p>&#128293; En bonus, ne manquez pas <strong>l&rsquo;&eacute;lection de nos d&eacute;l&eacute;gu&eacute;s du mois<\/strong> avec deux invit&eacute;s de marque : <strong>Hanna et Benjamin Moub&egrave;che<\/strong>, accompagn&eacute;s de <strong>Yaya<\/strong>.<\/p><p>&nbsp;<\/p><p>&#128073; Disponible sur toutes vos plateformes de podcast pr&eacute;f&eacute;r&eacute;es. Abonnez-vous et ne manquez rien de l&rsquo;actu NBA !<\/p><p><iframe id=\"ausha-6GjU\" style=\"border: none; width: 100%; height: 220px;\" src=\"https:\/\/player.ausha.co\/?showId=bWKXAUmVYRJn&amp;color=%23751CBF&amp;podcastId=oZejRUN89Kp9&amp;v=3&amp;playerId=ausha-6GjU\" name=\"Ausha Podcast Player\" height=\"220\" frameborder=\"0\"><\/iframe><script src=\"https:\/\/player.ausha.co\/ausha-player.js\"><\/script><\/p><h3><strong>O&ugrave; &eacute;couter le podcast NBA de&nbsp;<a href=\"https:\/\/theplayoffs.news\/fr\/nba-basketball\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>TFA<\/a>&nbsp;?&nbsp;<\/strong><\/h3><ul>\n<li><a href=\"https:\/\/open.spotify.com\/show\/12rbf0HOG3Kxc4QjnDeBpc\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Spotify<\/a><\/li>\n<li><a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/stepback-le-podcast-nba-de-the-free-agent\/id1627529982\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Apple<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLnM0nGdBYylir7lq4XZKfWTRyQGFF54Kh\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Youtube<\/a><\/li>\n<li><a href=\"https:\/\/www.deezer.com\/show\/3767197\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Deezer<\/a><\/li>\n<li><a href=\"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9mZWVkLmF1c2hhLmNvL2JXS1hBVW1WWVJKbg?sa=X&amp;ved=0CAMQ4aUDahcKEwiYnc26pef4AhUAAAAAHQAAAAAQNQ\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Google<\/a><\/li>\n<li><a href=\"https:\/\/music.amazon.com\/podcasts\/f5019385-00b6-4393-b3bb-46eb5e9b1904\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Amazon<\/a><\/li>\n<li><a href=\"https:\/\/podcastaddict.com\/podcast\/3985747\" target=\"_blank\" rel=\"noopener\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Podcast Addict<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":339351,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[6692,6598,4504],"sport":[],"saison":[],"class_list":["post-1469400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-benjamin-moubeche","tag-conseil-de-classe","tag-podcast-nba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Podcast NBA - Le conseil de classe - &eacute;pisode 2 - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast NBA - Le conseil de classe - &eacute;pisode 2 - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T07:08:50+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charles Taudin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Taudin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/\",\"name\":\"Podcast NBA - Le conseil de classe - \u00e9pisode 2 - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png\",\"datePublished\":\"2024-12-03T06:08:50+00:00\",\"dateModified\":\"2024-12-03T06:08:50+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png\",\"width\":1080,\"height\":1080,\"caption\":\"podcast NBA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast NBA &#8211; Le conseil de classe &#8211; \u00e9pisode 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\",\"name\":\"Charles Taudin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"caption\":\"Charles Taudin\"},\"description\":\"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.\",\"sameAs\":[\"https:\/\/www.instagram.com\/ctaudin_\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podcast NBA - Le conseil de classe - &eacute;pisode 2 - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Podcast NBA - Le conseil de classe - &eacute;pisode 2 - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","og_image":[{"width":1080,"height":1080,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png","type":"image\/png"}],"author":"Charles Taudin","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Charles Taudin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/","name":"Podcast NBA - Le conseil de classe - \u00e9pisode 2 - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png","datePublished":"2024-12-03T06:08:50+00:00","dateModified":"2024-12-03T06:08:50+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/05\/PODCAST-2.png","width":1080,"height":1080,"caption":"podcast NBA"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/podcast-nba-le-conseil-de-classe-episode-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Podcast NBA &#8211; Le conseil de classe &#8211; \u00e9pisode 2"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133","name":"Charles Taudin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","caption":"Charles Taudin"},"description":"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.","sameAs":["https:\/\/www.instagram.com\/ctaudin_\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1469400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1469400"}],"version-history":[{"count":3,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1469400\/revisions"}],"predecessor-version":[{"id":1469438,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1469400\/revisions\/1469438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/339351"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1469400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1469400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1469400"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1469400"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1469400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}