{"id":1458256,"date":"2024-09-19T09:58:51","date_gmt":"2024-09-19T07:58:51","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1458256"},"modified":"2024-09-19T09:58:51","modified_gmt":"2024-09-19T07:58:51","slug":"jordan-love-retour-a-lentrainement","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/","title":{"rendered":"Jordan Love: retour \u00e0 l&rsquo;entra\u00eenement et &lsquo;espoirs&rsquo; de jouer lors de la week 3!"},"content":{"rendered":"<h2>NFL &ndash; Le quarterback des Green Bay Packers, Jordan Love, a retrouv&eacute; le chemin de l&rsquo;entra&icirc;nement ce mercredi et esp&egrave;re pouvoir &ecirc;tre sur le terrain d&egrave;s ce week-end.<\/h2><p>Les inqui&eacute;tudes entourant l&rsquo;&eacute;tat de sant&eacute; de Jordan Love qui sont n&eacute;es apr&egrave;s<a href=\"https:\/\/theplayoffs.news\/fr\/nfl\/jordan-love-souffre-dune-entorse-du-genou\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'> la blessure de ce dernier<\/a> face aux Philadelphie Eagles en ouverture de la saison NFL 2024 seront finalement lev&eacute;es assez rapidement. Alors que sa franchise des Green Bay Packers avaient d&eacute;cid&eacute; de ne pas placer leur quarterback sur la liste des bless&eacute;s apr&egrave;s sa blessure au genou, Love a pu retrouver ses partenaires d&rsquo;entra&icirc;nement depuis ce mercredi pour une session dans lequel il fut limit&eacute; dans son nombre d&rsquo;exercices mais pour laquelle il fut tout de m&ecirc;me pr&eacute;sent.<\/p><p>Une reprise de l&rsquo;entra&icirc;nement qui sonne comme un vrai signe encourageant pour le joueur et pour tous ses co&eacute;quipiers m&ecirc;me si le quarterback rempla&ccedil;ant, Malik Willis, a r&eacute;alis&eacute; une performance plut&ocirc;t solide pour aller chercher la victoire dimanche dernier face aux Colts d&rsquo;Indianapolis. Il n&rsquo;en reste pas moins que le retour d&rsquo;un quarterback titulaire &agrave; l&rsquo;entra&icirc;nement poss&egrave;de toujours l&rsquo;avantage de galvaniser les troupes. Mais Jordan Love sera-t-il suffisamment remis de sa blessure au genou pour reprendre sa place sur le terrain en comp&eacute;tition d&egrave;s cette week 3?<\/p><blockquote><p>&laquo;&nbsp;Je prends vraiment les entra&icirc;nements jour apr&egrave;s jour&nbsp;&raquo; a pr&eacute;cis&eacute; Jordan Love aux <a href=\"https:\/\/x.com\/ByRyanWood\/status\/1836489252760117465\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>journalistes pr&eacute;sents &agrave; l&rsquo;entra&icirc;nement des Packers<\/a>. &laquo;&nbsp;Je veux voir comment je me sens au fil des entra&icirc;nements et nous prendrons une d&eacute;cision ensuite. J&rsquo;ai bon espoir de pouvoir jouer dimanche mais il faut vraiment prendre cela au jour le jour.&nbsp;&raquo;<\/p><\/blockquote><p>Nul doute que Matt LaFleur et le staff des Green Bay Packers ne prendront sans doute pas beaucoup de risques concernant la blessure de leur quarterback et son retour au jeu. Si Jordan Love n&rsquo;est pas disponible pour dimanche, Malik Willis prendra sa place pour un match que ce dernier doit particuli&egrave;rement attendre puisqu&rsquo;il a jou&eacute; pour les Tennessee Titans que les Packers rencontreront dimanche.<\/p><p><em>Cr&eacute;dit photo: Tom Silverstein \/ Milwaukee Journal Sentinel \/ USA TODAY NETWORK<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180309964,"featured_media":1458257,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[118,40],"tags":[908,270],"sport":[2785],"saison":[6111],"class_list":["post-1458256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nfl","category-nfl","tag-green-bay-packers","tag-jordan-love","sport-nfl","saison-6111"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jordan Love: retour &agrave; l&#039;entra&icirc;nement et &#039;espoirs&#039; de jouer lors de la week 3! - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jordan Love: retour &agrave; l&#039;entra&icirc;nement et &#039;espoirs&#039; de jouer lors de la week 3! - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T09:58:51+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flavien Jumeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavien Jumeau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/\",\"name\":\"Jordan Love: retour \u00e0 l\\\\'entra\u00eenement et \\\\'espoirs\\\\' de jouer lors de la week 3! - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg\",\"datePublished\":\"2024-09-19T07:58:51+00:00\",\"dateModified\":\"2024-09-19T07:58:51+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg\",\"width\":1920,\"height\":1440,\"caption\":\"Green Bay Packers quarterback Jordan Love warms up before the Week 1 game against the Philadelphia Eagles on Friday, Sept. 6, 2024, in S\u00e3o Paulo, Brazil.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jordan Love: retour \u00e0 l&rsquo;entra\u00eenement et &lsquo;espoirs&rsquo; de jouer lors de la week 3!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\",\"name\":\"Flavien Jumeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"caption\":\"Flavien Jumeau\"},\"description\":\"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jordan Love: retour &agrave; l&#039;entra&icirc;nement et &#039;espoirs&#039; de jouer lors de la week 3! - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/","og_locale":"fr_FR","og_type":"article","og_title":"Jordan Love: retour &agrave; l&#039;entra&icirc;nement et &#039;espoirs&#039; de jouer lors de la week 3! - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","og_image":[{"width":1920,"height":1440,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg","type":"image\/jpeg"}],"author":"Flavien Jumeau","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Flavien Jumeau","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/","name":"Jordan Love: retour \u00e0 l\\'entra\u00eenement et \\'espoirs\\' de jouer lors de la week 3! - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg","datePublished":"2024-09-19T07:58:51+00:00","dateModified":"2024-09-19T07:58:51+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24167338.jpg","width":1920,"height":1440,"caption":"Green Bay Packers quarterback Jordan Love warms up before the Week 1 game against the Philadelphia Eagles on Friday, Sept. 6, 2024, in S\u00e3o Paulo, Brazil."},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/jordan-love-retour-a-lentrainement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Jordan Love: retour \u00e0 l&rsquo;entra\u00eenement et &lsquo;espoirs&rsquo; de jouer lors de la week 3!"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d","name":"Flavien Jumeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","caption":"Flavien Jumeau"},"description":"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!","url":"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180309964"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1458256"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458256\/revisions"}],"predecessor-version":[{"id":1458259,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458256\/revisions\/1458259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1458257"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1458256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1458256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1458256"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1458256"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1458256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}