{"id":1458251,"date":"2024-09-19T09:38:54","date_gmt":"2024-09-19T07:38:54","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1458251"},"modified":"2024-09-19T09:38:54","modified_gmt":"2024-09-19T07:38:54","slug":"tua-tagovailoa-commotions-assurance","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/","title":{"rendered":"Tua Tagovailoa: les commotions c\u00e9r\u00e9brales exclues de l&rsquo;assurance?"},"content":{"rendered":"<h2>NFL &ndash; La situation de la sant&eacute; de Tua Tagovailoa semble encore &agrave; cette heure particuli&egrave;rement floue. Tout comme celle entourant les garanties financi&egrave;res pour le joueur.<\/h2><p>Alors que le quarterback des Miami Dolphins, Tua Tagovailoa, tente de se remettre doucement de sa derni&egrave;re <a href=\"https:\/\/theplayoffs.news\/fr\/nfl\/tua-tagovailoa-commotion-cerebrale-week-2\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>commotion c&eacute;r&eacute;brale subie jeudi dernier<\/a> face aux Bills de Buffalo, les Dolphins de leur c&ocirc;t&eacute; se penchent de plus en plus sur les petites lignes qui figurent au contrat du quarterback de la franchise floridienne. Car ces assurances pourraient ne pas prendre en charge le cas des commotions c&eacute;r&eacute;brales selon une enqu&ecirc;te men&eacute;e par <a href=\"https:\/\/www.espn.com\/nfl\/story\/_\/id\/41274295\/nfl-insurance-policies-star-players-aaron-rodgers-tua-tagovailoa-jared-goff-joe-burrow-christian-mccaffrey\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Kalyn Kahler d&rsquo;ESPN<\/a>.<\/p><p>Qu&rsquo;on se le dise, cela n&rsquo;aurait rien de particuli&egrave;rement &eacute;tonnant de voir que les commotions c&eacute;r&eacute;brales soient exclues des garanties financi&egrave;res entourant les blessures de Tua Tagovailoa &agrave; l&rsquo;avenir. Les assurances connaissent parfaitement la situation du joueur et les deux commotions c&eacute;r&eacute;brales subies lors de la saison 2022 et ils auront vite fait de rayer la disposition couvrant les futures commotions du joueur. Pour sch&eacute;matiser, c&rsquo;est un peu comme si une assurance habitation refusait de vous assurer pour un risque d&rsquo;inondation alors que vous &ecirc;tes sur un terrain inondable.<\/p><p>Si l&rsquo;on regarde cette affaire par le c&ocirc;t&eacute; le plus humain de la question, il est clair que la sant&eacute; du joueur pr&eacute;vaudra toujours. La vie d&rsquo;un homme n&rsquo;a pas de prix et il n&rsquo;est pas usurp&eacute; de dire que Tua Tagovailoa peut risquer sa vie en retournant sur un terrain de NFL. Mais il ne faut pas &eacute;carter trop vite la logique financi&egrave;re qui demeure derri&egrave;re cette affaire et les pertes abyssales qu&rsquo;une retraite du quarterback des Miami Dolphins pourrait engendrer pour la franchise floridienne.<\/p><p>Plusieurs cas de figures semblent se pr&eacute;senter: soit Tua Tagovailoa obtient l&rsquo;accord des m&eacute;decins pour rejouer et les Dolphins continuent de lui verser son salaire garanti tant qu&rsquo;il jouera. S&rsquo;il d&eacute;cide de prendre sa retraite de son propre chef, il ne pourra plus pr&eacute;tendre aux ann&eacute;es garanties qu&rsquo;il n&rsquo;aura pas effectu&eacute;. Mais si les m&eacute;decins d&eacute;clarent le quarterback inapte &agrave; la pratique du football am&eacute;ricain en NFL, alors les Miami Dolphins devront verser les 160 millions garantis pr&eacute;vus au contrat sign&eacute; cet &eacute;t&eacute;.<\/p><p>Un argent qui sera donc d&ucirc; sans possibilit&eacute; de se retourner vers les assurances pour en obtenir le d&eacute;dommagement. Au-del&agrave; de la question imm&eacute;diate de la sant&eacute; du joueur et de la saison 2024 des Dolphins, c&rsquo;est aussi le probl&egrave;me de la sant&eacute; financi&egrave;re de la franchise sur les prochaines saisons qui commence &agrave; &eacute;merger doucement.<\/p><p><em>Cr&eacute;dit photo: Sam Navarro-Imagn Images<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180309964,"featured_media":1458253,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[118,40],"tags":[864,1045],"sport":[2785],"saison":[6111],"class_list":["post-1458251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nfl","category-nfl","tag-miami-dolphins","tag-tua-tagovailoa","sport-nfl","saison-6111"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tua Tagovailoa: les commotions c&eacute;r&eacute;brales exclues de l&#039;assurance? - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tua Tagovailoa: les commotions c&eacute;r&eacute;brales exclues de l&#039;assurance? - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T09:38:54+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flavien Jumeau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavien Jumeau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/\",\"name\":\"Tua Tagovailoa: les commotions c\u00e9r\u00e9brales exclues de l\\\\'assurance? - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg\",\"datePublished\":\"2024-09-19T07:38:54+00:00\",\"dateModified\":\"2024-09-19T07:38:54+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg\",\"width\":1920,\"height\":1281,\"caption\":\"Sep 12, 2024; Miami Gardens, Florida, USA; Miami Dolphins quarterback Tua Tagovailoa (1) throws the football against the Buffalo Bills during the third quarter at Hard Rock Stadium. Mandatory Credit: Sam Navarro-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tua Tagovailoa: les commotions c\u00e9r\u00e9brales exclues de l&rsquo;assurance?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d\",\"name\":\"Flavien Jumeau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g\",\"caption\":\"Flavien Jumeau\"},\"description\":\"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tua Tagovailoa: les commotions c&eacute;r&eacute;brales exclues de l&#039;assurance? - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/","og_locale":"fr_FR","og_type":"article","og_title":"Tua Tagovailoa: les commotions c&eacute;r&eacute;brales exclues de l&#039;assurance? - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","og_image":[{"width":1920,"height":1281,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg","type":"image\/jpeg"}],"author":"Flavien Jumeau","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Flavien Jumeau","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/","name":"Tua Tagovailoa: les commotions c\u00e9r\u00e9brales exclues de l\\'assurance? - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg","datePublished":"2024-09-19T07:38:54+00:00","dateModified":"2024-09-19T07:38:54+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24218275.jpg","width":1920,"height":1281,"caption":"Sep 12, 2024; Miami Gardens, Florida, USA; Miami Dolphins quarterback Tua Tagovailoa (1) throws the football against the Buffalo Bills during the third quarter at Hard Rock Stadium. Mandatory Credit: Sam Navarro-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/tua-tagovailoa-commotions-assurance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Tua Tagovailoa: les commotions c\u00e9r\u00e9brales exclues de l&rsquo;assurance?"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/def63bc6746dc5957469b75feb99e66d","name":"Flavien Jumeau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7fa8ba5a4b7e4ce35fe152f083f352db28ad0acce692004ed88a7a7d78893f7?s=96&d=mm&r=g","caption":"Flavien Jumeau"},"description":"Amoureux du sport (et de vraiment tous les sports) depuis mon plus jeune \u00e2ge, j\u2019ai longtemps h\u00e9site entre le snooker et le curling. Finalement c\u2019est le foot US que j\u2019ai d\u00e9cid\u00e9 de choisir! Responsable foot US sur TPO et animateur du podcast Tailgate j\u2019ai pour mission de vous faire d\u00e9couvrir ce sport passionnant si ce n\u2019est pas encore fait et de vous donner les derni\u00e8res actus. Le tout dans la bonne humeur et avec toujours un jeu de mots ou deux savamment distill\u00e9s! Fan des Saints, pour moi Drew Brees est le vrai GOAT!","url":"https:\/\/theplayoffs.news\/fr\/author\/flavien-jumeaugmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180309964"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1458251"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458251\/revisions"}],"predecessor-version":[{"id":1458255,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458251\/revisions\/1458255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1458253"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1458251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1458251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1458251"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1458251"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1458251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}