{"id":1458141,"date":"2024-09-18T20:37:07","date_gmt":"2024-09-18T18:37:07","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1458141"},"modified":"2024-09-18T20:37:07","modified_gmt":"2024-09-18T18:37:07","slug":"nfl-les-joueurs-de-la-week-2","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/","title":{"rendered":"NFL : les joueurs de la week 2"},"content":{"rendered":"<h2>A l&rsquo;aube de la week 3 de NFL, les joueurs de la week 2 ont &eacute;t&eacute; d&eacute;voil&eacute;s dans une semaine &agrave; rebondissements.<\/h2><p>Upset &eacute;tait le ma&icirc;tre mot de cette week 2 de la saison 2024 de <a href=\"https:\/\/theplayoffs.news\/fr\/nfl\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NFL<\/a>. Avec des victoires notables des Saints, des Vikings, ainsi que des Raiders et des Falcons face &agrave; des vrais pr&eacute;tendants au titre, la semaine a &eacute;t&eacute; assez charg&eacute;e en &eacute;motions.<\/p><h3>Conf&eacute;rence AFC<\/h3><h4>Joueur offensif de la week 2<\/h4><p>James Cook remporte ce titre hebdomadaire, le troisi&egrave;me pour un running back durant cette saison 2024 de NFL. Les Bills se sont impos&eacute;s en prime time face aux Dolphins gr&acirc;ce &agrave; notamment trois touchdowns de James Cook : deux &agrave; la course et un &agrave; la r&eacute;ception ce qui place Buffalo au sommet de l&rsquo;AFC East et toujours invaincu.<\/p><h4>Joueur d&eacute;fensif de la week 2<\/h4><p>Maxx Crosby a &eacute;t&eacute; d&eacute;cisif pour Las Vegas dans un upset face aux Ravens d&eacute;sormais &agrave; 0-2. Le DE des Raiders sort d&rsquo;un match avec six plaquages, dont quatre pour perte, ainsi que deux sacks et une passe d&eacute;fendue ce qui en fait l&rsquo;arme d&eacute;fensive cruciale qui a perturb&eacute; cette attaque au sol des Ravens.<\/p><h4>Joueur des &eacute;quipes sp&eacute;ciales de la week 2<\/h4><p>Ka&rsquo;imi Fairbairn, kicker des Texans, a largement contribu&eacute; au succ&egrave;s de Houston face &agrave; Chicago lors du SNF. Le kicker de 30 ans a r&eacute;alis&eacute; un match parfait avec quatre field goals inscrits ainsi qu&rsquo;un PAT converti, totalisant 13 points sur les 19 marqu&eacute;s par Houston dans ce duel entre deux futurs talents de la NFL.<\/p><h3>Conf&eacute;rence NFC<\/h3><h4>Joueur offensif de la week 2<\/h4><p>Qui d&rsquo;autre qu&rsquo;Alvin Kamara des Saints dans l&rsquo;upset de la semaine ? Le running back des Saints est donc le quatri&egrave;me running back &agrave; remporter ce titre, apr&egrave;s un match exceptionnel face aux Cowboys o&ugrave; il a totalis&eacute; 115 yards au sol, 65 &agrave; la r&eacute;ception, avec trois touchdowns &agrave; la course et un au sol dans un match remport&eacute; 44-19 pour les Saints.<\/p><h4>Joueur d&eacute;fensif de la week 2<\/h4><p>Dans un match prime time du lundi, Jessie Bates a &eacute;t&eacute; excellent pour les Falcons qui surprennent les Eagles dans un duel entre volatiles. Le safety a effectu&eacute; 12 plaquages, a d&eacute;fendu deux passes et a surtout effectu&eacute; une interception, interception qui s&rsquo;est av&eacute;r&eacute;e d&eacute;cisive pour la victoire d&rsquo;Atlanta.<\/p><h4>Joueur des &eacute;quipes sp&eacute;ciales de la week 2<\/h4><p>Le kicker des Commanders Austin Seibert a &eacute;t&eacute; magistral dans le premier succ&egrave;s de 2024 pour Washington en <a href=\"https:\/\/www.nfl.com\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>NFL<\/a>. Le kicker de la capitale f&eacute;d&eacute;rale a r&eacute;alis&eacute; un sans faute avec sept field goals inscrits pour un total de 21 points, ce qui fait 100% des points de la franchise dans un duel de division face aux Giants.<\/p><p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310178,"featured_media":1458144,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[118,40],"tags":[79,6461],"sport":[2785],"saison":[6111],"class_list":["post-1458141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nfl","category-nfl","tag-nfl","tag-nfl-player-of-the-week","sport-nfl","saison-6111"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NFL : les joueurs de la week 2 - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NFL : les joueurs de la week 2 - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T20:37:07+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Berlemont\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Berlemont\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/\",\"name\":\"NFL : les joueurs de la week 2 - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg\",\"datePublished\":\"2024-09-18T18:37:07+00:00\",\"dateModified\":\"2024-09-18T18:37:07+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b6b04a451dab03a5ab75cec8912e8942\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg\",\"width\":1920,\"height\":1281,\"caption\":\"Sep 15, 2024; Arlington, Texas, USA; New Orleans Saints running back Alvin Kamara (41) runs against the Dallas Cowboys in the second half at AT&amp;T Stadium. Mandatory Credit: Tim Heitman-Imagn Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NFL : les joueurs de la week 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b6b04a451dab03a5ab75cec8912e8942\",\"name\":\"Arthur Berlemont\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/19ddab1d62ab0a19b186b86cee130432b120dd6f085625a6a6757dd1aa90a5f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/19ddab1d62ab0a19b186b86cee130432b120dd6f085625a6a6757dd1aa90a5f3?s=96&d=mm&r=g\",\"caption\":\"Arthur Berlemont\"},\"description\":\"Etudiant passionn\u00e9 de sport, avant tout m\u00e9caniques, j\\\\'ai d\u00e9couvert les sports US il y a quelques ann\u00e9es. J\\\\'ai tout de suite accroch\u00e9 pour la ville de Cincinnati et ses franchises de NFL et MLB. Aujourd\\\\'hui, je suis l\u00e0 par passion dans la r\u00e9daction d\\\\'articles sur divers sports que j\\\\'affectionne.\",\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/arthur-berlemontgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NFL : les joueurs de la week 2 - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/","og_locale":"fr_FR","og_type":"article","og_title":"NFL : les joueurs de la week 2 - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","og_image":[{"width":1920,"height":1281,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg","type":"image\/jpeg"}],"author":"Arthur Berlemont","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Arthur Berlemont","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/","name":"NFL : les joueurs de la week 2 - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg","datePublished":"2024-09-18T18:37:07+00:00","dateModified":"2024-09-18T18:37:07+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b6b04a451dab03a5ab75cec8912e8942"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/09\/USATSI_24243734.jpg","width":1920,"height":1281,"caption":"Sep 15, 2024; Arlington, Texas, USA; New Orleans Saints running back Alvin Kamara (41) runs against the Dallas Cowboys in the second half at AT&amp;T Stadium. Mandatory Credit: Tim Heitman-Imagn Images"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nfl\/nfl-les-joueurs-de-la-week-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"NFL : les joueurs de la week 2"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/b6b04a451dab03a5ab75cec8912e8942","name":"Arthur Berlemont","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/19ddab1d62ab0a19b186b86cee130432b120dd6f085625a6a6757dd1aa90a5f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19ddab1d62ab0a19b186b86cee130432b120dd6f085625a6a6757dd1aa90a5f3?s=96&d=mm&r=g","caption":"Arthur Berlemont"},"description":"Etudiant passionn\u00e9 de sport, avant tout m\u00e9caniques, j\\'ai d\u00e9couvert les sports US il y a quelques ann\u00e9es. J\\'ai tout de suite accroch\u00e9 pour la ville de Cincinnati et ses franchises de NFL et MLB. Aujourd\\'hui, je suis l\u00e0 par passion dans la r\u00e9daction d\\'articles sur divers sports que j\\'affectionne.","url":"https:\/\/theplayoffs.news\/fr\/author\/arthur-berlemontgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310178"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1458141"}],"version-history":[{"count":3,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458141\/revisions"}],"predecessor-version":[{"id":1458147,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1458141\/revisions\/1458147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1458144"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1458141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1458141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1458141"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1458141"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1458141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}