{"id":1438097,"date":"2024-06-12T17:47:17","date_gmt":"2024-06-12T15:47:17","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1438097"},"modified":"2024-06-12T17:47:17","modified_gmt":"2024-06-12T15:47:17","slug":"nba-finals-2024-kyrie-irving-veut-rebondir","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/","title":{"rendered":"NBA Finals 2024 : Kyrie Irving veut rebondir"},"content":{"rendered":"<h2><strong>NBA &ndash; Alors que se profile la nuit prochaine le troisi&egrave;me &eacute;pisode des Finales NBA 2024 (2h30 heure fran&ccedil;aise), les Dallas Mavericks sont dos au mur. Un r&eacute;veil passera s&ucirc;rement par une &eacute;l&eacute;vation du niveau de jeu de Kyrie Irving.<\/strong><\/h2><p><strong>&nbsp;<\/strong><\/p><p>28 points, 8 passes d&eacute;cisives, 5 rebonds, 0\/8 &agrave; trois points &agrave; 35.5% au tir. Cette ligne de stats de <a href=\"https:\/\/theplayoffs.news\/fr\/nba-basketball\/kyrie-irving-en-grosse-difficulte-face-a-son-ancienne-equipe\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Kyrie Irving<\/a> n&rsquo;est pas celle d&rsquo;un match, mais celle des deux premiers matchs du moment le plus important de la saison. L&rsquo;ancien Cavalier doit absolument se ressaisir pour donner une chance &agrave; son &eacute;quipe de Dallas de l&rsquo;emporter. Et il en est le premier conscient.<\/p><p>&nbsp;<\/p><h3><strong>&laquo;&nbsp;Je dois mieux jouer&nbsp;&raquo;<\/strong><\/h3><p>En effet, m&ecirc;me s&rsquo;il ne faut pas tout attribuer des m&eacute;saventures texanes &agrave; Kyrie Irving, son niveau de jeu sur les deux premiers matchs n&rsquo;a pas &eacute;t&eacute; &agrave; la hauteur du joueur qu&rsquo;il est.<\/p><p>Lui-m&ecirc;me s&rsquo;en est d&rsquo;ailleurs d&eacute;sol&eacute; aupr&egrave;s de son co&eacute;quipier star Luka Don&#269;i&#263; selon ce qu&rsquo;il a r&eacute;v&eacute;l&eacute; aux journalistes hier, &laquo;&nbsp;j&rsquo;ai dit &agrave; mon <em>hermano [fr&egrave;re en espagnol] <\/em>que je devais mieux jouer pour lui, &agrave; ses c&ocirc;t&eacute;s. Pour que nous puissions accomplir notre objectif, nous devons tous les deux bien jouer et nous devons tous les deux faire toutes les petites choses. Nous devons faire tout ce qui est possible pour gagner.&nbsp;&raquo; <a href=\"https:\/\/www.espn.com\/nba\/story\/_\/id\/40328203\/got-play-better\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>affirmait un Irving remobilis&eacute; avant de poursuivre, <\/a><\/p><p>&laquo;&nbsp;&Ccedil;a a &eacute;t&eacute; une conversation facile. Mais c&rsquo;est moi qui l&rsquo;ai d&rsquo;abord trouv&eacute; pour qu&rsquo;il sache que c&rsquo;est de ma faute, je prends la responsabilit&eacute; de ne pas particuli&egrave;rement bien jouer. [&hellip;] La premi&egrave;re chose est d&rsquo;accepter que je n&rsquo;ai pas bien jouer ou pas &agrave; mes standards habituels, pas aussi bien que je l&rsquo;aurais voulu&nbsp;&raquo; finissait-il.<\/p><blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Irving took a lot of analytics-unfriendly shots in game 2 <\/p>\n<p>(Note that most of these came with 10+ seconds remaining on the shot clock)<\/p>\n<p>Tough to win if that's a large part of your shot diet <a href=\"https:\/\/t.co\/8DLJ2qAV8Z\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>pic.twitter.com\/8DLJ2qAV8Z<\/a><\/p>\n<p>&mdash; Jeremias Engelmann (@JerryEngelmann) <a href=\"https:\/\/twitter.com\/JerryEngelmann\/status\/1800061459239706849?ref_src=twsrc%5Etfw\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>June 10, 2024<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Effectivement, pour le moment Irving tourne &agrave; 14 points et 4 passes d&eacute;cisives de moyenne &agrave; 35.5% au tir en deux matchs sur ces finales, le tout sans avoir inscrit le moindre trois points. Une ligne qui fait t&acirc;che par rapport aux 21.9 points, 5.1 passes d&eacute;cisives et ses 1.2 interceptions de moyenne &agrave; 47% au tir et &agrave; 39% &agrave; trois points sur ces Playoffs 2024, sans oublier non plus les trois 3 performances &agrave; plus de 30 points inscrits par Irving lors du dernier tour face &agrave; Minnesota.<\/p><p>Mais l&rsquo;ancien de l&rsquo;universit&eacute; de Duke en a vu d&rsquo;autres et ne se laisse pas abattre. Ses 15 matchs disput&eacute;s en Finales NBA, 93 en Playoffs et 729 en NBA t&eacute;moignent de cela. Par ailleurs Irving sait aussi ce que c&rsquo;est que d&rsquo;&ecirc;tre men&eacute; 2-0 en finale en ayant &eacute;t&eacute; largement domin&eacute; sur les deux premiers matchs.<\/p><p>Ce fut notamment le cas lors des Finales 2016 les opposant aux Warriors de Golden State que Cleveland et Irving avaient fini par remporter alors que ce dernier avait l&agrave;-aussi connu ses deux pires performances lors des deux premiers matchs (10 points seulement dans le match 2 en 2016).<\/p><p>&laquo;&nbsp;En tant que comp&eacute;titeur c&rsquo;est frustrant. Mais je ne veux pas que tout cela influence ou se r&eacute;percute sur aucune autre d&eacute;cision que j&rsquo;ai &agrave; prendre l&agrave; [sur le parquet] en tant que joueur.&nbsp;&raquo; affirmait Irving.<\/p><p>De l&rsquo;autre c&ocirc;t&eacute;, Joe Mazzula, entra&icirc;neur des Celtics n&rsquo;arrivait pas pleinement &agrave; se satisfaire du travail d&eacute;fensif de son &eacute;quipe malgr&eacute; ces contre-performances du meneur adverse, &laquo;&nbsp;il ne s&rsquo;agit pas le stopper, il s&rsquo;agit juste de rendre les choses difficiles pour lui parce qu&rsquo;il a cette capacit&eacute; &agrave; influer sur chaque action.<\/p><p>Donc on doit juste se battre pour cela. Il a eu des bons tirs. Je pense qu&rsquo;on doit mieux d&eacute;fendre sur lui. Je pense qu&rsquo;il sera d&eacute;finitivement plus agressif.&nbsp;&raquo; analyse-t-il avec une pointe de sur-exigence.<\/p><p>&nbsp;<\/p><p>\n<div id=\"attachment_1438099\" style=\"width: 798px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1438099\" class=\" wp-image-1438099\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051-300x200.jpg\" alt=\"\" width=\"788\" height=\"526\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051-300x200.jpg 300w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051-1030x687.jpg 1030w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051-1320x880.jpg 1320w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512051.jpg 1920w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><p id=\"caption-attachment-1438099\" class=\"wp-caption-text\">Kyrie Irving a &eacute;t&eacute; minutieusement d&eacute;fendu par Boston durant les deux premiers match de la finale. Mandatory Credit: David Butler II-USA TODAY Sports<\/p><\/div>\n<\/p><p>&nbsp;<\/p><p>Mais comme nous l&rsquo;avons vu pr&eacute;c&eacute;demment, il en faudra plus pour d&eacute;mobiliser Kyrie Irving qui &laquo;&nbsp;sait ce que &ccedil;a endure&nbsp;&raquo; de gagner une finale, &laquo;&nbsp;on sait ce pourquoi on est l&agrave;, mais maintenant on doit &eacute;lever notre niveau de jeu &agrave; un &eacute;tage sup&eacute;rieur et &ccedil;a commence par moi.&nbsp;&raquo; concluait-il avec d&eacute;termination.<\/p><p>&nbsp;<\/p><p>R&eacute;ponse cette nuit &agrave; partir de 2h30 (heure fran&ccedil;aise) dans un American Airlines Center qui retrouve les Finales NBA pour la premi&egrave;re fois depuis Juin 2011. Sortez le pop-corn&hellip;<\/p><p>&copy; Peter Casey-USA TODAY Sports<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":180310210,"featured_media":1438098,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[595,7360,1073],"sport":[2783],"saison":[6111],"class_list":["post-1438097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-dallas-mavericks","tag-finales-nba-2024","tag-kyrie-irving","sport-nba","saison-6111"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T17:47:17+02:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Romain Balle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Romain Balle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/\",\"name\":\"NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg\",\"datePublished\":\"2024-06-12T15:47:17+00:00\",\"dateModified\":\"2024-06-12T15:47:17+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/6d5286c8c5dec1bbd3e6341f17a41111\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg\",\"width\":1920,\"height\":1279,\"caption\":\"Jun 9, 2024; Boston, Massachusetts, USA; Dallas Mavericks guard Kyrie Irving (11) high fives forward P.J. Washington (25) after a play against the Boston Celtics during the third quarter in game two of the 2024 NBA Finals at TD Garden. Mandatory Credit: Peter Casey-USA TODAY Sports\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA Finals 2024 : Kyrie Irving veut rebondir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/6d5286c8c5dec1bbd3e6341f17a41111\",\"name\":\"Romain Balle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05ddb849264c48c5ab2084b8927e8da5ec4ccb05c2bd91acb1c3d4c2785ce057?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05ddb849264c48c5ab2084b8927e8da5ec4ccb05c2bd91acb1c3d4c2785ce057?s=96&d=mm&r=g\",\"caption\":\"Romain Balle\"},\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/romainballe02gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","og_image":[{"width":1920,"height":1279,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg","type":"image\/jpeg"}],"author":"Romain Balle","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Romain Balle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/","name":"NBA Finals 2024 : Kyrie Irving veut rebondir - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg","datePublished":"2024-06-12T15:47:17+00:00","dateModified":"2024-06-12T15:47:17+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/6d5286c8c5dec1bbd3e6341f17a41111"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2024\/06\/USATSI_23512410-1.jpg","width":1920,"height":1279,"caption":"Jun 9, 2024; Boston, Massachusetts, USA; Dallas Mavericks guard Kyrie Irving (11) high fives forward P.J. Washington (25) after a play against the Boston Celtics during the third quarter in game two of the 2024 NBA Finals at TD Garden. Mandatory Credit: Peter Casey-USA TODAY Sports"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/nba-finals-2024-kyrie-irving-veut-rebondir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"NBA Finals 2024 : Kyrie Irving veut rebondir"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/6d5286c8c5dec1bbd3e6341f17a41111","name":"Romain Balle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05ddb849264c48c5ab2084b8927e8da5ec4ccb05c2bd91acb1c3d4c2785ce057?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05ddb849264c48c5ab2084b8927e8da5ec4ccb05c2bd91acb1c3d4c2785ce057?s=96&d=mm&r=g","caption":"Romain Balle"},"url":"https:\/\/theplayoffs.news\/fr\/author\/romainballe02gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1438097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/180310210"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1438097"}],"version-history":[{"count":2,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1438097\/revisions"}],"predecessor-version":[{"id":1438102,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1438097\/revisions\/1438102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1438098"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1438097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1438097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1438097"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1438097"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1438097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}