{"id":1063568,"date":"2023-11-09T17:56:39","date_gmt":"2023-11-09T16:56:39","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/?p=1063568"},"modified":"2023-11-09T18:04:09","modified_gmt":"2023-11-09T17:04:09","slug":"lakers-sont-ils-vraiment-une-star-succes","status":"publish","type":"post","link":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/","title":{"rendered":"Les Lakers sont-ils vraiment \u00e0 une star du succ\u00e8s ?"},"content":{"rendered":"<h2>NBA &ndash; Deux ans de suite que les Lakers connaissent un d&eacute;but de saison difficile avec son lot de blessures et d&rsquo;incertitude dans le jeu.<\/h2><p>L&rsquo;ann&eacute;e derni&egrave;re, les Los Angeles Lakers avaient d&eacute;but&eacute; la saison de mani&egrave;re cataclysmique avec un bilan de 2-10. beaucoup avaient alors vu une implosion &agrave; venir de l&rsquo;&eacute;quipe qui pourtant s&rsquo;est qualifi&eacute; pour le play-in et sera all&eacute; jusqu&rsquo;en finale de conf&eacute;rence.<\/p><p>Apr&egrave;s un recrutement plut&ocirc;t intelligent, les Lakers se pr&eacute;sentent pour la saison 2023-24 avec la ferme intention de revenir avec les m&ecirc;me ambitions pour la 21&egrave; saison de <a href=\"https:\/\/theplayoffs.news\/fr\/joueur\/lebron-james-nba-3932\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'><strong>LeBron James<\/strong><\/a>. Mais apr&egrave;s 8 matchs, le tableau ne d&eacute;peint pas cela. Bien au contraire.<\/p><p>Un bilan m&eacute;diocre de 3-5 et une d&eacute;faite qui fait mal face aux Rockets dans la nuit de mercredi &agrave; jeudi : tels sont les Lakers 2023-24 &agrave; cette heure-ci. Attention, la saison derni&egrave;re, nous a appris &agrave; nous m&eacute;fier des conclusions trop h&acirc;tives les concernants.<\/p><h3>Les blessures : premi&egrave;re source de frustration<\/h3><p>Si les Lakers ne gagnent pas c&rsquo;est aussi par manque de ressources sur le terrain. Oui, les blessures ont d&eacute;j&agrave; &eacute;maill&eacute; l&rsquo;&eacute;quipe et en particulier, celui qui avait pour objectif de jouer les 82 matchs cette saison : Anthony Davis. Il est sans doute le meilleur joueur de cette &eacute;quipe &agrave; l&rsquo;heure actuelle. Celui qui repr&eacute;sente le futur de la franchise.<\/p><p>\n<div id=\"attachment_1063780\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1063780\" class=\"size-full wp-image-1063780\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1.jpg 1920w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-300x200.jpg 300w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-1030x687.jpg 1030w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-768x512.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-1536x1024.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-1500x1000.jpg 1500w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-705x470.jpg 705w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21835836-1-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-1063780\" class=\"wp-caption-text\">Los Angeles Lakers Anthony Davis Credit: Jasen Vinlove-USA TODAY Sports<\/p><\/div>\n<\/p><p>Il est dominant &agrave; la fois d&eacute;fensivement et offensivement et son absence se fat clairement sentir.<\/p><p>Premi&egrave;re cons&eacute;quence : les lakers sont domin&eacute;s aux rebonds. En l&rsquo;absence de Davis, Hayes et Vanderblit, les Lakers se sont repos&eacute;s sur Wood, James et Hachimura et le r&eacute;sultats n&rsquo;&eacute;tait clairement pas bon : Houstonna domin&eacute; les Lakers 57 &agrave; 34 au rebonds et notamment sur les rebonds offensifs, menant &agrave; des deuxi&egrave;me chance. les Lakers se classent au 30e rang en ce qui concerne les points de seconde chance des adversaires ; ils sont au 5e rang en ce qui concerne les points en contre-attaque des adversaires.<\/p><p>En l&rsquo;&eacute;tat actuel des chose : il s&rsquo;agit l&agrave; du plus gros soucis &agrave; r&eacute;gler pour les Lakers. Malheureusement, &agrave; part faire revenir les bless&eacute;s, les Lakers vont avoir des difficult&eacute;s pr&egrave;s du cercle en d&eacute;fense. Et le prochain match face aux Suns, ne devrait pas arranger les choses.<\/p><p>De l&rsquo;autre c&ocirc;t&eacute; du terrain, ce n&rsquo;est pas forc&eacute;ment mieux notamment sur deux aspects : les lancers francs et les shoots longues distances. Mais ces deux aspects sont ma&icirc;trisables et ne d&eacute;pendent pas des blessures &eacute;ventuelles.<\/p><h3>Quelles solutions pour ces Lakers ?<\/h3><p>Premi&egrave;rement, m&ecirc;me avec un effectif r&eacute;duit, Darvim Ham doit changer certaines combinaisons de joueurs. Selon NBA.com, les Lakers ont &eacute;t&eacute; domin&eacute; de 22,0 points par 100 possessions lorsque le trio Reaves, Russell et Prince &eacute;tait ensemble sur le parquet.<\/p><p>\n<div id=\"attachment_1063779\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1063779\" class=\"size-full wp-image-1063779\" src=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984.jpg\" alt=\"\" width=\"1920\" height=\"1257\" srcset=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984.jpg 1920w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-300x196.jpg 300w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-1030x674.jpg 1030w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-768x503.jpg 768w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-1536x1006.jpg 1536w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-1500x982.jpg 1500w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-705x462.jpg 705w, https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850984-1320x864.jpg 1320w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-1063779\" class=\"wp-caption-text\">Los Angeles Lakers head coach Darvin Ham Credit: Thomas Shea-USA TODAY Sports<\/p><\/div>\n<\/p><p>Les Blessures ne vont pas faciliter la t&acirc;che d&rsquo;Ham sur ce premier point bien que le retour de Vanderbilt devrait lui apporter une solution &agrave; court terme.<\/p><h4>Recruter ?<\/h4><p>Les premi&egrave;res rumeurs d&rsquo;une arriv&eacute;e d&rsquo;une troisi&egrave;me star dans la cit&eacute; des anges font surface. Et <a href=\"https:\/\/bleacherreport.com\/articles\/10096673-is-it-already-time-for-lakers-to-panic-chase-a-third-star\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Bleacher Report<\/a> fat &eacute;tat de plusieurs noms : DeMar DeRozan, Kyrie irving, Buddy Hield ou encore Zach Lavine. Un retour d&rsquo;<a href=\"https:\/\/theplayoffs.news\/fr\/nba-basketball\/lakers-regret-alex-caruso\/\" class=\"trk-cta-link\" data-cta-trk='{\"ctaType\":\"Link\",\"ctaSubType\":\"main\"}'>Alex Caruso semble m&ecirc;me envisag&eacute;<\/a>.<\/p><p>Mais est-ce forc&eacute;ment la bonne solution ? Les Lakers ont-ils les assets pour pouvoir faire cela ?<\/p><p>En l&rsquo;&eacute;tat, le roster des Lakers n&rsquo;est pas &agrave; jeter &agrave; la poubelle. Les nouvelles pi&egrave;ces apport&eacute;es doivent se fondre dans le moule de l&rsquo;&eacute;quipe, la coh&eacute;sion doit aussi se faire. Comme l&rsquo;a soulign&eacute; LeBron James, la coh&eacute;sion ne peut se faire quand il manque les joueurs cl&eacute;s.<\/p><p>La partie offensive est peut tr&egrave;s vite tourner. Austin Reaves par exemple, n&rsquo;est pas au m&ecirc;me niveau que la saison pass&eacute;e et cela se ressent. D&rsquo;Angelo Russell doit vraiment apporter beaucoup plus sinon la trade deadline sera le moment pour lui de quitter, une deuxi&egrave;me fois, le navire Angelino.<\/p><p>Pour la d&eacute;fense, il s&rsquo;agit plus d&rsquo;un manque d&rsquo;envie pour le moment, d&rsquo;agressivit&eacute;, mais l&agrave; encore, c&rsquo;est une philosophie que Darvin Ham doit inculquer &agrave; ses joueurs. Et enfin, prier pour que Davis soit fait de bois et non plus de sucre.<\/p><p>&nbsp;<\/p><p>Credit: Thomas Shea-USA TODAY Sports<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":1063778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"kia_subtitle":"","_mux_skip_reasons":[],"proofreadBy":0,"footnotes":""},"categories":[110,10],"tags":[763,116,117],"sport":[],"saison":[],"class_list":["post-1063568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-nba","category-nba","tag-anthony-davis","tag-lebron-james","tag-los-angeles-lakers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Lakers sont-ils vraiment &agrave; une star du succ&egrave;s ? - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Lakers sont-ils vraiment &agrave; une star du succ&egrave;s ? - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T18:04:09+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Taudin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Taudin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/\",\"name\":\"Les Lakers sont-ils vraiment \u00e0 une star du succ\u00e8s ? - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg\",\"datePublished\":\"2023-11-09T16:56:39+00:00\",\"dateModified\":\"2023-11-09T17:04:09+00:00\",\"author\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\"},\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg\",\"width\":1920,\"height\":1498,\"caption\":\"Nov 8, 2023; Houston, Texas, USA; Los Angeles Lakers forward LeBron James (23) waits for play to start against the Houston Rockets in the first quarter at Toyota Center. Mandatory Credit: Thomas Shea-USA TODAY Sports\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Lakers sont-ils vraiment \u00e0 une star du succ\u00e8s ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133\",\"name\":\"Charles Taudin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g\",\"caption\":\"Charles Taudin\"},\"description\":\"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.\",\"sameAs\":[\"https:\/\/www.instagram.com\/ctaudin_\/\"],\"url\":\"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Lakers sont-ils vraiment &agrave; une star du succ&egrave;s ? - The Playoffs FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Lakers sont-ils vraiment &agrave; une star du succ&egrave;s ? - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2023-11-09T17:04:09+00:00","og_image":[{"width":1920,"height":1498,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg","type":"image\/jpeg"}],"author":"Charles Taudin","twitter_card":"summary_large_image","twitter_creator":"@TheFreeAgentFR","twitter_site":"@TheFreeAgentFR","twitter_misc":{"\u00c9crit par":"Charles Taudin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/","url":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/","name":"Les Lakers sont-ils vraiment \u00e0 une star du succ\u00e8s ? - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg","datePublished":"2023-11-09T16:56:39+00:00","dateModified":"2023-11-09T17:04:09+00:00","author":{"@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133"},"breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2023\/11\/USATSI_21850986.jpg","width":1920,"height":1498,"caption":"Nov 8, 2023; Houston, Texas, USA; Los Angeles Lakers forward LeBron James (23) waits for play to start against the Houston Rockets in the first quarter at Toyota Center. Mandatory Credit: Thomas Shea-USA TODAY Sports"},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/actualite-nba\/lakers-sont-ils-vraiment-une-star-succes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Lakers sont-ils vraiment \u00e0 une star du succ\u00e8s ?"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/eee5b69ad5d3c51cabe881c839dbe133","name":"Charles Taudin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a1e772205ce9fd255edfcafc93013736822e20261f294c5753b20c41ede9f2?s=96&d=mm&r=g","caption":"Charles Taudin"},"description":"R\u00e9dacteur en chef global de The Playoffs, j\u2019ai cr\u00e9\u00e9 The Free Agent, devenu The Playoffs FR, en 2020 durant la pand\u00e9mie. Amoureux depuis des ann\u00e9es des 4 sports majeurs am\u00e9ricains, j\u2019organise maintenant la strat\u00e9gie \u00e9ditoriale et les r\u00e9seaux sociaux de l\u2019ensemble des versions de The Playoffs. Il m\u2019arrive encore d\u2019\u00e9crire sur certains sports que j\u2019affectionne particuli\u00e8rement comme la NFL ou la MLB. Si vous devez retenir qu\u2019une chose : Eli Manning est le vrai GOAT pour avoir battu deux fois Tom Brady.","sameAs":["https:\/\/www.instagram.com\/ctaudin_\/"],"url":"https:\/\/theplayoffs.news\/fr\/author\/charles-taudin\/"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1063568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=1063568"}],"version-history":[{"count":6,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1063568\/revisions"}],"predecessor-version":[{"id":1063782,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/posts\/1063568\/revisions\/1063782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/1063778"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=1063568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/categories?post=1063568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/tags?post=1063568"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=1063568"},{"taxonomy":"saison","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/saison?post=1063568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}