{"id":358567,"date":"2022-06-29T13:48:48","date_gmt":"2022-06-29T11:48:48","guid":{"rendered":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-los-angeles-dodgers-mlb\/"},"modified":"2024-10-27T02:07:08","modified_gmt":"2024-10-27T00:07:08","slug":"brusdar-graterol-mlb-81930","status":"publish","type":"joueur","link":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/","title":{"rendered":"Brusdar Graterol &#8211; Los Angeles Dodgers MLB"},"content":{"rendered":"\n","protected":false},"featured_media":358568,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"kia_subtitle":"","footnotes":""},"sport":[2786],"class_list":["post-358567","joueur","type-joueur","status-publish","has-post-thumbnail","hentry","sport-mlb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/\" \/>\n<meta property=\"og:site_name\" content=\"The Playoffs FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheFreeAgentFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-27T02:07:08+01:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheFreeAgentFR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/\",\"url\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/\",\"name\":\"Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR\",\"isPartOf\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png\",\"datePublished\":\"2022-06-29T11:48:48+00:00\",\"dateModified\":\"2024-10-27T00:07:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage\",\"url\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png\",\"contentUrl\":\"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png\",\"width\":600,\"height\":436},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/theplayoffs.news\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brusdar Graterol &#8211; Los Angeles Dodgers MLB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theplayoffs.news\/fr\/#website\",\"url\":\"https:\/\/theplayoffs.news\/fr\/\",\"name\":\"The Playoffs FR\",\"description\":\"NBA-NFL-NHL-MLB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR","og_url":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/","og_site_name":"The Playoffs FR","article_publisher":"https:\/\/www.facebook.com\/TheFreeAgentFR\/","article_modified_time":"2024-10-27T00:07:08+00:00","og_image":[{"width":600,"height":436,"url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@TheFreeAgentFR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/","url":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/","name":"Brusdar Graterol - Los Angeles Dodgers MLB - The Playoffs FR","isPartOf":{"@id":"https:\/\/theplayoffs.news\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage"},"image":{"@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage"},"thumbnailUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png","datePublished":"2022-06-29T11:48:48+00:00","dateModified":"2024-10-27T00:07:08+00:00","breadcrumb":{"@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#primaryimage","url":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png","contentUrl":"https:\/\/theplayoffs.news\/fr\/wp-content\/uploads\/2022\/06\/40965.png","width":600,"height":436},{"@type":"BreadcrumbList","@id":"https:\/\/theplayoffs.news\/fr\/joueur\/brusdar-graterol-mlb-81930\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/theplayoffs.news\/fr\/"},{"@type":"ListItem","position":2,"name":"Brusdar Graterol &#8211; Los Angeles Dodgers MLB"}]},{"@type":"WebSite","@id":"https:\/\/theplayoffs.news\/fr\/#website","url":"https:\/\/theplayoffs.news\/fr\/","name":"The Playoffs FR","description":"NBA-NFL-NHL-MLB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theplayoffs.news\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/joueur\/358567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/joueur"}],"about":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/types\/joueur"}],"replies":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/comments?post=358567"}],"version-history":[{"count":0,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/joueur\/358567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media\/358568"}],"wp:attachment":[{"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/media?parent=358567"}],"wp:term":[{"taxonomy":"sport","embeddable":true,"href":"https:\/\/theplayoffs.news\/fr\/wp-json\/wp\/v2\/sport?post=358567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}